{"id":1079,"date":"2024-12-11T21:35:36","date_gmt":"2024-12-11T21:35:36","guid":{"rendered":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/?page_id=1079"},"modified":"2025-01-10T13:26:01","modified_gmt":"2025-01-10T13:26:01","slug":"inicio","status":"publish","type":"page","link":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/","title":{"rendered":"In\u00edcio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1079\" class=\"elementor elementor-1079\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bafda83 e-con-full e-flex e-con e-parent\" data-id=\"bafda83\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-12d32fc e-con-full e-flex e-con e-child\" data-id=\"12d32fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce6bd9a animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ce6bd9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aumente a qualidade de vida com <span style=\"color: #fc81db\"><strong>abordagens INTEGRATIVAS<\/strong><\/span> inovadoras<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77b6f6f animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"77b6f6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Planos terap\u00eauticos personalizados para doen\u00e7as neurol\u00f3gicas de Parkinson e Alzheimer, especialista em disturbios do movimento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12595fc elementor-align-center animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"12595fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;zoomIn&quot;,&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/wa.me\/5582991062927\u200b\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89ff1e4 e-con-full e-flex e-con e-child\" data-id=\"89ff1e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29b702b animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"29b702b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2024\/12\/LP-ineuro-viva-mais-parkinson-banners-15-1024x1024.png\" class=\"attachment-large size-large wp-image-1122\" alt=\"\" srcset=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2024\/12\/LP-ineuro-viva-mais-parkinson-banners-15-1024x1024.png 1024w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2024\/12\/LP-ineuro-viva-mais-parkinson-banners-15-300x300.png 300w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2024\/12\/LP-ineuro-viva-mais-parkinson-banners-15-150x150.png 150w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2024\/12\/LP-ineuro-viva-mais-parkinson-banners-15-768x768.png 768w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2024\/12\/LP-ineuro-viva-mais-parkinson-banners-15.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba63adf e-flex e-con-boxed e-con e-parent\" data-id=\"ba63adf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bca2cdb animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bca2cdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Neurologia Integrada<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9070d0 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f9070d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Neurologista especialista em tratamento de dist\u00farbios de movimento, Parkinson e dist\u00farbios da mem\u00f3ria. Master Coach Sist\u00eamica e Medicina Integrativa. Formada pela Universidade Federal de Alagoas, com mestrado em Neurologia pela Universidade Federal Fluminense, oferece consultas e exames, incluindo eletroneuromiografia. Atende na InNeuro Macei\u00f3 e aceita diversos conv\u00eanios. Destaca-se pelo atendimento humanizado e pela compet\u00eancia cl\u00ednica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a01e249 e-flex e-con-boxed e-con e-parent\" data-id=\"a01e249\" data-element_type=\"container\" data-e-type=\"container\" id=\"especialidades\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e168fda animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e168fda\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Minhas Especialidades<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5585d48 elementor-align-center animated-slow elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"5585d48\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star-half\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Alcance seus objetivos de forma saud\u00e1vel e sustent\u00e1vel<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15853d2 e-grid e-con-full e-con e-child\" data-id=\"15853d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9df5f41 elementor-cta--skin-cover animated-slow elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"9df5f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-stacked elementor-shape-circle elementor-animated-item--grow\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"4b5a9d85b6\"><path d=\"M 81 418 L 323 418 L 323 715.710938 L 81 715.710938 Z M 81 418 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><path fill=\"#960033\" d=\"M 407.980469 235.167969 L 378.109375 235.167969 L 378.109375 205.285156 C 378.109375 204.578125 378.039062 203.875 377.902344 203.179688 C 377.761719 202.484375 377.558594 201.808594 377.285156 201.152344 C 377.015625 200.496094 376.683594 199.875 376.289062 199.285156 C 375.894531 198.695312 375.445312 198.152344 374.945312 197.648438 C 374.441406 197.148438 373.898438 196.699219 373.308594 196.304688 C 372.71875 195.914062 372.097656 195.578125 371.441406 195.308594 C 370.785156 195.035156 370.109375 194.832031 369.414062 194.695312 C 368.71875 194.554688 368.015625 194.484375 367.308594 194.484375 L 325.1875 194.484375 C 324.480469 194.484375 323.777344 194.554688 323.082031 194.695312 C 322.386719 194.832031 321.710938 195.035156 321.054688 195.308594 C 320.398438 195.578125 319.777344 195.914062 319.1875 196.304688 C 318.597656 196.699219 318.054688 197.148438 317.550781 197.648438 C 317.050781 198.152344 316.601562 198.695312 316.207031 199.285156 C 315.8125 199.875 315.480469 200.496094 315.210938 201.152344 C 314.9375 201.808594 314.734375 202.484375 314.597656 203.179688 C 314.457031 203.875 314.386719 204.578125 314.386719 205.285156 L 314.386719 235.167969 L 284.515625 235.167969 C 283.804688 235.167969 283.105469 235.238281 282.410156 235.378906 C 281.714844 235.515625 281.039062 235.71875 280.382812 235.992188 C 279.726562 236.261719 279.105469 236.597656 278.515625 236.988281 C 277.925781 237.382812 277.378906 237.832031 276.878906 238.332031 C 276.378906 238.835938 275.929688 239.378906 275.535156 239.96875 C 275.140625 240.558594 274.808594 241.179688 274.539062 241.835938 C 274.265625 242.492188 274.0625 243.167969 273.921875 243.863281 C 273.785156 244.558594 273.714844 245.261719 273.714844 245.96875 L 273.714844 288.089844 C 273.714844 288.796875 273.785156 289.5 273.921875 290.195312 C 274.0625 290.890625 274.265625 291.566406 274.539062 292.222656 C 274.808594 292.878906 275.140625 293.5 275.535156 294.089844 C 275.929688 294.679688 276.378906 295.226562 276.878906 295.726562 C 277.378906 296.226562 277.925781 296.675781 278.515625 297.070312 C 279.105469 297.464844 279.726562 297.796875 280.382812 298.066406 C 281.039062 298.339844 281.714844 298.542969 282.410156 298.683594 C 283.105469 298.820312 283.804688 298.890625 284.515625 298.890625 L 314.386719 298.890625 L 314.386719 328.761719 C 314.386719 329.472656 314.457031 330.171875 314.597656 330.867188 C 314.734375 331.566406 314.9375 332.238281 315.210938 332.894531 C 315.480469 333.550781 315.8125 334.171875 316.207031 334.761719 C 316.601562 335.351562 317.050781 335.898438 317.550781 336.398438 C 318.054688 336.898438 318.597656 337.347656 319.1875 337.742188 C 319.777344 338.136719 320.398438 338.46875 321.054688 338.738281 C 321.710938 339.011719 322.386719 339.214844 323.082031 339.355469 C 323.777344 339.492188 324.480469 339.5625 325.1875 339.5625 L 367.308594 339.5625 C 368.015625 339.5625 368.71875 339.492188 369.414062 339.355469 C 370.109375 339.214844 370.785156 339.011719 371.441406 338.738281 C 372.097656 338.46875 372.71875 338.136719 373.308594 337.742188 C 373.898438 337.347656 374.441406 336.898438 374.945312 336.398438 C 375.445312 335.898438 375.894531 335.351562 376.289062 334.761719 C 376.683594 334.171875 377.015625 333.550781 377.285156 332.894531 C 377.558594 332.238281 377.761719 331.566406 377.902344 330.867188 C 378.039062 330.171875 378.109375 329.472656 378.109375 328.761719 L 378.109375 298.890625 L 407.980469 298.890625 C 408.691406 298.890625 409.390625 298.820312 410.085938 298.683594 C 410.785156 298.542969 411.457031 298.339844 412.113281 298.066406 C 412.769531 297.796875 413.390625 297.464844 413.980469 297.070312 C 414.570312 296.675781 415.117188 296.226562 415.617188 295.726562 C 416.117188 295.226562 416.566406 294.679688 416.960938 294.089844 C 417.355469 293.5 417.6875 292.878906 417.957031 292.222656 C 418.230469 291.566406 418.433594 290.890625 418.574219 290.195312 C 418.710938 289.5 418.78125 288.796875 418.78125 288.089844 L 418.78125 245.96875 C 418.78125 245.261719 418.710938 244.558594 418.574219 243.863281 C 418.433594 243.167969 418.230469 242.492188 417.957031 241.835938 C 417.6875 241.179688 417.355469 240.558594 416.960938 239.96875 C 416.566406 239.378906 416.117188 238.835938 415.617188 238.332031 C 415.117188 237.832031 414.570312 237.382812 413.980469 236.988281 C 413.390625 236.597656 412.769531 236.261719 412.113281 235.992188 C 411.457031 235.71875 410.785156 235.515625 410.085938 235.378906 C 409.390625 235.238281 408.691406 235.167969 407.980469 235.167969 Z M 397.179688 277.289062 L 367.308594 277.289062 C 366.597656 277.289062 365.898438 277.359375 365.199219 277.496094 C 364.503906 277.636719 363.832031 277.839844 363.175781 278.113281 C 362.519531 278.382812 361.898438 278.714844 361.308594 279.109375 C 360.71875 279.503906 360.171875 279.953125 359.671875 280.453125 C 359.167969 280.953125 358.722656 281.5 358.328125 282.089844 C 357.933594 282.679688 357.601562 283.300781 357.332031 283.957031 C 357.058594 284.613281 356.855469 285.285156 356.714844 285.984375 C 356.578125 286.679688 356.507812 287.378906 356.507812 288.089844 L 356.507812 317.960938 L 335.988281 317.960938 L 335.988281 288.089844 C 335.988281 287.378906 335.917969 286.679688 335.78125 285.984375 C 335.640625 285.285156 335.4375 284.613281 335.167969 283.957031 C 334.894531 283.300781 334.5625 282.679688 334.167969 282.089844 C 333.773438 281.5 333.328125 280.953125 332.824219 280.453125 C 332.324219 279.953125 331.777344 279.503906 331.1875 279.109375 C 330.597656 278.714844 329.976562 278.382812 329.320312 278.113281 C 328.664062 277.839844 327.992188 277.636719 327.296875 277.496094 C 326.601562 277.359375 325.898438 277.289062 325.1875 277.289062 L 295.316406 277.289062 L 295.316406 256.769531 L 325.1875 256.769531 C 325.898438 256.769531 326.601562 256.699219 327.296875 256.5625 C 327.992188 256.421875 328.664062 256.21875 329.320312 255.949219 C 329.976562 255.675781 330.597656 255.34375 331.1875 254.949219 C 331.777344 254.554688 332.324219 254.109375 332.824219 253.605469 C 333.328125 253.105469 333.773438 252.558594 334.167969 251.96875 C 334.5625 251.378906 334.894531 250.757812 335.167969 250.101562 C 335.4375 249.449219 335.640625 248.773438 335.78125 248.078125 C 335.917969 247.382812 335.988281 246.679688 335.988281 245.96875 L 335.988281 216.085938 L 356.507812 216.085938 L 356.507812 245.96875 C 356.507812 246.679688 356.578125 247.382812 356.714844 248.078125 C 356.855469 248.773438 357.058594 249.449219 357.332031 250.101562 C 357.601562 250.757812 357.933594 251.378906 358.328125 251.96875 C 358.722656 252.558594 359.167969 253.105469 359.671875 253.605469 C 360.171875 254.109375 360.71875 254.554688 361.308594 254.949219 C 361.898438 255.34375 362.519531 255.675781 363.175781 255.949219 C 363.832031 256.21875 364.503906 256.421875 365.199219 256.5625 C 365.898438 256.699219 366.597656 256.769531 367.308594 256.769531 L 397.179688 256.769531 Z M 397.179688 277.289062 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 493.96875 284.621094 L 512.199219 284.621094 L 554.65625 327.066406 C 555.410156 327.820312 556.257812 328.449219 557.199219 328.953125 C 558.140625 329.457031 559.136719 329.8125 560.183594 330.019531 C 561.230469 330.230469 562.285156 330.28125 563.347656 330.175781 C 564.414062 330.070312 565.4375 329.816406 566.421875 329.40625 C 567.410156 328.996094 568.316406 328.453125 569.140625 327.777344 C 569.96875 327.101562 570.675781 326.316406 571.269531 325.429688 C 571.863281 324.542969 572.316406 323.585938 572.625 322.566406 C 572.933594 321.542969 573.089844 320.5 573.089844 319.429688 L 573.089844 284.621094 L 585.652344 284.621094 C 586.441406 284.621094 587.230469 284.578125 588.019531 284.5 C 588.804688 284.421875 589.585938 284.300781 590.363281 284.148438 C 591.136719 283.992188 591.90625 283.796875 592.660156 283.566406 C 593.417969 283.332031 594.160156 283.066406 594.890625 282.761719 C 595.621094 282.457031 596.335938 282.117188 597.03125 281.742188 C 597.730469 281.371094 598.40625 280.960938 599.0625 280.519531 C 599.71875 280.078125 600.355469 279.609375 600.964844 279.105469 C 601.574219 278.601562 602.160156 278.070312 602.71875 277.511719 C 603.277344 276.949219 603.808594 276.363281 604.308594 275.75 C 604.808594 275.140625 605.28125 274.503906 605.71875 273.84375 C 606.15625 273.1875 606.5625 272.507812 606.933594 271.808594 C 607.308594 271.113281 607.644531 270.398438 607.945312 269.667969 C 608.246094 268.933594 608.511719 268.191406 608.742188 267.433594 C 608.972656 266.675781 609.164062 265.910156 609.316406 265.132812 C 609.46875 264.355469 609.585938 263.574219 609.664062 262.789062 C 609.738281 262 609.777344 261.210938 609.777344 260.421875 L 609.777344 118.398438 C 609.777344 117.609375 609.738281 116.820312 609.660156 116.03125 C 609.585938 115.246094 609.46875 114.464844 609.316406 113.6875 C 609.160156 112.914062 608.96875 112.144531 608.738281 111.390625 C 608.511719 110.632812 608.246094 109.886719 607.941406 109.15625 C 607.640625 108.425781 607.304688 107.710938 606.929688 107.015625 C 606.558594 106.316406 606.152344 105.636719 605.714844 104.980469 C 605.277344 104.320312 604.804688 103.6875 604.304688 103.074219 C 603.804688 102.464844 603.273438 101.878906 602.714844 101.316406 C 602.15625 100.757812 601.570312 100.226562 600.960938 99.722656 C 600.351562 99.21875 599.71875 98.75 599.058594 98.308594 C 598.402344 97.867188 597.726562 97.460938 597.03125 97.085938 C 596.332031 96.710938 595.617188 96.371094 594.890625 96.070312 C 594.160156 95.765625 593.414062 95.496094 592.660156 95.265625 C 591.902344 95.035156 591.136719 94.839844 590.363281 94.683594 C 589.585938 94.527344 588.804688 94.410156 588.019531 94.332031 C 587.230469 94.25 586.441406 94.210938 585.652344 94.207031 L 368.570312 94.207031 C 367.78125 94.210938 366.992188 94.25 366.203125 94.332031 C 365.417969 94.410156 364.636719 94.527344 363.859375 94.683594 C 363.085938 94.839844 362.320312 95.035156 361.5625 95.265625 C 360.808594 95.496094 360.0625 95.765625 359.332031 96.070312 C 358.605469 96.371094 357.890625 96.710938 357.191406 97.085938 C 356.496094 97.460938 355.820312 97.867188 355.164062 98.308594 C 354.503906 98.75 353.871094 99.21875 353.261719 99.722656 C 352.652344 100.226562 352.066406 100.757812 351.507812 101.316406 C 350.949219 101.875 350.417969 102.464844 349.917969 103.074219 C 349.417969 103.6875 348.945312 104.320312 348.507812 104.980469 C 348.070312 105.636719 347.664062 106.316406 347.292969 107.015625 C 346.917969 107.710938 346.582031 108.425781 346.28125 109.15625 C 345.976562 109.886719 345.710938 110.632812 345.484375 111.390625 C 345.253906 112.144531 345.0625 112.914062 344.90625 113.6875 C 344.753906 114.464844 344.636719 115.246094 344.5625 116.03125 C 344.484375 116.820312 344.445312 117.609375 344.445312 118.398438 L 344.445312 161.425781 L 224.359375 161.425781 C 223.515625 161.429688 222.671875 161.472656 221.832031 161.558594 C 220.988281 161.644531 220.15625 161.769531 219.324219 161.9375 C 218.496094 162.105469 217.679688 162.3125 216.871094 162.558594 C 216.0625 162.804688 215.265625 163.09375 214.488281 163.417969 C 213.707031 163.742188 212.945312 164.105469 212.199219 164.503906 C 211.453125 164.902344 210.730469 165.335938 210.027344 165.808594 C 209.324219 166.277344 208.648438 166.78125 207.996094 167.316406 C 207.339844 167.855469 206.714844 168.421875 206.117188 169.019531 C 205.519531 169.617188 204.953125 170.242188 204.417969 170.894531 C 203.878906 171.546875 203.375 172.226562 202.90625 172.929688 C 202.4375 173.632812 202 174.355469 201.601562 175.101562 C 201.203125 175.84375 200.839844 176.609375 200.515625 177.386719 C 200.191406 178.167969 199.90625 178.964844 199.65625 179.769531 C 199.410156 180.578125 199.203125 181.398438 199.035156 182.226562 C 198.871094 183.054688 198.742188 183.890625 198.660156 184.730469 C 198.574219 185.574219 198.527344 186.414062 198.527344 187.261719 L 198.527344 346.796875 C 198.527344 347.644531 198.570312 348.488281 198.65625 349.328125 C 198.738281 350.167969 198.867188 351.003906 199.03125 351.832031 C 199.199219 352.660156 199.40625 353.480469 199.652344 354.289062 C 199.898438 355.097656 200.183594 355.890625 200.507812 356.671875 C 200.832031 357.453125 201.195312 358.214844 201.59375 358.957031 C 201.992188 359.703125 202.425781 360.425781 202.898438 361.128906 C 203.367188 361.832031 203.871094 362.507812 204.410156 363.164062 C 204.945312 363.816406 205.511719 364.441406 206.109375 365.039062 C 206.707031 365.636719 207.335938 366.203125 207.988281 366.738281 C 208.640625 367.273438 209.320312 367.777344 210.023438 368.246094 C 210.726562 368.714844 211.449219 369.148438 212.195312 369.546875 C 212.941406 369.945312 213.703125 370.304688 214.484375 370.628906 C 215.265625 370.953125 216.058594 371.238281 216.867188 371.484375 C 217.675781 371.730469 218.496094 371.933594 219.324219 372.101562 C 220.152344 372.265625 220.988281 372.390625 221.832031 372.472656 C 222.671875 372.554688 223.515625 372.597656 224.359375 372.597656 L 239.761719 372.597656 L 239.761719 413.046875 C 239.761719 414.113281 239.914062 415.15625 240.226562 416.179688 C 240.535156 417.203125 240.988281 418.15625 241.582031 419.042969 C 242.175781 419.933594 242.882812 420.714844 243.710938 421.390625 C 244.535156 422.070312 245.441406 422.613281 246.429688 423.019531 C 247.414062 423.429688 248.4375 423.6875 249.5 423.789062 C 250.5625 423.894531 251.621094 423.84375 252.667969 423.636719 C 253.714844 423.425781 254.707031 423.070312 255.652344 422.566406 C 256.59375 422.066406 257.441406 421.4375 258.195312 420.679688 L 306.300781 372.597656 L 468.136719 372.597656 C 468.980469 372.597656 469.824219 372.554688 470.667969 372.472656 C 471.507812 372.390625 472.34375 372.265625 473.171875 372.097656 C 474.003906 371.933594 474.820312 371.726562 475.632812 371.484375 C 476.441406 371.238281 477.234375 370.953125 478.015625 370.628906 C 478.796875 370.304688 479.5625 369.941406 480.308594 369.542969 C 481.054688 369.144531 481.777344 368.710938 482.480469 368.242188 C 483.183594 367.769531 483.863281 367.269531 484.515625 366.730469 C 485.167969 366.195312 485.796875 365.628906 486.394531 365.03125 C 486.992188 364.433594 487.558594 363.804688 488.097656 363.152344 C 488.632812 362.5 489.136719 361.820312 489.605469 361.117188 C 490.074219 360.414062 490.511719 359.691406 490.910156 358.945312 C 491.308594 358.199219 491.671875 357.4375 491.996094 356.65625 C 492.320312 355.875 492.605469 355.078125 492.851562 354.269531 C 493.097656 353.460938 493.300781 352.640625 493.46875 351.8125 C 493.632812 350.984375 493.757812 350.148438 493.84375 349.308594 C 493.925781 348.464844 493.96875 347.621094 493.96875 346.777344 Z M 366.042969 118.398438 C 366.042969 118.0625 366.101562 117.734375 366.230469 117.421875 C 366.355469 117.105469 366.539062 116.828125 366.773438 116.585938 C 367.011719 116.339844 367.285156 116.152344 367.597656 116.019531 C 367.90625 115.882812 368.234375 115.8125 368.570312 115.808594 L 585.652344 115.808594 C 585.988281 115.8125 586.316406 115.882812 586.625 116.019531 C 586.9375 116.152344 587.210938 116.339844 587.449219 116.585938 C 587.683594 116.828125 587.867188 117.105469 587.992188 117.421875 C 588.121094 117.734375 588.179688 118.0625 588.179688 118.398438 L 588.179688 260.417969 C 588.183594 260.761719 588.121094 261.085938 587.996094 261.402344 C 587.871094 261.71875 587.6875 262 587.453125 262.242188 C 587.214844 262.488281 586.941406 262.675781 586.628906 262.8125 C 586.316406 262.945312 585.992188 263.015625 585.652344 263.023438 L 562.289062 263.023438 C 561.582031 263.023438 560.878906 263.09375 560.183594 263.230469 C 559.488281 263.367188 558.8125 263.574219 558.15625 263.84375 C 557.503906 264.117188 556.878906 264.449219 556.289062 264.84375 C 555.699219 265.238281 555.15625 265.683594 554.652344 266.1875 C 554.152344 266.6875 553.703125 267.234375 553.3125 267.824219 C 552.917969 268.414062 552.585938 269.035156 552.3125 269.691406 C 552.042969 270.34375 551.835938 271.019531 551.699219 271.714844 C 551.558594 272.410156 551.492188 273.113281 551.492188 273.824219 L 551.492188 293.359375 L 524.308594 266.175781 C 523.292969 265.164062 522.125 264.386719 520.804688 263.839844 C 519.480469 263.292969 518.101562 263.023438 516.671875 263.023438 L 493.992188 263.023438 L 493.992188 187.261719 C 493.988281 186.414062 493.945312 185.574219 493.859375 184.730469 C 493.773438 183.890625 493.648438 183.054688 493.480469 182.226562 C 493.3125 181.398438 493.105469 180.578125 492.859375 179.769531 C 492.613281 178.964844 492.328125 178.167969 492.003906 177.386719 C 491.675781 176.609375 491.316406 175.84375 490.914062 175.101562 C 490.515625 174.355469 490.082031 173.632812 489.613281 172.929688 C 489.140625 172.226562 488.636719 171.546875 488.101562 170.894531 C 487.566406 170.242188 486.996094 169.617188 486.398438 169.019531 C 485.800781 168.421875 485.175781 167.855469 484.523438 167.316406 C 483.871094 166.78125 483.191406 166.277344 482.492188 165.808594 C 481.789062 165.335938 481.0625 164.902344 480.320312 164.503906 C 479.574219 164.105469 478.8125 163.742188 478.03125 163.417969 C 477.25 163.09375 476.457031 162.804688 475.648438 162.558594 C 474.839844 162.3125 474.019531 162.105469 473.191406 161.9375 C 472.363281 161.769531 471.527344 161.644531 470.6875 161.558594 C 469.847656 161.472656 469.003906 161.429688 468.160156 161.425781 L 366.042969 161.425781 Z M 468.136719 351 L 301.816406 351 C 300.386719 351 299.007812 351.273438 297.683594 351.820312 C 296.363281 352.371094 295.195312 353.152344 294.179688 354.164062 L 261.359375 386.984375 L 261.359375 361.800781 C 261.359375 361.089844 261.292969 360.386719 261.152344 359.691406 C 261.015625 358.996094 260.808594 358.320312 260.539062 357.667969 C 260.265625 357.011719 259.933594 356.386719 259.539062 355.800781 C 259.144531 355.210938 258.699219 354.664062 258.195312 354.164062 C 257.695312 353.660156 257.148438 353.214844 256.5625 352.820312 C 255.972656 352.425781 255.347656 352.09375 254.695312 351.820312 C 254.039062 351.550781 253.363281 351.34375 252.667969 351.207031 C 251.972656 351.070312 251.269531 351 250.558594 351 L 224.359375 351 C 224.082031 351 223.808594 350.972656 223.535156 350.917969 C 223.261719 350.863281 223 350.785156 222.742188 350.679688 C 222.484375 350.570312 222.242188 350.441406 222.011719 350.289062 C 221.78125 350.132812 221.566406 349.960938 221.371094 349.761719 C 221.171875 349.566406 220.996094 349.355469 220.84375 349.125 C 220.6875 348.894531 220.558594 348.648438 220.453125 348.394531 C 220.34375 348.136719 220.265625 347.871094 220.210938 347.601562 C 220.15625 347.328125 220.125 347.054688 220.125 346.777344 L 220.125 187.261719 C 220.125 186.984375 220.15625 186.707031 220.210938 186.4375 C 220.265625 186.164062 220.34375 185.898438 220.453125 185.640625 C 220.558594 185.386719 220.6875 185.140625 220.84375 184.910156 C 220.996094 184.679688 221.171875 184.46875 221.371094 184.269531 C 221.566406 184.074219 221.78125 183.898438 222.011719 183.742188 C 222.242188 183.589844 222.484375 183.460938 222.742188 183.351562 C 222.996094 183.246094 223.261719 183.164062 223.535156 183.109375 C 223.808594 183.054688 224.082031 183.027344 224.359375 183.027344 L 468.136719 183.027344 C 468.414062 183.027344 468.691406 183.054688 468.960938 183.109375 C 469.234375 183.164062 469.5 183.246094 469.753906 183.351562 C 470.011719 183.460938 470.253906 183.589844 470.484375 183.746094 C 470.71875 183.898438 470.929688 184.074219 471.128906 184.269531 C 471.324219 184.46875 471.5 184.679688 471.652344 184.910156 C 471.808594 185.140625 471.9375 185.386719 472.046875 185.640625 C 472.152344 185.898438 472.230469 186.164062 472.285156 186.4375 C 472.339844 186.707031 472.371094 186.984375 472.371094 187.261719 L 472.371094 346.796875 C 472.367188 347.074219 472.339844 347.347656 472.285156 347.621094 C 472.226562 347.890625 472.144531 348.152344 472.039062 348.40625 C 471.929688 348.664062 471.800781 348.90625 471.644531 349.132812 C 471.492188 349.363281 471.316406 349.574219 471.117188 349.769531 C 470.921875 349.964844 470.710938 350.140625 470.480469 350.292969 C 470.25 350.445312 470.003906 350.574219 469.75 350.679688 C 469.492188 350.785156 469.230469 350.863281 468.957031 350.917969 C 468.6875 350.972656 468.414062 351 468.136719 351 Z M 468.136719 351 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#4b5a9d85b6)\"><path fill=\"#960033\" d=\"M 91.800781 715.789062 L 311.859375 715.789062 C 312.570312 715.789062 313.273438 715.71875 313.96875 715.582031 C 314.664062 715.445312 315.339844 715.238281 315.992188 714.96875 C 316.648438 714.695312 317.273438 714.363281 317.859375 713.96875 C 318.449219 713.574219 318.996094 713.128906 319.496094 712.625 C 320 712.125 320.445312 711.578125 320.839844 710.988281 C 321.234375 710.398438 321.566406 709.777344 321.839844 709.121094 C 322.109375 708.46875 322.316406 707.792969 322.453125 707.097656 C 322.59375 706.402344 322.660156 705.699219 322.660156 704.988281 L 322.660156 690.214844 C 322.65625 687.222656 322.539062 684.234375 322.3125 681.25 C 322.085938 678.269531 321.746094 675.296875 321.300781 672.339844 C 320.851562 669.378906 320.296875 666.441406 319.632812 663.523438 C 318.96875 660.605469 318.195312 657.71875 317.316406 654.859375 C 316.4375 651.996094 315.453125 649.175781 314.367188 646.386719 C 313.277344 643.597656 312.089844 640.855469 310.796875 638.15625 C 309.503906 635.457031 308.117188 632.808594 306.628906 630.214844 C 305.140625 627.617188 303.558594 625.078125 301.886719 622.597656 C 300.210938 620.121094 298.445312 617.707031 296.589844 615.359375 C 294.738281 613.007812 292.796875 610.734375 290.773438 608.527344 C 288.753906 606.324219 286.652344 604.195312 284.46875 602.148438 C 282.289062 600.097656 280.035156 598.132812 277.710938 596.25 C 275.386719 594.367188 272.992188 592.574219 270.535156 590.867188 C 268.074219 589.164062 265.554688 587.550781 262.976562 586.03125 C 260.398438 584.515625 257.769531 583.09375 255.085938 581.769531 C 252.402344 580.445312 249.671875 579.222656 246.898438 578.101562 C 248.222656 577.289062 249.523438 576.441406 250.796875 575.5625 C 252.074219 574.679688 253.328125 573.765625 254.554688 572.816406 C 255.78125 571.867188 256.984375 570.886719 258.15625 569.871094 C 259.332031 568.855469 260.480469 567.8125 261.597656 566.734375 C 262.714844 565.660156 263.804688 564.554688 264.863281 563.417969 C 265.917969 562.285156 266.945312 561.121094 267.941406 559.933594 C 268.9375 558.742188 269.902344 557.527344 270.832031 556.285156 C 271.761719 555.042969 272.65625 553.773438 273.515625 552.484375 C 274.378906 551.195312 275.203125 549.882812 275.996094 548.546875 C 276.785156 547.210938 277.539062 545.855469 278.257812 544.480469 C 278.972656 543.101562 279.652344 541.710938 280.296875 540.296875 C 280.9375 538.882812 281.542969 537.453125 282.105469 536.011719 C 282.671875 534.566406 283.195312 533.105469 283.683594 531.632812 C 284.167969 530.15625 284.613281 528.671875 285.019531 527.175781 C 285.425781 525.675781 285.792969 524.167969 286.117188 522.652344 C 286.441406 521.136719 286.722656 519.609375 286.964844 518.078125 C 287.207031 516.542969 287.40625 515.007812 287.566406 513.460938 C 287.726562 511.917969 287.84375 510.371094 287.917969 508.824219 C 287.992188 507.273438 288.027344 505.722656 288.019531 504.171875 C 288.007812 502.617188 287.960938 501.070312 287.867188 499.519531 C 287.773438 497.972656 287.640625 496.425781 287.464844 494.882812 C 287.289062 493.34375 287.074219 491.804688 286.8125 490.277344 C 286.554688 488.746094 286.257812 487.222656 285.914062 485.710938 C 285.574219 484.195312 285.191406 482.691406 284.769531 481.199219 C 284.347656 479.707031 283.886719 478.226562 283.386719 476.757812 C 282.882812 475.289062 282.34375 473.835938 281.761719 472.398438 C 281.179688 470.957031 280.5625 469.535156 279.90625 468.128906 C 279.246094 466.726562 278.554688 465.339844 277.820312 463.96875 C 277.089844 462.601562 276.320312 461.253906 275.515625 459.929688 C 274.710938 458.601562 273.871094 457.296875 272.996094 456.015625 C 272.121094 454.734375 271.210938 453.480469 270.265625 452.246094 C 269.324219 451.015625 268.347656 449.808594 267.339844 448.628906 C 266.332031 447.449219 265.292969 446.300781 264.222656 445.175781 C 263.152344 444.050781 262.050781 442.957031 260.921875 441.894531 C 259.792969 440.832031 258.632812 439.800781 257.449219 438.796875 C 256.261719 437.796875 255.050781 436.828125 253.8125 435.890625 C 252.574219 434.957031 251.3125 434.054688 250.027344 433.1875 C 248.742188 432.320312 247.433594 431.488281 246.101562 430.691406 C 244.769531 429.894531 243.417969 429.132812 242.046875 428.410156 C 240.671875 427.683594 239.28125 427 237.871094 426.347656 C 236.460938 425.699219 235.035156 425.089844 233.59375 424.519531 C 232.152344 423.945312 230.695312 423.414062 229.222656 422.921875 C 227.753906 422.429688 226.269531 421.976562 224.773438 421.5625 C 223.277344 421.148438 221.773438 420.777344 220.257812 420.445312 C 218.738281 420.113281 217.214844 419.824219 215.683594 419.574219 C 214.152344 419.324219 212.617188 419.117188 211.074219 418.949219 C 209.53125 418.785156 207.984375 418.660156 206.433594 418.578125 C 204.886719 418.492188 203.335938 418.453125 201.785156 418.453125 C 200.230469 418.453125 198.679688 418.496094 197.132812 418.582031 C 195.582031 418.667969 194.035156 418.792969 192.496094 418.960938 C 190.953125 419.128906 189.414062 419.339844 187.882812 419.589844 C 186.351562 419.839844 184.828125 420.132812 183.3125 420.46875 C 181.796875 420.800781 180.292969 421.175781 178.796875 421.589844 C 177.304688 422.003906 175.820312 422.460938 174.347656 422.953125 C 172.878906 423.449219 171.421875 423.984375 169.980469 424.558594 C 168.539062 425.128906 167.113281 425.742188 165.703125 426.394531 C 164.296875 427.042969 162.90625 427.730469 161.535156 428.457031 C 160.164062 429.183594 158.8125 429.945312 157.480469 430.742188 C 156.152344 431.542969 154.84375 432.375 153.558594 433.246094 C 152.273438 434.113281 151.011719 435.015625 149.773438 435.953125 C 148.539062 436.890625 147.328125 437.863281 146.144531 438.863281 C 144.960938 439.867188 143.804688 440.902344 142.675781 441.964844 C 141.546875 443.03125 140.449219 444.125 139.378906 445.25 C 138.308594 446.375 137.269531 447.527344 136.265625 448.707031 C 135.257812 449.890625 134.28125 451.09375 133.339844 452.328125 C 132.398438 453.5625 131.492188 454.820312 130.617188 456.101562 C 129.742188 457.382812 128.90625 458.6875 128.101562 460.015625 C 127.296875 461.34375 126.53125 462.691406 125.800781 464.0625 C 125.070312 465.429688 124.378906 466.816406 123.722656 468.222656 C 123.066406 469.628906 122.449219 471.054688 121.871094 472.492188 C 121.292969 473.933594 120.753906 475.386719 120.253906 476.855469 C 119.753906 478.324219 119.292969 479.804688 118.871094 481.300781 C 118.453125 482.792969 118.070312 484.296875 117.734375 485.8125 C 117.394531 487.324219 117.097656 488.847656 116.839844 490.378906 C 116.582031 491.910156 116.367188 493.445312 116.195312 494.988281 C 116.019531 496.527344 115.886719 498.074219 115.796875 499.621094 C 115.707031 501.171875 115.660156 502.722656 115.652344 504.273438 C 115.644531 505.824219 115.679688 507.375 115.757812 508.925781 C 115.835938 510.476562 115.953125 512.023438 116.117188 513.566406 C 116.277344 515.109375 116.476562 516.648438 116.722656 518.179688 C 116.964844 519.710938 117.25 521.238281 117.578125 522.753906 C 117.902344 524.269531 118.269531 525.777344 118.679688 527.273438 C 119.085938 528.773438 119.53125 530.257812 120.019531 531.730469 C 120.507812 533.203125 121.035156 534.660156 121.601562 536.105469 C 122.167969 537.550781 122.773438 538.980469 123.417969 540.390625 C 124.0625 541.800781 124.742188 543.195312 125.460938 544.570312 C 126.179688 545.945312 126.9375 547.300781 127.726562 548.636719 C 128.519531 549.96875 129.347656 551.28125 130.210938 552.570312 C 131.074219 553.859375 131.972656 555.125 132.902344 556.367188 C 133.835938 557.609375 134.796875 558.824219 135.796875 560.011719 C 136.792969 561.199219 137.820312 562.363281 138.878906 563.496094 C 139.941406 564.628906 141.03125 565.734375 142.148438 566.808594 C 143.269531 567.882812 144.414062 568.925781 145.589844 569.9375 C 146.765625 570.949219 147.96875 571.929688 149.199219 572.878906 C 150.425781 573.828125 151.679688 574.742188 152.957031 575.621094 C 154.234375 576.5 155.535156 577.34375 156.859375 578.15625 C 154.082031 579.269531 151.351562 580.488281 148.664062 581.808594 C 145.976562 583.125 143.34375 584.542969 140.761719 586.058594 C 138.179688 587.570312 135.65625 589.179688 133.195312 590.882812 C 130.730469 592.582031 128.335938 594.375 126.003906 596.253906 C 123.675781 598.132812 121.417969 600.097656 119.234375 602.144531 C 117.050781 604.191406 114.945312 606.316406 112.921875 608.519531 C 110.894531 610.722656 108.953125 612.996094 107.097656 615.34375 C 105.238281 617.691406 103.472656 620.105469 101.792969 622.585938 C 100.117188 625.0625 98.53125 627.601562 97.042969 630.195312 C 95.554688 632.792969 94.160156 635.441406 92.867188 638.140625 C 91.574219 640.839844 90.382812 643.585938 89.296875 646.371094 C 88.207031 649.160156 87.222656 651.984375 86.339844 654.84375 C 85.460938 657.707031 84.691406 660.597656 84.023438 663.515625 C 83.359375 666.433594 82.804688 669.371094 82.355469 672.332031 C 81.910156 675.292969 81.574219 678.265625 81.347656 681.25 C 81.121094 684.234375 81.003906 687.222656 81 690.214844 L 81 704.988281 C 81 705.699219 81.070312 706.402344 81.207031 707.097656 C 81.347656 707.792969 81.550781 708.46875 81.824219 709.121094 C 82.09375 709.777344 82.425781 710.398438 82.820312 710.988281 C 83.214844 711.578125 83.664062 712.125 84.164062 712.625 C 84.664062 713.128906 85.210938 713.574219 85.800781 713.96875 C 86.390625 714.363281 87.011719 714.695312 87.667969 714.96875 C 88.324219 715.238281 89 715.445312 89.695312 715.582031 C 90.390625 715.71875 91.089844 715.789062 91.800781 715.789062 Z M 137.246094 504.78125 C 137.246094 503.722656 137.273438 502.667969 137.324219 501.609375 C 137.375 500.554688 137.453125 499.5 137.558594 498.449219 C 137.660156 497.398438 137.792969 496.347656 137.945312 495.304688 C 138.101562 494.257812 138.28125 493.21875 138.488281 492.179688 C 138.695312 491.144531 138.925781 490.113281 139.183594 489.085938 C 139.441406 488.0625 139.722656 487.042969 140.027344 486.03125 C 140.335938 485.019531 140.667969 484.015625 141.023438 483.023438 C 141.378906 482.027344 141.757812 481.042969 142.164062 480.066406 C 142.566406 479.089844 142.996094 478.121094 143.449219 477.167969 C 143.898438 476.210938 144.375 475.265625 144.875 474.335938 C 145.371094 473.402344 145.890625 472.484375 146.4375 471.578125 C 146.980469 470.671875 147.542969 469.777344 148.132812 468.898438 C 148.71875 468.019531 149.328125 467.15625 149.957031 466.308594 C 150.585938 465.457031 151.238281 464.625 151.90625 463.808594 C 152.578125 462.992188 153.269531 462.191406 153.976562 461.40625 C 154.6875 460.625 155.414062 459.859375 156.164062 459.113281 C 156.910156 458.363281 157.675781 457.636719 158.460938 456.925781 C 159.242188 456.214844 160.042969 455.527344 160.859375 454.855469 C 161.675781 454.183594 162.507812 453.535156 163.359375 452.90625 C 164.207031 452.277344 165.070312 451.667969 165.949219 451.082031 C 166.828125 450.492188 167.722656 449.929688 168.628906 449.382812 C 169.535156 448.839844 170.453125 448.320312 171.386719 447.820312 C 172.320312 447.324219 173.261719 446.847656 174.21875 446.398438 C 175.171875 445.945312 176.140625 445.515625 177.117188 445.113281 C 178.09375 444.707031 179.078125 444.328125 180.074219 443.972656 C 181.070312 443.617188 182.070312 443.285156 183.082031 442.976562 C 184.09375 442.671875 185.113281 442.386719 186.136719 442.132812 C 187.164062 441.875 188.195312 441.644531 189.230469 441.4375 C 190.269531 441.230469 191.308594 441.050781 192.355469 440.894531 C 193.398438 440.738281 194.449219 440.609375 195.5 440.507812 C 196.550781 440.402344 197.605469 440.324219 198.660156 440.273438 C 199.71875 440.222656 200.773438 440.195312 201.832031 440.195312 C 202.886719 440.195312 203.945312 440.222656 205 440.273438 C 206.054688 440.324219 207.109375 440.402344 208.160156 440.507812 C 209.214844 440.609375 210.261719 440.738281 211.308594 440.894531 C 212.351562 441.050781 213.394531 441.230469 214.429688 441.4375 C 215.46875 441.644531 216.5 441.875 217.523438 442.132812 C 218.550781 442.386719 219.566406 442.671875 220.578125 442.976562 C 221.589844 443.285156 222.59375 443.617188 223.589844 443.972656 C 224.582031 444.328125 225.570312 444.707031 226.546875 445.113281 C 227.523438 445.515625 228.488281 445.945312 229.445312 446.398438 C 230.398438 446.847656 231.34375 447.324219 232.277344 447.820312 C 233.207031 448.320312 234.128906 448.839844 235.035156 449.382812 C 235.941406 449.929688 236.832031 450.492188 237.710938 451.082031 C 238.589844 451.667969 239.453125 452.277344 240.304688 452.90625 C 241.152344 453.535156 241.984375 454.183594 242.800781 454.855469 C 243.621094 455.527344 244.417969 456.214844 245.203125 456.925781 C 245.984375 457.636719 246.75 458.363281 247.5 459.113281 C 248.246094 459.859375 248.976562 460.625 249.683594 461.40625 C 250.394531 462.191406 251.085938 462.992188 251.753906 463.808594 C 252.425781 464.625 253.074219 465.457031 253.707031 466.308594 C 254.335938 467.15625 254.941406 468.019531 255.53125 468.898438 C 256.117188 469.777344 256.683594 470.671875 257.226562 471.578125 C 257.769531 472.484375 258.289062 473.402344 258.789062 474.335938 C 259.285156 475.265625 259.761719 476.210938 260.214844 477.167969 C 260.664062 478.121094 261.09375 479.089844 261.5 480.066406 C 261.902344 481.042969 262.285156 482.027344 262.640625 483.023438 C 262.996094 484.015625 263.328125 485.019531 263.632812 486.03125 C 263.941406 487.042969 264.222656 488.0625 264.480469 489.085938 C 264.734375 490.113281 264.96875 491.144531 265.175781 492.179688 C 265.378906 493.21875 265.5625 494.257812 265.714844 495.304688 C 265.871094 496.347656 266 497.398438 266.105469 498.449219 C 266.207031 499.5 266.285156 500.554688 266.335938 501.609375 C 266.390625 502.667969 266.414062 503.722656 266.414062 504.78125 C 266.414062 505.835938 266.390625 506.894531 266.335938 507.949219 C 266.285156 509.003906 266.207031 510.058594 266.105469 511.109375 C 266 512.164062 265.871094 513.210938 265.714844 514.257812 C 265.5625 515.300781 265.378906 516.34375 265.175781 517.378906 C 264.96875 518.417969 264.734375 519.445312 264.480469 520.472656 C 264.222656 521.496094 263.941406 522.515625 263.632812 523.527344 C 263.328125 524.539062 262.996094 525.542969 262.640625 526.539062 C 262.285156 527.53125 261.902344 528.519531 261.5 529.496094 C 261.09375 530.472656 260.664062 531.4375 260.214844 532.394531 C 259.761719 533.347656 259.285156 534.292969 258.789062 535.222656 C 258.289062 536.15625 257.769531 537.074219 257.226562 537.984375 C 256.683594 538.890625 256.117188 539.78125 255.53125 540.660156 C 254.941406 541.539062 254.335938 542.402344 253.707031 543.253906 C 253.074219 544.101562 252.425781 544.933594 251.753906 545.75 C 251.085938 546.570312 250.394531 547.367188 249.683594 548.152344 C 248.976562 548.933594 248.246094 549.699219 247.5 550.449219 C 246.75 551.195312 245.984375 551.921875 245.203125 552.632812 C 244.417969 553.34375 243.621094 554.035156 242.800781 554.703125 C 241.984375 555.375 241.152344 556.023438 240.304688 556.652344 C 239.453125 557.285156 238.589844 557.890625 237.710938 558.480469 C 236.832031 559.066406 235.941406 559.632812 235.035156 560.175781 C 234.128906 560.71875 233.207031 561.238281 232.277344 561.738281 C 231.34375 562.234375 230.398438 562.710938 229.445312 563.164062 C 228.488281 563.613281 227.523438 564.042969 226.546875 564.449219 C 225.570312 564.851562 224.582031 565.230469 223.589844 565.589844 C 222.59375 565.945312 221.589844 566.277344 220.578125 566.582031 C 219.566406 566.890625 218.550781 567.171875 217.523438 567.429688 C 216.5 567.683594 215.46875 567.917969 214.429688 568.121094 C 213.394531 568.328125 212.351562 568.507812 211.308594 568.664062 C 210.261719 568.820312 209.214844 568.949219 208.160156 569.054688 C 207.109375 569.15625 206.054688 569.234375 205 569.285156 C 203.945312 569.335938 202.886719 569.363281 201.832031 569.363281 C 200.773438 569.363281 199.71875 569.335938 198.664062 569.28125 C 197.609375 569.230469 196.554688 569.152344 195.503906 569.046875 C 194.453125 568.941406 193.402344 568.8125 192.359375 568.65625 C 191.3125 568.5 190.273438 568.316406 189.238281 568.109375 C 188.199219 567.902344 187.171875 567.671875 186.144531 567.414062 C 185.121094 567.15625 184.101562 566.875 183.089844 566.566406 C 182.082031 566.257812 181.078125 565.925781 180.082031 565.570312 C 179.089844 565.214844 178.105469 564.832031 177.128906 564.425781 C 176.152344 564.023438 175.1875 563.59375 174.230469 563.140625 C 173.277344 562.6875 172.332031 562.214844 171.402344 561.714844 C 170.46875 561.21875 169.550781 560.695312 168.644531 560.152344 C 167.738281 559.609375 166.847656 559.042969 165.96875 558.457031 C 165.089844 557.867188 164.226562 557.261719 163.378906 556.632812 C 162.527344 556 161.695312 555.351562 160.878906 554.679688 C 160.0625 554.011719 159.261719 553.320312 158.480469 552.609375 C 157.699219 551.902344 156.933594 551.171875 156.183594 550.425781 C 155.4375 549.679688 154.710938 548.914062 154 548.128906 C 153.289062 547.347656 152.601562 546.546875 151.929688 545.730469 C 151.257812 544.914062 150.609375 544.082031 149.980469 543.234375 C 149.351562 542.386719 148.742188 541.519531 148.15625 540.644531 C 147.566406 539.765625 147.003906 538.871094 146.457031 537.964844 C 145.914062 537.058594 145.394531 536.140625 144.894531 535.210938 C 144.398438 534.277344 143.921875 533.335938 143.46875 532.378906 C 143.015625 531.425781 142.589844 530.460938 142.183594 529.484375 C 141.777344 528.507812 141.398438 527.523438 141.042969 526.527344 C 140.683594 525.53125 140.351562 524.53125 140.046875 523.519531 C 139.738281 522.507812 139.457031 521.492188 139.199219 520.464844 C 138.941406 519.441406 138.707031 518.410156 138.5 517.375 C 138.292969 516.339844 138.113281 515.296875 137.957031 514.253906 C 137.800781 513.207031 137.667969 512.160156 137.566406 511.109375 C 137.460938 510.054688 137.382812 509.003906 137.328125 507.949219 C 137.277344 506.890625 137.25 505.835938 137.246094 504.78125 Z M 102.601562 690.214844 C 102.601562 688.59375 102.644531 686.96875 102.726562 685.347656 C 102.808594 683.726562 102.929688 682.109375 103.089844 680.492188 C 103.25 678.878906 103.453125 677.265625 103.691406 675.660156 C 103.929688 674.054688 104.210938 672.457031 104.527344 670.867188 C 104.847656 669.273438 105.203125 667.691406 105.601562 666.117188 C 105.996094 664.542969 106.429688 662.976562 106.902344 661.425781 C 107.375 659.871094 107.886719 658.332031 108.433594 656.804688 C 108.980469 655.273438 109.566406 653.761719 110.1875 652.261719 C 110.8125 650.761719 111.46875 649.277344 112.164062 647.8125 C 112.859375 646.34375 113.589844 644.894531 114.355469 643.464844 C 115.121094 642.03125 115.921875 640.621094 116.757812 639.230469 C 117.59375 637.835938 118.460938 636.464844 119.363281 635.117188 C 120.265625 633.765625 121.199219 632.441406 122.167969 631.136719 C 123.136719 629.832031 124.132812 628.554688 125.164062 627.300781 C 126.195312 626.042969 127.253906 624.816406 128.34375 623.613281 C 129.4375 622.410156 130.554688 621.234375 131.703125 620.085938 C 132.851562 618.9375 134.027344 617.820312 135.230469 616.730469 C 136.429688 615.640625 137.660156 614.578125 138.914062 613.550781 C 140.167969 612.519531 141.449219 611.519531 142.753906 610.554688 C 144.054688 609.585938 145.382812 608.652344 146.730469 607.75 C 148.082031 606.847656 149.453125 605.976562 150.84375 605.140625 C 152.238281 604.308594 153.648438 603.507812 155.078125 602.742188 C 156.511719 601.972656 157.960938 601.242188 159.425781 600.550781 C 160.894531 599.855469 162.378906 599.195312 163.878906 598.574219 C 165.375 597.953125 166.890625 597.367188 168.417969 596.816406 C 169.945312 596.269531 171.488281 595.757812 173.039062 595.289062 C 174.59375 594.816406 176.15625 594.378906 177.730469 593.984375 C 179.304688 593.589844 180.890625 593.230469 182.480469 592.914062 C 184.074219 592.59375 185.671875 592.316406 187.277344 592.078125 C 188.882812 591.835938 190.492188 591.636719 192.109375 591.476562 C 193.722656 591.3125 195.34375 591.191406 196.964844 591.109375 C 198.585938 591.03125 200.207031 590.988281 201.832031 590.984375 C 203.453125 590.988281 205.078125 591.03125 206.699219 591.109375 C 208.320312 591.191406 209.9375 591.3125 211.554688 591.476562 C 213.167969 591.636719 214.777344 591.835938 216.382812 592.078125 C 217.992188 592.316406 219.589844 592.59375 221.179688 592.914062 C 222.773438 593.230469 224.355469 593.589844 225.929688 593.984375 C 227.503906 594.378906 229.070312 594.816406 230.621094 595.289062 C 232.175781 595.757812 233.714844 596.269531 235.242188 596.816406 C 236.769531 597.367188 238.285156 597.949219 239.785156 598.574219 C 241.285156 599.195312 242.765625 599.855469 244.234375 600.550781 C 245.703125 601.242188 247.152344 601.972656 248.582031 602.742188 C 250.011719 603.507812 251.425781 604.308594 252.816406 605.140625 C 254.210938 605.976562 255.582031 606.847656 256.929688 607.75 C 258.277344 608.652344 259.605469 609.585938 260.910156 610.554688 C 262.214844 611.519531 263.492188 612.519531 264.746094 613.550781 C 266 614.578125 267.230469 615.640625 268.433594 616.730469 C 269.636719 617.820312 270.8125 618.9375 271.960938 620.085938 C 273.105469 621.234375 274.226562 622.410156 275.316406 623.613281 C 276.40625 624.816406 277.46875 626.042969 278.496094 627.300781 C 279.527344 628.554688 280.527344 629.832031 281.492188 631.136719 C 282.460938 632.441406 283.394531 633.765625 284.296875 635.117188 C 285.199219 636.464844 286.070312 637.835938 286.90625 639.230469 C 287.738281 640.621094 288.539062 642.03125 289.304688 643.464844 C 290.070312 644.894531 290.800781 646.34375 291.496094 647.8125 C 292.191406 649.277344 292.851562 650.761719 293.472656 652.261719 C 294.09375 653.761719 294.679688 655.273438 295.226562 656.804688 C 295.777344 658.332031 296.285156 659.871094 296.757812 661.425781 C 297.230469 662.976562 297.664062 664.542969 298.0625 666.117188 C 298.457031 667.691406 298.816406 669.273438 299.132812 670.867188 C 299.453125 672.457031 299.730469 674.054688 299.96875 675.660156 C 300.210938 677.265625 300.410156 678.878906 300.570312 680.492188 C 300.734375 682.109375 300.855469 683.726562 300.933594 685.347656 C 301.015625 686.96875 301.058594 688.59375 301.0625 690.214844 L 301.0625 694.191406 L 102.601562 694.191406 Z M 102.601562 690.214844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#960033\" d=\"M 653.238281 505.925781 C 654.558594 505.113281 655.859375 504.265625 657.136719 503.386719 C 658.414062 502.503906 659.664062 501.589844 660.890625 500.640625 C 662.117188 499.691406 663.320312 498.707031 664.492188 497.695312 C 665.667969 496.679688 666.8125 495.636719 667.933594 494.558594 C 669.050781 493.484375 670.136719 492.378906 671.195312 491.246094 C 672.253906 490.109375 673.28125 488.949219 674.277344 487.757812 C 675.269531 486.566406 676.234375 485.351562 677.164062 484.109375 C 678.09375 482.867188 678.988281 481.601562 679.847656 480.308594 C 680.710938 479.019531 681.535156 477.707031 682.328125 476.371094 C 683.117188 475.039062 683.871094 473.683594 684.589844 472.304688 C 685.304688 470.929688 685.984375 469.535156 686.625 468.125 C 687.269531 466.710938 687.871094 465.28125 688.4375 463.835938 C 689 462.394531 689.527344 460.933594 690.011719 459.460938 C 690.496094 457.988281 690.945312 456.5 691.347656 455.003906 C 691.753906 453.507812 692.121094 452 692.445312 450.480469 C 692.769531 448.964844 693.050781 447.441406 693.292969 445.90625 C 693.535156 444.375 693.734375 442.835938 693.894531 441.292969 C 694.054688 439.75 694.167969 438.203125 694.246094 436.65625 C 694.320312 435.105469 694.355469 433.554688 694.34375 432.003906 C 694.335938 430.453125 694.285156 428.902344 694.195312 427.351562 C 694.101562 425.804688 693.96875 424.257812 693.792969 422.71875 C 693.617188 421.175781 693.398438 419.640625 693.140625 418.109375 C 692.882812 416.582031 692.582031 415.058594 692.242188 413.546875 C 691.902344 412.03125 691.519531 410.53125 691.097656 409.035156 C 690.675781 407.542969 690.214844 406.0625 689.710938 404.59375 C 689.210938 403.128906 688.667969 401.671875 688.089844 400.234375 C 687.507812 398.796875 686.890625 397.375 686.230469 395.96875 C 685.574219 394.5625 684.878906 393.175781 684.148438 391.808594 C 683.417969 390.441406 682.648438 389.09375 681.84375 387.769531 C 681.039062 386.441406 680.199219 385.136719 679.324219 383.855469 C 678.445312 382.574219 677.539062 381.320312 676.59375 380.085938 C 675.652344 378.855469 674.675781 377.652344 673.667969 376.472656 C 672.660156 375.292969 671.621094 374.140625 670.550781 373.019531 C 669.480469 371.894531 668.378906 370.800781 667.25 369.738281 C 666.121094 368.675781 664.964844 367.640625 663.777344 366.640625 C 662.59375 365.640625 661.382812 364.671875 660.144531 363.734375 C 658.90625 362.800781 657.644531 361.898438 656.359375 361.03125 C 655.070312 360.164062 653.761719 359.332031 652.433594 358.535156 C 651.101562 357.738281 649.75 356.976562 648.375 356.253906 C 647.003906 355.53125 645.613281 354.84375 644.203125 354.195312 C 642.796875 353.546875 641.371094 352.9375 639.925781 352.363281 C 638.484375 351.792969 637.027344 351.261719 635.558594 350.769531 C 634.085938 350.273438 632.601562 349.820312 631.109375 349.410156 C 629.613281 348.996094 628.105469 348.625 626.589844 348.292969 C 625.074219 347.960938 623.550781 347.671875 622.019531 347.421875 C 620.488281 347.171875 618.953125 346.964844 617.410156 346.796875 C 615.867188 346.632812 614.320312 346.507812 612.773438 346.421875 C 611.222656 346.339844 609.671875 346.300781 608.121094 346.300781 C 606.570312 346.300781 605.019531 346.34375 603.472656 346.429688 C 601.921875 346.515625 600.375 346.640625 598.832031 346.808594 C 597.292969 346.976562 595.753906 347.1875 594.222656 347.4375 C 592.691406 347.6875 591.171875 347.980469 589.65625 348.3125 C 588.140625 348.648438 586.632812 349.023438 585.140625 349.4375 C 583.644531 349.851562 582.160156 350.304688 580.691406 350.800781 C 579.222656 351.296875 577.765625 351.828125 576.324219 352.402344 C 574.882812 352.976562 573.457031 353.589844 572.046875 354.238281 C 570.640625 354.890625 569.25 355.578125 567.878906 356.300781 C 566.507812 357.027344 565.15625 357.789062 563.828125 358.589844 C 562.496094 359.386719 561.1875 360.21875 559.902344 361.089844 C 558.617188 361.957031 557.355469 362.863281 556.121094 363.796875 C 554.882812 364.734375 553.675781 365.707031 552.488281 366.707031 C 551.304688 367.710938 550.148438 368.746094 549.023438 369.808594 C 547.894531 370.875 546.796875 371.96875 545.726562 373.09375 C 544.65625 374.21875 543.617188 375.371094 542.613281 376.550781 C 541.605469 377.730469 540.632812 378.9375 539.6875 380.171875 C 538.746094 381.402344 537.839844 382.660156 536.964844 383.941406 C 536.09375 385.222656 535.253906 386.527344 534.449219 387.855469 C 533.648438 389.183594 532.878906 390.53125 532.148438 391.898438 C 531.417969 393.269531 530.726562 394.65625 530.070312 396.0625 C 529.414062 397.46875 528.796875 398.890625 528.21875 400.332031 C 527.640625 401.769531 527.101562 403.222656 526.601562 404.691406 C 526.101562 406.160156 525.640625 407.640625 525.222656 409.136719 C 524.800781 410.628906 524.421875 412.132812 524.082031 413.648438 C 523.742188 415.160156 523.445312 416.683594 523.1875 418.214844 C 522.933594 419.742188 522.714844 421.277344 522.542969 422.820312 C 522.367188 424.363281 522.238281 425.90625 522.148438 427.457031 C 522.054688 429.003906 522.007812 430.554688 522 432.105469 C 521.996094 433.65625 522.03125 435.207031 522.105469 436.757812 C 522.183594 438.308594 522.304688 439.855469 522.464844 441.398438 C 522.625 442.941406 522.828125 444.476562 523.070312 446.007812 C 523.3125 447.542969 523.597656 449.066406 523.925781 450.582031 C 524.25 452.101562 524.617188 453.605469 525.023438 455.105469 C 525.433594 456.601562 525.878906 458.085938 526.367188 459.558594 C 526.855469 461.03125 527.382812 462.488281 527.949219 463.933594 C 528.515625 465.378906 529.121094 466.804688 529.761719 468.21875 C 530.40625 469.628906 531.089844 471.023438 531.808594 472.398438 C 532.527344 473.773438 533.28125 475.128906 534.074219 476.460938 C 534.863281 477.796875 535.691406 479.105469 536.554688 480.398438 C 537.417969 481.6875 538.316406 482.949219 539.246094 484.191406 C 540.175781 485.433594 541.140625 486.648438 542.136719 487.835938 C 543.132812 489.027344 544.164062 490.1875 545.222656 491.320312 C 546.28125 492.453125 547.371094 493.558594 548.488281 494.632812 C 549.609375 495.707031 550.757812 496.75 551.929688 497.761719 C 553.105469 498.773438 554.308594 499.753906 555.539062 500.703125 C 556.765625 501.652344 558.019531 502.5625 559.296875 503.445312 C 560.574219 504.324219 561.875 505.167969 563.199219 505.980469 C 560.421875 507.09375 557.6875 508.3125 555 509.632812 C 552.3125 510.949219 549.679688 512.367188 547.097656 513.882812 C 544.515625 515.394531 541.992188 517.003906 539.53125 518.707031 C 537.070312 520.40625 534.671875 522.199219 532.34375 524.078125 C 530.015625 525.957031 527.757812 527.921875 525.574219 529.96875 C 523.390625 532.015625 521.285156 534.140625 519.257812 536.34375 C 517.234375 538.546875 515.292969 540.820312 513.433594 543.167969 C 511.578125 545.515625 509.808594 547.929688 508.132812 550.410156 C 506.453125 552.886719 504.871094 555.425781 503.378906 558.019531 C 501.890625 560.617188 500.5 563.265625 499.207031 565.964844 C 497.914062 568.664062 496.722656 571.40625 495.632812 574.195312 C 494.542969 576.984375 493.558594 579.808594 492.679688 582.667969 C 491.800781 585.53125 491.027344 588.421875 490.363281 591.339844 C 489.699219 594.257812 489.140625 597.195312 488.695312 600.15625 C 488.246094 603.117188 487.910156 606.085938 487.683594 609.074219 C 487.457031 612.058594 487.34375 615.046875 487.339844 618.039062 L 487.339844 632.8125 C 487.339844 633.523438 487.40625 634.226562 487.546875 634.921875 C 487.683594 635.617188 487.890625 636.292969 488.160156 636.945312 C 488.433594 637.601562 488.765625 638.222656 489.160156 638.8125 C 489.554688 639.402344 490 639.949219 490.503906 640.449219 C 491.003906 640.953125 491.550781 641.398438 492.140625 641.792969 C 492.726562 642.1875 493.351562 642.519531 494.003906 642.792969 C 494.660156 643.0625 495.335938 643.269531 496.03125 643.40625 C 496.726562 643.542969 497.429688 643.613281 498.140625 643.613281 L 718.199219 643.613281 C 718.90625 643.613281 719.609375 643.542969 720.304688 643.40625 C 721 643.269531 721.675781 643.0625 722.332031 642.792969 C 722.988281 642.519531 723.609375 642.1875 724.199219 641.792969 C 724.789062 641.398438 725.335938 640.953125 725.835938 640.449219 C 726.335938 639.949219 726.785156 639.402344 727.179688 638.8125 C 727.574219 638.222656 727.90625 637.601562 728.175781 636.945312 C 728.449219 636.292969 728.652344 635.617188 728.792969 634.921875 C 728.929688 634.226562 729 633.523438 729 632.8125 L 729 618.039062 C 728.992188 615.046875 728.878906 612.058594 728.652344 609.074219 C 728.425781 606.089844 728.089844 603.121094 727.640625 600.160156 C 727.195312 597.203125 726.640625 594.265625 725.976562 591.347656 C 725.308594 588.429688 724.539062 585.539062 723.660156 582.679688 C 722.78125 579.820312 721.796875 576.996094 720.710938 574.207031 C 719.621094 571.417969 718.433594 568.675781 717.140625 565.976562 C 715.851562 563.277344 714.460938 560.628906 712.972656 558.03125 C 711.488281 555.4375 709.90625 552.898438 708.230469 550.417969 C 706.554688 547.9375 704.789062 545.523438 702.9375 543.175781 C 701.082031 540.828125 699.144531 538.550781 697.121094 536.347656 C 695.097656 534.140625 692.996094 532.015625 690.8125 529.964844 C 688.632812 527.917969 686.378906 525.949219 684.054688 524.066406 C 681.726562 522.1875 679.335938 520.394531 676.875 518.6875 C 674.417969 516.984375 671.898438 515.371094 669.320312 513.851562 C 666.738281 512.335938 664.109375 510.914062 661.425781 509.589844 C 658.742188 508.269531 656.011719 507.046875 653.238281 505.925781 Z M 543.597656 432.605469 C 543.597656 431.546875 543.621094 430.492188 543.671875 429.433594 C 543.726562 428.378906 543.804688 427.324219 543.90625 426.273438 C 544.011719 425.222656 544.140625 424.171875 544.296875 423.128906 C 544.449219 422.082031 544.628906 421.039062 544.835938 420.003906 C 545.042969 418.96875 545.273438 417.9375 545.53125 416.910156 C 545.789062 415.886719 546.070312 414.867188 546.378906 413.855469 C 546.683594 412.84375 547.015625 411.839844 547.371094 410.84375 C 547.726562 409.851562 548.109375 408.863281 548.511719 407.886719 C 548.917969 406.910156 549.34375 405.945312 549.796875 404.988281 C 550.25 404.035156 550.722656 403.089844 551.222656 402.15625 C 551.722656 401.226562 552.242188 400.304688 552.785156 399.398438 C 553.328125 398.492188 553.894531 397.601562 554.480469 396.722656 C 555.066406 395.84375 555.675781 394.980469 556.304688 394.128906 C 556.9375 393.28125 557.585938 392.449219 558.257812 391.632812 C 558.925781 390.8125 559.617188 390.015625 560.328125 389.230469 C 561.039062 388.449219 561.765625 387.683594 562.511719 386.933594 C 563.261719 386.1875 564.027344 385.457031 564.808594 384.75 C 565.59375 384.039062 566.394531 383.347656 567.210938 382.679688 C 568.027344 382.007812 568.859375 381.359375 569.707031 380.726562 C 570.558594 380.097656 571.421875 379.492188 572.300781 378.902344 C 573.179688 378.316406 574.074219 377.75 574.980469 377.207031 C 575.886719 376.664062 576.804688 376.144531 577.738281 375.644531 C 578.667969 375.148438 579.613281 374.671875 580.570312 374.21875 C 581.523438 373.769531 582.492188 373.339844 583.46875 372.933594 C 584.445312 372.53125 585.429688 372.152344 586.425781 371.792969 C 587.421875 371.4375 588.421875 371.105469 589.433594 370.800781 C 590.445312 370.492188 591.464844 370.210938 592.488281 369.953125 C 593.515625 369.699219 594.546875 369.464844 595.582031 369.261719 C 596.621094 369.054688 597.660156 368.875 598.707031 368.71875 C 599.753906 368.5625 600.800781 368.433594 601.851562 368.332031 C 602.90625 368.226562 603.957031 368.148438 605.015625 368.097656 C 606.070312 368.046875 607.125 368.019531 608.183594 368.019531 C 609.242188 368.019531 610.296875 368.046875 611.351562 368.097656 C 612.40625 368.148438 613.460938 368.226562 614.515625 368.332031 C 615.566406 368.433594 616.613281 368.5625 617.660156 368.71875 C 618.707031 368.875 619.746094 369.054688 620.785156 369.261719 C 621.820312 369.46875 622.851562 369.699219 623.875 369.957031 C 624.902344 370.214844 625.921875 370.496094 626.929688 370.800781 C 627.941406 371.109375 628.945312 371.441406 629.941406 371.796875 C 630.9375 372.152344 631.921875 372.535156 632.898438 372.9375 C 633.875 373.34375 634.839844 373.769531 635.796875 374.222656 C 636.753906 374.675781 637.695312 375.148438 638.628906 375.648438 C 639.5625 376.148438 640.480469 376.667969 641.386719 377.210938 C 642.292969 377.753906 643.1875 378.320312 644.066406 378.90625 C 644.945312 379.496094 645.808594 380.101562 646.65625 380.734375 C 647.503906 381.363281 648.339844 382.011719 649.15625 382.683594 C 649.972656 383.355469 650.773438 384.042969 651.554688 384.753906 C 652.339844 385.464844 653.105469 386.191406 653.851562 386.941406 C 654.597656 387.6875 655.328125 388.453125 656.035156 389.234375 C 656.746094 390.019531 657.4375 390.820312 658.105469 391.636719 C 658.777344 392.453125 659.429688 393.285156 660.058594 394.136719 C 660.6875 394.984375 661.296875 395.847656 661.882812 396.726562 C 662.46875 397.605469 663.035156 398.5 663.578125 399.40625 C 664.121094 400.3125 664.640625 401.230469 665.140625 402.164062 C 665.636719 403.097656 666.113281 404.039062 666.566406 404.996094 C 667.015625 405.953125 667.445312 406.917969 667.851562 407.894531 C 668.253906 408.871094 668.632812 409.855469 668.992188 410.851562 C 669.347656 411.847656 669.679688 412.851562 669.984375 413.863281 C 670.292969 414.875 670.574219 415.890625 670.828125 416.917969 C 671.085938 417.941406 671.316406 418.972656 671.523438 420.011719 C 671.730469 421.046875 671.910156 422.089844 672.066406 423.132812 C 672.21875 424.179688 672.351562 425.226562 672.453125 426.28125 C 672.558594 427.332031 672.632812 428.386719 672.6875 429.441406 C 672.738281 430.496094 672.765625 431.554688 672.761719 432.609375 C 672.761719 433.667969 672.738281 434.722656 672.683594 435.78125 C 672.632812 436.835938 672.554688 437.890625 672.453125 438.941406 C 672.347656 439.992188 672.21875 441.042969 672.0625 442.085938 C 671.910156 443.132812 671.726562 444.175781 671.519531 445.210938 C 671.316406 446.246094 671.082031 447.277344 670.828125 448.304688 C 670.570312 449.328125 670.289062 450.347656 669.980469 451.359375 C 669.671875 452.371094 669.34375 453.375 668.984375 454.367188 C 668.628906 455.363281 668.25 456.351562 667.84375 457.328125 C 667.441406 458.304688 667.011719 459.269531 666.558594 460.222656 C 666.105469 461.179688 665.632812 462.125 665.132812 463.054688 C 664.636719 463.988281 664.113281 464.90625 663.570312 465.8125 C 663.027344 466.71875 662.460938 467.613281 661.875 468.492188 C 661.289062 469.371094 660.679688 470.234375 660.050781 471.082031 C 659.417969 471.933594 658.769531 472.765625 658.097656 473.582031 C 657.425781 474.398438 656.738281 475.199219 656.027344 475.980469 C 655.316406 476.765625 654.589844 477.53125 653.839844 478.277344 C 653.09375 479.023438 652.328125 479.753906 651.542969 480.464844 C 650.761719 481.171875 649.960938 481.863281 649.144531 482.535156 C 648.328125 483.203125 647.492188 483.855469 646.644531 484.484375 C 645.796875 485.113281 644.933594 485.722656 644.050781 486.308594 C 643.171875 486.894531 642.28125 487.460938 641.375 488.003906 C 640.46875 488.546875 639.546875 489.066406 638.617188 489.566406 C 637.683594 490.0625 636.738281 490.539062 635.785156 490.992188 C 634.828125 491.441406 633.863281 491.871094 632.886719 492.273438 C 631.910156 492.679688 630.921875 493.058594 629.929688 493.414062 C 628.933594 493.773438 627.929688 494.101562 626.917969 494.410156 C 625.90625 494.714844 624.886719 494.996094 623.863281 495.253906 C 622.835938 495.511719 621.804688 495.742188 620.769531 495.949219 C 619.734375 496.15625 618.691406 496.335938 617.644531 496.488281 C 616.601562 496.644531 615.550781 496.773438 614.5 496.878906 C 613.449219 496.980469 612.394531 497.058594 611.339844 497.109375 C 610.28125 497.160156 609.226562 497.1875 608.167969 497.1875 C 607.113281 497.1875 606.054688 497.160156 605 497.105469 C 603.945312 497.054688 602.894531 496.972656 601.839844 496.871094 C 600.789062 496.765625 599.742188 496.632812 598.695312 496.480469 C 597.652344 496.324219 596.613281 496.140625 595.574219 495.933594 C 594.539062 495.726562 593.507812 495.496094 592.484375 495.238281 C 591.460938 494.980469 590.441406 494.695312 589.429688 494.390625 C 588.421875 494.082031 587.417969 493.75 586.421875 493.394531 C 585.429688 493.035156 584.441406 492.65625 583.46875 492.25 C 582.492188 491.847656 581.527344 491.417969 580.570312 490.964844 C 579.617188 490.511719 578.671875 490.039062 577.742188 489.539062 C 576.808594 489.039062 575.890625 488.519531 574.984375 487.976562 C 574.078125 487.433594 573.1875 486.867188 572.308594 486.28125 C 571.429688 485.691406 570.566406 485.082031 569.71875 484.453125 C 568.871094 483.824219 568.039062 483.175781 567.222656 482.503906 C 566.40625 481.832031 565.605469 481.144531 564.820312 480.433594 C 564.039062 479.722656 563.273438 478.996094 562.527344 478.25 C 561.78125 477.5 561.050781 476.738281 560.34375 475.953125 C 559.632812 475.171875 558.941406 474.371094 558.273438 473.554688 C 557.601562 472.738281 556.953125 471.90625 556.324219 471.054688 C 555.695312 470.207031 555.085938 469.34375 554.496094 468.464844 C 553.910156 467.585938 553.34375 466.695312 552.800781 465.789062 C 552.257812 464.882812 551.738281 463.964844 551.238281 463.03125 C 550.742188 462.101562 550.265625 461.15625 549.8125 460.203125 C 549.363281 459.246094 548.933594 458.28125 548.527344 457.304688 C 548.125 456.332031 547.742188 455.34375 547.386719 454.351562 C 547.03125 453.355469 546.699219 452.351562 546.390625 451.34375 C 546.082031 450.332031 545.800781 449.3125 545.542969 448.289062 C 545.285156 447.265625 545.054688 446.234375 544.847656 445.199219 C 544.640625 444.160156 544.460938 443.121094 544.304688 442.074219 C 544.148438 441.03125 544.015625 439.984375 543.914062 438.929688 C 543.808594 437.878906 543.730469 436.828125 543.675781 435.769531 C 543.625 434.714844 543.597656 433.660156 543.597656 432.605469 Z M 707.398438 622.011719 L 508.9375 622.011719 L 508.9375 618.039062 C 508.941406 616.414062 508.984375 614.792969 509.066406 613.171875 C 509.144531 611.550781 509.265625 609.933594 509.429688 608.316406 C 509.589844 606.703125 509.789062 605.089844 510.03125 603.484375 C 510.269531 601.878906 510.546875 600.28125 510.867188 598.6875 C 511.183594 597.097656 511.542969 595.515625 511.9375 593.941406 C 512.335938 592.367188 512.769531 590.800781 513.242188 589.25 C 513.714844 587.695312 514.222656 586.15625 514.773438 584.625 C 515.320312 583.097656 515.90625 581.585938 516.527344 580.085938 C 517.148438 578.585938 517.808594 577.101562 518.503906 575.636719 C 519.199219 574.167969 519.929688 572.71875 520.695312 571.289062 C 521.460938 569.855469 522.261719 568.445312 523.09375 567.054688 C 523.929688 565.660156 524.800781 564.289062 525.703125 562.941406 C 526.605469 561.589844 527.539062 560.265625 528.507812 558.960938 C 529.472656 557.65625 530.472656 556.378906 531.503906 555.125 C 532.53125 553.867188 533.59375 552.640625 534.683594 551.4375 C 535.773438 550.234375 536.894531 549.058594 538.039062 547.910156 C 539.1875 546.761719 540.363281 545.644531 541.566406 544.554688 C 542.769531 543.464844 544 542.402344 545.253906 541.371094 C 546.507812 540.34375 547.785156 539.34375 549.089844 538.375 C 550.394531 537.410156 551.722656 536.472656 553.070312 535.570312 C 554.417969 534.667969 555.789062 533.800781 557.183594 532.964844 C 558.574219 532.128906 559.988281 531.332031 561.417969 530.5625 C 562.847656 529.796875 564.296875 529.066406 565.765625 528.371094 C 567.234375 527.679688 568.714844 527.019531 570.214844 526.398438 C 571.714844 525.773438 573.230469 525.191406 574.757812 524.640625 C 576.285156 524.09375 577.824219 523.582031 579.378906 523.109375 C 580.929688 522.636719 582.496094 522.203125 584.070312 521.808594 C 585.644531 521.414062 587.226562 521.054688 588.820312 520.738281 C 590.410156 520.417969 592.011719 520.140625 593.617188 519.898438 C 595.222656 519.660156 596.832031 519.460938 598.445312 519.296875 C 600.0625 519.136719 601.679688 519.015625 603.300781 518.933594 C 604.921875 518.851562 606.546875 518.8125 608.167969 518.808594 C 609.792969 518.8125 611.414062 518.851562 613.035156 518.933594 C 614.65625 519.015625 616.277344 519.136719 617.890625 519.296875 C 619.507812 519.460938 621.117188 519.660156 622.722656 519.898438 C 624.328125 520.140625 625.925781 520.417969 627.519531 520.738281 C 629.109375 521.054688 630.695312 521.414062 632.269531 521.808594 C 633.84375 522.203125 635.40625 522.636719 636.960938 523.109375 C 638.511719 523.582031 640.054688 524.09375 641.582031 524.640625 C 643.109375 525.191406 644.625 525.773438 646.121094 526.398438 C 647.621094 527.019531 649.105469 527.679688 650.574219 528.371094 C 652.039062 529.066406 653.488281 529.796875 654.921875 530.5625 C 656.351562 531.332031 657.761719 532.128906 659.15625 532.964844 C 660.546875 533.800781 661.917969 534.667969 663.269531 535.570312 C 664.617188 536.472656 665.945312 537.410156 667.246094 538.375 C 668.550781 539.34375 669.832031 540.34375 671.085938 541.371094 C 672.339844 542.402344 673.570312 543.464844 674.769531 544.554688 C 675.972656 545.644531 677.148438 546.761719 678.296875 547.910156 C 679.445312 549.058594 680.5625 550.234375 681.65625 551.4375 C 682.746094 552.640625 683.804688 553.867188 684.835938 555.125 C 685.867188 556.378906 686.863281 557.65625 687.832031 558.960938 C 688.796875 560.265625 689.734375 561.589844 690.636719 562.941406 C 691.539062 564.289062 692.40625 565.660156 693.242188 567.054688 C 694.078125 568.445312 694.878906 569.855469 695.644531 571.289062 C 696.410156 572.71875 697.140625 574.167969 697.835938 575.636719 C 698.53125 577.101562 699.1875 578.585938 699.8125 580.085938 C 700.433594 581.585938 701.019531 583.097656 701.566406 584.625 C 702.113281 586.15625 702.625 587.695312 703.097656 589.25 C 703.570312 590.800781 704.003906 592.367188 704.398438 593.941406 C 704.796875 595.515625 705.152344 597.097656 705.472656 598.6875 C 705.789062 600.28125 706.066406 601.878906 706.308594 603.484375 C 706.546875 605.089844 706.75 606.703125 706.910156 608.316406 C 707.070312 609.933594 707.191406 611.550781 707.273438 613.171875 C 707.355469 614.792969 707.398438 616.414062 707.398438 618.039062 Z M 707.398438 622.011719 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 541.078125 156.253906 L 558.359375 156.253906 C 559.070312 156.253906 559.769531 156.183594 560.464844 156.046875 C 561.160156 155.910156 561.835938 155.703125 562.492188 155.433594 C 563.148438 155.160156 563.769531 154.828125 564.359375 154.433594 C 564.949219 154.039062 565.496094 153.59375 565.996094 153.089844 C 566.496094 152.589844 566.945312 152.042969 567.339844 151.453125 C 567.734375 150.863281 568.066406 150.242188 568.335938 149.585938 C 568.609375 148.933594 568.8125 148.257812 568.953125 147.5625 C 569.089844 146.867188 569.160156 146.164062 569.160156 145.453125 C 569.160156 144.746094 569.089844 144.042969 568.953125 143.347656 C 568.8125 142.652344 568.609375 141.976562 568.335938 141.320312 C 568.066406 140.667969 567.734375 140.042969 567.339844 139.453125 C 566.945312 138.863281 566.496094 138.320312 565.996094 137.816406 C 565.496094 137.316406 564.949219 136.867188 564.359375 136.472656 C 563.769531 136.082031 563.148438 135.746094 562.492188 135.476562 C 561.835938 135.203125 561.160156 135 560.464844 134.863281 C 559.769531 134.722656 559.070312 134.652344 558.359375 134.652344 L 541.078125 134.652344 C 540.371094 134.652344 539.667969 134.722656 538.972656 134.863281 C 538.277344 135 537.601562 135.203125 536.945312 135.476562 C 536.292969 135.746094 535.667969 136.082031 535.078125 136.472656 C 534.488281 136.867188 533.945312 137.316406 533.441406 137.816406 C 532.941406 138.320312 532.492188 138.863281 532.101562 139.453125 C 531.707031 140.042969 531.371094 140.667969 531.101562 141.320312 C 530.832031 141.976562 530.625 142.652344 530.488281 143.347656 C 530.347656 144.042969 530.28125 144.746094 530.28125 145.453125 C 530.28125 146.164062 530.347656 146.867188 530.488281 147.5625 C 530.625 148.257812 530.832031 148.933594 531.101562 149.585938 C 531.371094 150.242188 531.707031 150.863281 532.101562 151.453125 C 532.492188 152.042969 532.941406 152.589844 533.441406 153.089844 C 533.945312 153.59375 534.488281 154.039062 535.078125 154.433594 C 535.667969 154.828125 536.292969 155.160156 536.945312 155.433594 C 537.601562 155.703125 538.277344 155.910156 538.972656 156.046875 C 539.667969 156.183594 540.371094 156.253906 541.078125 156.253906 Z M 541.078125 156.253906 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 526.941406 194.398438 L 558.261719 194.398438 C 558.972656 194.398438 559.671875 194.332031 560.371094 194.191406 C 561.066406 194.054688 561.738281 193.847656 562.394531 193.578125 C 563.050781 193.304688 563.671875 192.972656 564.261719 192.578125 C 564.851562 192.1875 565.398438 191.738281 565.898438 191.238281 C 566.402344 190.734375 566.847656 190.191406 567.242188 189.601562 C 567.636719 189.011719 567.96875 188.386719 568.238281 187.734375 C 568.511719 187.078125 568.714844 186.402344 568.855469 185.707031 C 568.992188 185.011719 569.0625 184.308594 569.0625 183.601562 C 569.0625 182.890625 568.992188 182.1875 568.855469 181.492188 C 568.714844 180.796875 568.511719 180.121094 568.238281 179.464844 C 567.96875 178.8125 567.636719 178.1875 567.242188 177.597656 C 566.847656 177.011719 566.402344 176.464844 565.898438 175.964844 C 565.398438 175.460938 564.851562 175.015625 564.261719 174.621094 C 563.671875 174.226562 563.050781 173.894531 562.394531 173.621094 C 561.738281 173.351562 561.066406 173.144531 560.371094 173.007812 C 559.671875 172.867188 558.972656 172.800781 558.261719 172.800781 L 526.941406 172.800781 C 526.234375 172.800781 525.53125 172.867188 524.835938 173.007812 C 524.140625 173.144531 523.464844 173.351562 522.808594 173.621094 C 522.152344 173.894531 521.53125 174.226562 520.941406 174.621094 C 520.351562 175.015625 519.808594 175.460938 519.304688 175.964844 C 518.804688 176.464844 518.355469 177.011719 517.960938 177.597656 C 517.570312 178.1875 517.234375 178.8125 516.964844 179.464844 C 516.691406 180.121094 516.488281 180.796875 516.351562 181.492188 C 516.210938 182.1875 516.140625 182.890625 516.140625 183.601562 C 516.140625 184.308594 516.210938 185.011719 516.351562 185.707031 C 516.488281 186.402344 516.691406 187.078125 516.964844 187.734375 C 517.234375 188.386719 517.570312 189.011719 517.960938 189.601562 C 518.355469 190.191406 518.804688 190.734375 519.304688 191.238281 C 519.808594 191.738281 520.351562 192.1875 520.941406 192.578125 C 521.53125 192.972656 522.152344 193.304688 522.808594 193.578125 C 523.464844 193.847656 524.140625 194.054688 524.835938 194.191406 C 525.53125 194.332031 526.234375 194.398438 526.941406 194.398438 Z M 526.941406 194.398438 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 524.878906 238.289062 L 558.359375 238.289062 C 559.070312 238.289062 559.769531 238.222656 560.464844 238.082031 C 561.160156 237.945312 561.835938 237.738281 562.492188 237.46875 C 563.148438 237.199219 563.769531 236.863281 564.359375 236.46875 C 564.949219 236.078125 565.496094 235.628906 565.996094 235.128906 C 566.496094 234.625 566.945312 234.082031 567.339844 233.492188 C 567.734375 232.902344 568.066406 232.277344 568.335938 231.625 C 568.609375 230.96875 568.8125 230.292969 568.953125 229.597656 C 569.089844 228.902344 569.160156 228.199219 569.160156 227.492188 C 569.160156 226.78125 569.089844 226.078125 568.953125 225.382812 C 568.8125 224.6875 568.609375 224.011719 568.335938 223.359375 C 568.066406 222.703125 567.734375 222.082031 567.339844 221.492188 C 566.945312 220.902344 566.496094 220.355469 565.996094 219.855469 C 565.496094 219.351562 564.949219 218.90625 564.359375 218.511719 C 563.769531 218.117188 563.148438 217.785156 562.492188 217.511719 C 561.835938 217.242188 561.160156 217.035156 560.464844 216.898438 C 559.769531 216.761719 559.070312 216.691406 558.359375 216.691406 L 524.878906 216.691406 C 524.171875 216.691406 523.46875 216.761719 522.773438 216.898438 C 522.078125 217.035156 521.402344 217.242188 520.746094 217.511719 C 520.089844 217.785156 519.46875 218.117188 518.878906 218.511719 C 518.289062 218.90625 517.746094 219.351562 517.242188 219.855469 C 516.742188 220.355469 516.292969 220.902344 515.898438 221.492188 C 515.503906 222.082031 515.171875 222.703125 514.902344 223.359375 C 514.628906 224.011719 514.425781 224.6875 514.289062 225.382812 C 514.148438 226.078125 514.078125 226.78125 514.078125 227.492188 C 514.078125 228.199219 514.148438 228.902344 514.289062 229.597656 C 514.425781 230.292969 514.628906 230.96875 514.902344 231.625 C 515.171875 232.277344 515.503906 232.902344 515.898438 233.492188 C 516.292969 234.082031 516.742188 234.625 517.242188 235.128906 C 517.746094 235.628906 518.289062 236.078125 518.878906 236.46875 C 519.46875 236.863281 520.089844 237.199219 520.746094 237.46875 C 521.402344 237.738281 522.078125 237.945312 522.773438 238.082031 C 523.46875 238.222656 524.171875 238.289062 524.878906 238.289062 Z M 524.878906 238.289062 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">Consulta Neurol\u00f3gica<\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tComo especialista em doen\u00e7a Neurodegenerativa, Dist\u00farbio do movimento e Medicina integrativa promovemos a conscientiza\u00e7\u00e3o e atendimento humanizado para pacientes e cuidadores, online e presencial.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/a-importancia-de-consultar-um-especialista-em-disturbios-do-movimento\/\">\n\t\t\t\t\t\tSaiba mais\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aba6ae8 elementor-cta--skin-cover animated-slow elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"aba6ae8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-stacked elementor-shape-circle elementor-animated-item--grow\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"4300494de4\"><path d=\"M 48.246094 65.308594 L 761.753906 65.308594 L 761.753906 778.820312 L 48.246094 778.820312 Z M 48.246094 65.308594 \" clip-rule=\"nonzero\"><\/path><\/clipPath><clipPath id=\"0f9450d431\"><path d=\"M 405 65.308594 C 207.96875 65.308594 48.246094 225.035156 48.246094 422.0625 C 48.246094 619.09375 207.96875 778.820312 405 778.820312 C 602.03125 778.820312 761.753906 619.09375 761.753906 422.0625 C 761.753906 225.035156 602.03125 65.308594 405 65.308594 Z M 405 65.308594 \" clip-rule=\"nonzero\"><\/path><\/clipPath><clipPath id=\"b5a3e79607\"><path d=\"M 67.355469 84.417969 L 742.976562 84.417969 L 742.976562 760 L 67.355469 760 Z M 67.355469 84.417969 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><g clip-path=\"url(#4300494de4)\"><g clip-path=\"url(#0f9450d431)\"><path fill=\"#960033\" d=\"M 48.246094 65.308594 L 761.753906 65.308594 L 761.753906 778.820312 L 48.246094 778.820312 Z M 48.246094 65.308594 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/g><path fill=\"#ffffff\" d=\"M 448.894531 528.535156 L 460.597656 572.652344 L 349.402344 572.652344 L 361.105469 528.535156 Z M 448.894531 528.535156 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 305.507812 602.589844 L 504.492188 602.589844 C 505.460938 602.59375 506.425781 602.691406 507.375 602.878906 C 508.328125 603.066406 509.253906 603.34375 510.152344 603.710938 C 511.050781 604.078125 511.90625 604.523438 512.71875 605.054688 C 513.53125 605.585938 514.289062 606.191406 514.984375 606.867188 C 515.679688 607.542969 516.304688 608.277344 516.863281 609.074219 C 517.417969 609.871094 517.890625 610.710938 518.285156 611.597656 C 518.675781 612.484375 518.980469 613.402344 519.199219 614.347656 C 519.417969 615.292969 519.542969 616.253906 519.574219 617.222656 L 290.425781 617.222656 C 290.457031 616.253906 290.582031 615.292969 290.800781 614.347656 C 291.015625 613.402344 291.320312 612.484375 291.714844 611.597656 C 292.109375 610.710938 292.582031 609.871094 293.136719 609.074219 C 293.691406 608.277344 294.320312 607.542969 295.015625 606.867188 C 295.710938 606.191406 296.464844 605.585938 297.277344 605.054688 C 298.089844 604.523438 298.949219 604.078125 299.847656 603.710938 C 300.746094 603.34375 301.671875 603.066406 302.621094 602.878906 C 303.574219 602.691406 304.535156 602.59375 305.507812 602.589844 Z M 305.507812 602.589844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 254.859375 271.925781 L 555.140625 271.925781 L 555.140625 323.019531 L 516.421875 323.019531 C 515.132812 323.019531 513.867188 323.183594 512.621094 323.507812 C 511.371094 323.832031 510.1875 324.3125 509.0625 324.941406 C 507.941406 325.574219 506.914062 326.335938 505.988281 327.230469 C 505.0625 328.125 504.261719 329.125 503.59375 330.222656 L 493.238281 347.332031 L 468.25 292.183594 C 467.679688 290.960938 466.957031 289.835938 466.089844 288.804688 C 465.222656 287.773438 464.234375 286.875 463.125 286.101562 C 462.019531 285.332031 460.832031 284.71875 459.5625 284.261719 C 458.296875 283.804688 456.988281 283.515625 455.644531 283.402344 C 454.292969 283.316406 452.953125 283.40625 451.625 283.679688 C 450.300781 283.949219 449.03125 284.394531 447.824219 285.007812 C 446.613281 285.621094 445.507812 286.386719 444.507812 287.296875 C 443.503906 288.207031 442.640625 289.238281 441.914062 290.382812 L 420.757812 323.921875 L 383.164062 323.921875 C 381.835938 323.925781 380.53125 324.101562 379.246094 324.453125 C 377.964844 324.804688 376.75 325.316406 375.605469 325.988281 C 374.457031 326.660156 373.417969 327.46875 372.488281 328.417969 C 371.554688 329.363281 370.761719 330.417969 370.109375 331.574219 L 356.605469 355.433594 L 342.421875 294.882812 C 342.257812 294.160156 342.039062 293.449219 341.765625 292.757812 C 341.492188 292.066406 341.167969 291.402344 340.792969 290.757812 C 340.417969 290.117188 339.996094 289.507812 339.527344 288.929688 C 339.058594 288.351562 338.550781 287.8125 338 287.3125 C 337.449219 286.8125 336.867188 286.355469 336.246094 285.945312 C 335.625 285.535156 334.980469 285.171875 334.304688 284.859375 C 333.628906 284.546875 332.933594 284.289062 332.21875 284.082031 C 331.503906 283.875 330.78125 283.726562 330.042969 283.628906 C 329.296875 283.523438 328.546875 283.472656 327.792969 283.476562 C 327.039062 283.480469 326.289062 283.539062 325.542969 283.65625 C 324.800781 283.773438 324.066406 283.941406 323.347656 284.167969 C 322.628906 284.394531 321.929688 284.671875 321.25 285 C 320.574219 285.328125 319.921875 285.707031 319.300781 286.132812 C 318.679688 286.558594 318.09375 287.027344 317.539062 287.539062 C 316.988281 288.054688 316.476562 288.605469 316.007812 289.195312 C 315.535156 289.785156 315.113281 290.40625 314.734375 291.058594 L 288.847656 336.753906 L 254.859375 336.753906 Z M 254.859375 271.925781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 524.976562 352.960938 L 555.140625 352.960938 L 555.140625 422.738281 L 254.859375 422.738281 L 254.859375 366.914062 L 297.628906 366.914062 C 298.957031 366.910156 300.261719 366.734375 301.546875 366.382812 C 302.828125 366.03125 304.042969 365.523438 305.1875 364.847656 C 306.335938 364.175781 307.375 363.367188 308.304688 362.417969 C 309.238281 361.472656 310.03125 360.417969 310.683594 359.261719 L 321.9375 339.226562 L 336.121094 399.777344 C 336.304688 400.511719 336.539062 401.226562 336.828125 401.921875 C 337.117188 402.617188 337.453125 403.289062 337.839844 403.9375 C 338.230469 404.585938 338.660156 405.199219 339.136719 405.785156 C 339.617188 406.367188 340.132812 406.914062 340.691406 407.421875 C 341.25 407.929688 341.839844 408.390625 342.464844 408.8125 C 343.089844 409.234375 343.746094 409.605469 344.425781 409.933594 C 345.105469 410.257812 345.804688 410.53125 346.527344 410.753906 C 347.246094 410.976562 347.980469 411.144531 348.726562 411.257812 L 350.75 411.257812 C 352.085938 411.277344 353.398438 411.117188 354.6875 410.777344 C 355.976562 410.4375 357.199219 409.929688 358.347656 409.253906 C 359.5 408.582031 360.539062 407.765625 361.464844 406.804688 C 362.390625 405.84375 363.171875 404.777344 363.808594 403.605469 L 391.945312 354.082031 L 428.859375 354.082031 C 430.136719 354.082031 431.390625 353.921875 432.625 353.609375 C 433.863281 353.292969 435.039062 352.832031 436.160156 352.222656 C 437.28125 351.613281 438.308594 350.875 439.246094 350.007812 C 440.179688 349.144531 440.996094 348.175781 441.691406 347.105469 L 452.496094 330 L 477.929688 385.597656 C 478.484375 386.839844 479.195312 387.984375 480.066406 389.03125 C 480.933594 390.078125 481.929688 390.988281 483.046875 391.765625 C 484.164062 392.539062 485.367188 393.148438 486.652344 393.59375 C 487.941406 394.035156 489.261719 394.300781 490.621094 394.378906 C 491.980469 394.460938 493.324219 394.359375 494.652344 394.070312 C 495.984375 393.78125 497.25 393.320312 498.453125 392.6875 C 499.65625 392.050781 500.75 391.265625 501.738281 390.328125 C 502.726562 389.390625 503.570312 388.339844 504.265625 387.171875 Z M 524.976562 352.960938 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#ffffff\" d=\"M 585.078125 226.90625 L 224.921875 226.90625 C 223.933594 226.90625 222.949219 227 221.980469 227.195312 C 221.007812 227.386719 220.066406 227.675781 219.152344 228.054688 C 218.234375 228.433594 217.367188 228.898438 216.542969 229.445312 C 215.71875 229.996094 214.957031 230.621094 214.257812 231.324219 C 213.558594 232.023438 212.933594 232.785156 212.382812 233.609375 C 211.832031 234.429688 211.367188 235.300781 210.988281 236.214844 C 210.609375 237.128906 210.324219 238.074219 210.128906 239.042969 C 209.9375 240.015625 209.839844 240.996094 209.839844 241.988281 L 209.839844 483.515625 C 209.851562 484.496094 209.960938 485.46875 210.160156 486.429688 C 210.363281 487.390625 210.65625 488.320312 211.039062 489.222656 C 211.425781 490.128906 211.894531 490.984375 212.445312 491.796875 C 213 492.609375 213.625 493.359375 214.324219 494.046875 C 215.023438 494.734375 215.78125 495.351562 216.601562 495.890625 C 217.421875 496.429688 218.285156 496.886719 219.195312 497.257812 C 220.105469 497.628906 221.039062 497.90625 222.003906 498.09375 C 222.96875 498.28125 223.941406 498.375 224.921875 498.371094 L 585.078125 498.371094 C 586.058594 498.375 587.03125 498.28125 587.996094 498.09375 C 588.957031 497.90625 589.894531 497.628906 590.804688 497.257812 C 591.710938 496.886719 592.578125 496.429688 593.398438 495.890625 C 594.214844 495.351562 594.976562 494.734375 595.675781 494.046875 C 596.375 493.359375 597 492.609375 597.554688 491.796875 C 598.105469 490.984375 598.574219 490.128906 598.957031 489.222656 C 599.34375 488.320312 599.636719 487.390625 599.835938 486.429688 C 600.039062 485.46875 600.148438 484.496094 600.160156 483.515625 L 600.160156 241.988281 C 600.160156 240.996094 600.0625 240.015625 599.867188 239.042969 C 599.675781 238.074219 599.390625 237.128906 599.011719 236.214844 C 598.632812 235.300781 598.167969 234.429688 597.617188 233.609375 C 597.066406 232.785156 596.441406 232.023438 595.742188 231.324219 C 595.039062 230.621094 594.277344 229.996094 593.457031 229.445312 C 592.632812 228.898438 591.761719 228.433594 590.847656 228.054688 C 589.933594 227.675781 588.992188 227.386719 588.019531 227.195312 C 587.046875 227 586.066406 226.90625 585.078125 226.90625 Z M 585.078125 437.820312 C 585.074219 438.804688 584.976562 439.78125 584.78125 440.746094 C 584.585938 441.710938 584.296875 442.644531 583.914062 443.550781 C 583.535156 444.460938 583.066406 445.320312 582.515625 446.136719 C 581.964844 446.953125 581.335938 447.703125 580.636719 448.394531 C 579.933594 449.085938 579.171875 449.703125 578.347656 450.242188 C 577.527344 450.78125 576.65625 451.234375 575.746094 451.601562 C 574.832031 451.96875 573.890625 452.242188 572.921875 452.425781 C 571.957031 452.605469 570.980469 452.691406 569.996094 452.675781 L 240.003906 452.675781 C 239.019531 452.691406 238.042969 452.605469 237.074219 452.425781 C 236.109375 452.242188 235.167969 451.96875 234.253906 451.601562 C 233.339844 451.234375 232.472656 450.78125 231.648438 450.242188 C 230.828125 449.703125 230.0625 449.085938 229.363281 448.394531 C 228.660156 447.703125 228.035156 446.953125 227.484375 446.136719 C 226.929688 445.320312 226.464844 444.460938 226.082031 443.550781 C 225.703125 442.644531 225.414062 441.707031 225.21875 440.746094 C 225.023438 439.78125 224.925781 438.804688 224.921875 437.820312 L 224.921875 257.066406 C 224.921875 256.078125 225.019531 255.097656 225.210938 254.125 C 225.40625 253.15625 225.691406 252.210938 226.070312 251.296875 C 226.449219 250.382812 226.914062 249.511719 227.464844 248.6875 C 228.015625 247.867188 228.640625 247.105469 229.339844 246.402344 C 230.039062 245.703125 230.800781 245.078125 231.625 244.527344 C 232.449219 243.976562 233.316406 243.511719 234.230469 243.132812 C 235.148438 242.753906 236.089844 242.46875 237.0625 242.277344 C 238.03125 242.082031 239.011719 241.988281 240.003906 241.988281 L 569.996094 241.988281 C 570.984375 241.988281 571.964844 242.082031 572.9375 242.277344 C 573.910156 242.46875 574.851562 242.753906 575.765625 243.132812 C 576.683594 243.511719 577.550781 243.976562 578.375 244.527344 C 579.199219 245.078125 579.960938 245.703125 580.660156 246.402344 C 581.359375 247.105469 581.984375 247.867188 582.535156 248.6875 C 583.085938 249.511719 583.550781 250.382812 583.929688 251.296875 C 584.308594 252.210938 584.59375 253.152344 584.789062 254.125 C 584.980469 255.097656 585.078125 256.078125 585.078125 257.066406 Z M 585.078125 437.820312 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#b5a3e79607)\"><path fill=\"#ffffff\" d=\"M 405 84.417969 C 399.472656 84.417969 393.953125 84.554688 388.433594 84.824219 C 382.914062 85.097656 377.402344 85.503906 371.90625 86.042969 C 366.40625 86.585938 360.921875 87.261719 355.457031 88.074219 C 349.992188 88.882812 344.546875 89.828125 339.128906 90.90625 C 333.707031 91.984375 328.320312 93.195312 322.957031 94.539062 C 317.597656 95.878906 312.273438 97.351562 306.984375 98.957031 C 301.699219 100.5625 296.453125 102.292969 291.25 104.15625 C 286.046875 106.015625 280.894531 108.003906 275.789062 110.121094 C 270.683594 112.234375 265.632812 114.472656 260.636719 116.835938 C 255.640625 119.199219 250.707031 121.683594 245.835938 124.289062 C 240.960938 126.890625 236.15625 129.613281 231.414062 132.457031 C 226.675781 135.296875 222.007812 138.253906 217.414062 141.320312 C 212.820312 144.390625 208.304688 147.574219 203.863281 150.863281 C 199.425781 154.15625 195.070312 157.554688 190.800781 161.058594 C 186.527344 164.566406 182.34375 168.175781 178.25 171.886719 C 174.15625 175.597656 170.15625 179.40625 166.25 183.3125 C 162.339844 187.21875 158.53125 191.222656 154.820312 195.316406 C 151.109375 199.410156 147.5 203.59375 143.996094 207.863281 C 140.492188 212.136719 137.09375 216.492188 133.800781 220.929688 C 130.507812 225.367188 127.328125 229.882812 124.257812 234.476562 C 121.1875 239.074219 118.230469 243.738281 115.390625 248.480469 C 112.550781 253.21875 109.828125 258.027344 107.222656 262.898438 C 104.617188 267.773438 102.132812 272.707031 99.773438 277.703125 C 97.410156 282.695312 95.171875 287.746094 93.054688 292.851562 C 90.941406 297.957031 88.953125 303.113281 87.089844 308.316406 C 85.230469 313.515625 83.496094 318.761719 81.894531 324.050781 C 80.289062 329.339844 78.816406 334.664062 77.472656 340.023438 C 76.128906 345.382812 74.921875 350.773438 73.84375 356.191406 C 72.765625 361.613281 71.820312 367.054688 71.007812 372.519531 C 70.199219 377.988281 69.523438 383.46875 68.980469 388.96875 C 68.4375 394.46875 68.03125 399.976562 67.761719 405.496094 C 67.488281 411.015625 67.355469 416.539062 67.355469 422.0625 C 67.355469 427.589844 67.488281 433.113281 67.761719 438.632812 C 68.03125 444.152344 68.4375 449.660156 68.980469 455.160156 C 69.523438 460.65625 70.199219 466.140625 71.007812 471.605469 C 71.820312 477.074219 72.765625 482.515625 73.84375 487.933594 C 74.921875 493.355469 76.128906 498.746094 77.472656 504.105469 C 78.816406 509.464844 80.289062 514.789062 81.894531 520.078125 C 83.496094 525.363281 85.230469 530.609375 87.089844 535.8125 C 88.953125 541.015625 90.941406 546.167969 93.054688 551.273438 C 95.171875 556.378906 97.410156 561.429688 99.773438 566.425781 C 102.132812 571.421875 104.617188 576.355469 107.222656 581.230469 C 109.828125 586.101562 112.550781 590.910156 115.390625 595.648438 C 118.230469 600.386719 121.1875 605.054688 124.257812 609.648438 C 127.328125 614.242188 130.507812 618.761719 133.800781 623.199219 C 137.09375 627.636719 140.492188 631.992188 143.996094 636.261719 C 147.5 640.535156 151.109375 644.71875 154.820312 648.8125 C 158.53125 652.90625 162.339844 656.90625 166.25 660.816406 C 170.15625 664.722656 174.15625 668.53125 178.25 672.242188 C 182.34375 675.953125 186.527344 679.5625 190.800781 683.066406 C 195.070312 686.574219 199.425781 689.972656 203.863281 693.261719 C 208.304688 696.554688 212.820312 699.734375 217.414062 702.804688 C 222.007812 705.875 226.675781 708.832031 231.414062 711.671875 C 236.15625 714.511719 240.960938 717.234375 245.835938 719.839844 C 250.707031 722.445312 255.640625 724.929688 260.636719 727.292969 C 265.632812 729.652344 270.683594 731.894531 275.789062 734.007812 C 280.894531 736.121094 286.046875 738.109375 291.25 739.972656 C 296.453125 741.832031 301.699219 743.566406 306.984375 745.171875 C 312.273438 746.773438 317.597656 748.246094 322.957031 749.589844 C 328.320312 750.933594 333.707031 752.144531 339.128906 753.222656 C 344.546875 754.300781 349.992188 755.242188 355.457031 756.054688 C 360.921875 756.867188 366.40625 757.542969 371.90625 758.082031 C 377.402344 758.625 382.914062 759.03125 388.433594 759.300781 C 393.953125 759.574219 399.472656 759.710938 405 759.710938 C 410.523438 759.710938 416.046875 759.574219 421.566406 759.300781 C 427.085938 759.03125 432.59375 758.625 438.09375 758.082031 C 443.59375 757.542969 449.078125 756.867188 454.542969 756.054688 C 460.007812 755.242188 465.449219 754.300781 470.871094 753.222656 C 476.289062 752.144531 481.679688 750.933594 487.039062 749.589844 C 492.402344 748.246094 497.726562 746.773438 503.011719 745.171875 C 508.300781 743.566406 513.546875 741.832031 518.75 739.972656 C 523.953125 738.109375 529.105469 736.121094 534.210938 734.007812 C 539.316406 731.894531 544.367188 729.652344 549.363281 727.292969 C 554.355469 724.929688 559.289062 722.445312 564.164062 719.839844 C 569.039062 717.234375 573.84375 714.511719 578.582031 711.671875 C 583.324219 708.832031 587.992188 705.875 592.585938 702.804688 C 597.179688 699.734375 601.695312 696.554688 606.132812 693.261719 C 610.574219 689.972656 614.929688 686.574219 619.199219 683.066406 C 623.472656 679.5625 627.652344 675.953125 631.75 672.242188 C 635.84375 668.53125 639.84375 664.722656 643.75 660.816406 C 647.65625 656.90625 651.46875 652.90625 655.179688 648.8125 C 658.890625 644.71875 662.496094 640.535156 666.003906 636.261719 C 669.507812 631.992188 672.90625 627.636719 676.199219 623.199219 C 679.492188 618.761719 682.671875 614.242188 685.742188 609.648438 C 688.8125 605.054688 691.765625 600.386719 694.605469 595.648438 C 697.449219 590.910156 700.171875 586.101562 702.777344 581.230469 C 705.382812 576.355469 707.863281 571.421875 710.226562 566.425781 C 712.589844 561.429688 714.828125 556.378906 716.941406 551.273438 C 719.058594 546.167969 721.046875 541.015625 722.90625 535.8125 C 724.769531 530.609375 726.5 525.363281 728.105469 520.078125 C 729.710938 514.789062 731.183594 509.464844 732.527344 504.105469 C 733.867188 498.746094 735.078125 493.355469 736.15625 487.933594 C 737.234375 482.515625 738.179688 477.074219 738.992188 471.605469 C 739.800781 466.140625 740.476562 460.65625 741.019531 455.160156 C 741.5625 449.660156 741.96875 444.152344 742.238281 438.632812 C 742.507812 433.113281 742.644531 427.589844 742.644531 422.0625 C 742.644531 416.539062 742.503906 411.015625 742.230469 405.5 C 741.960938 399.980469 741.550781 394.472656 741.007812 388.972656 C 740.464844 383.472656 739.785156 377.992188 738.972656 372.527344 C 738.160156 367.0625 737.214844 361.621094 736.136719 356.199219 C 735.058594 350.78125 733.847656 345.394531 732.5 340.035156 C 731.15625 334.675781 729.683594 329.351562 728.078125 324.0625 C 726.472656 318.777344 724.738281 313.53125 722.878906 308.332031 C 721.015625 303.128906 719.027344 297.976562 716.910156 292.871094 C 714.796875 287.765625 712.554688 282.71875 710.191406 277.722656 C 707.828125 272.730469 705.34375 267.796875 702.738281 262.921875 C 700.136719 258.050781 697.410156 253.246094 694.570312 248.507812 C 691.730469 243.765625 688.773438 239.101562 685.703125 234.507812 C 682.632812 229.914062 679.453125 225.398438 676.160156 220.960938 C 672.871094 216.523438 669.472656 212.167969 665.964844 207.898438 C 662.460938 203.625 658.851562 199.445312 655.140625 195.347656 C 651.429688 191.253906 647.621094 187.253906 643.714844 183.347656 C 639.808594 179.441406 635.808594 175.632812 631.714844 171.921875 C 627.621094 168.210938 623.4375 164.601562 619.167969 161.097656 C 614.894531 157.59375 610.542969 154.195312 606.105469 150.902344 C 601.664062 147.609375 597.148438 144.429688 592.554688 141.359375 C 587.960938 138.289062 583.296875 135.332031 578.558594 132.492188 C 573.820312 129.652344 569.011719 126.929688 564.140625 124.324219 C 559.269531 121.71875 554.335938 119.234375 549.339844 116.871094 C 544.34375 114.507812 539.296875 112.269531 534.191406 110.152344 C 529.085938 108.039062 523.933594 106.046875 518.734375 104.1875 C 513.53125 102.324219 508.285156 100.589844 503 98.984375 C 497.710938 97.378906 492.390625 95.90625 487.03125 94.5625 C 481.671875 93.21875 476.28125 92.007812 470.863281 90.925781 C 465.445312 89.847656 460 88.902344 454.535156 88.089844 C 449.070312 87.277344 443.589844 86.597656 438.089844 86.054688 C 432.59375 85.511719 427.082031 85.105469 421.566406 84.832031 C 416.046875 84.558594 410.523438 84.421875 405 84.417969 Z M 630.097656 483.515625 C 630.09375 484.988281 630.015625 486.457031 629.867188 487.921875 C 629.71875 489.390625 629.5 490.84375 629.210938 492.289062 C 628.917969 493.734375 628.558594 495.160156 628.128906 496.570312 C 627.699219 497.976562 627.199219 499.363281 626.632812 500.722656 C 626.066406 502.082031 625.4375 503.414062 624.742188 504.710938 C 624.046875 506.007812 623.289062 507.269531 622.46875 508.496094 C 621.648438 509.71875 620.773438 510.902344 619.835938 512.039062 C 618.902344 513.179688 617.914062 514.269531 616.871094 515.308594 C 615.828125 516.351562 614.738281 517.339844 613.601562 518.273438 C 612.460938 519.210938 611.28125 520.085938 610.058594 520.90625 C 608.832031 521.726562 607.570312 522.484375 606.273438 523.179688 C 604.972656 523.875 603.644531 524.507812 602.285156 525.074219 C 600.925781 525.636719 599.539062 526.136719 598.128906 526.566406 C 596.722656 526.996094 595.296875 527.355469 593.851562 527.648438 C 592.40625 527.9375 590.953125 528.15625 589.484375 528.304688 C 588.019531 528.453125 586.550781 528.53125 585.078125 528.535156 L 479.957031 528.535156 L 491.660156 572.652344 L 504.492188 572.652344 C 505.96875 572.652344 507.4375 572.726562 508.90625 572.867188 C 510.371094 573.011719 511.828125 573.230469 513.277344 573.515625 C 514.722656 573.804688 516.152344 574.160156 517.5625 574.589844 C 518.972656 575.015625 520.359375 575.511719 521.722656 576.078125 C 523.085938 576.640625 524.417969 577.269531 525.71875 577.964844 C 527.015625 578.660156 528.28125 579.417969 529.507812 580.238281 C 530.734375 581.054688 531.917969 581.933594 533.054688 582.867188 C 534.195312 583.804688 535.289062 584.792969 536.328125 585.835938 C 537.371094 586.878906 538.363281 587.96875 539.296875 589.109375 C 540.230469 590.25 541.109375 591.433594 541.929688 592.660156 C 542.746094 593.882812 543.503906 595.148438 544.199219 596.449219 C 544.894531 597.75 545.523438 599.082031 546.089844 600.441406 C 546.652344 601.804688 547.148438 603.191406 547.578125 604.601562 C 548.003906 606.015625 548.363281 607.441406 548.648438 608.890625 C 548.9375 610.335938 549.152344 611.792969 549.296875 613.261719 C 549.441406 614.726562 549.511719 616.199219 549.511719 617.671875 L 549.511719 632.078125 C 549.515625 633.0625 549.421875 634.035156 549.234375 634.996094 C 549.046875 635.960938 548.769531 636.898438 548.398438 637.804688 C 548.027344 638.714844 547.570312 639.578125 547.03125 640.398438 C 546.492188 641.21875 545.875 641.976562 545.1875 642.675781 C 544.5 643.375 543.75 644.003906 542.9375 644.554688 C 542.125 645.109375 541.269531 645.574219 540.363281 645.960938 C 539.460938 646.34375 538.53125 646.636719 537.570312 646.839844 C 536.609375 647.042969 535.636719 647.148438 534.65625 647.160156 L 275.34375 647.160156 C 274.363281 647.148438 273.390625 647.042969 272.429688 646.839844 C 271.46875 646.636719 270.539062 646.34375 269.632812 645.960938 C 268.730469 645.574219 267.875 645.109375 267.0625 644.554688 C 266.25 644.003906 265.5 643.375 264.8125 642.675781 C 264.121094 641.976562 263.507812 641.21875 262.96875 640.398438 C 262.429688 639.578125 261.972656 638.714844 261.601562 637.804688 C 261.230469 636.898438 260.953125 635.960938 260.765625 634.996094 C 260.578125 634.035156 260.484375 633.0625 260.488281 632.078125 L 260.488281 617.671875 C 260.488281 616.199219 260.558594 614.726562 260.703125 613.261719 C 260.847656 611.792969 261.0625 610.335938 261.351562 608.890625 C 261.636719 607.441406 261.996094 606.015625 262.421875 604.601562 C 262.851562 603.191406 263.347656 601.804688 263.910156 600.441406 C 264.476562 599.082031 265.105469 597.75 265.800781 596.449219 C 266.492188 595.148438 267.25 593.882812 268.070312 592.660156 C 268.890625 591.433594 269.765625 590.25 270.703125 589.109375 C 271.636719 587.96875 272.625 586.878906 273.667969 585.835938 C 274.710938 584.792969 275.804688 583.804688 276.941406 582.867188 C 278.082031 581.933594 279.265625 581.054688 280.492188 580.238281 C 281.71875 579.417969 282.980469 578.660156 284.28125 577.964844 C 285.582031 577.269531 286.914062 576.640625 288.277344 576.078125 C 289.640625 575.511719 291.027344 575.015625 292.4375 574.589844 C 293.847656 574.160156 295.277344 573.804688 296.722656 573.515625 C 298.167969 573.230469 299.625 573.011719 301.09375 572.867188 C 302.5625 572.726562 304.03125 572.652344 305.507812 572.652344 L 318.335938 572.652344 L 330.042969 528.535156 L 224.921875 528.535156 C 223.449219 528.53125 221.980469 528.453125 220.511719 528.304688 C 219.046875 528.15625 217.59375 527.9375 216.148438 527.648438 C 214.703125 527.355469 213.277344 526.996094 211.867188 526.566406 C 210.460938 526.136719 209.074219 525.636719 207.714844 525.074219 C 206.355469 524.507812 205.023438 523.875 203.726562 523.179688 C 202.425781 522.484375 201.167969 521.726562 199.941406 520.90625 C 198.71875 520.085938 197.535156 519.210938 196.398438 518.273438 C 195.257812 517.339844 194.167969 516.351562 193.128906 515.308594 C 192.085938 514.269531 191.097656 513.179688 190.164062 512.039062 C 189.226562 510.902344 188.351562 509.71875 187.53125 508.496094 C 186.710938 507.269531 185.953125 506.007812 185.257812 504.710938 C 184.5625 503.414062 183.929688 502.082031 183.363281 500.722656 C 182.800781 499.363281 182.300781 497.976562 181.871094 496.570312 C 181.441406 495.160156 181.082031 493.734375 180.789062 492.289062 C 180.5 490.84375 180.28125 489.390625 180.132812 487.921875 C 179.984375 486.457031 179.90625 484.988281 179.902344 483.515625 L 179.902344 241.988281 C 179.90625 240.511719 179.984375 239.042969 180.132812 237.578125 C 180.28125 236.113281 180.5 234.65625 180.789062 233.210938 C 181.078125 231.769531 181.441406 230.339844 181.871094 228.933594 C 182.300781 227.523438 182.800781 226.140625 183.363281 224.777344 C 183.929688 223.417969 184.5625 222.089844 185.257812 220.789062 C 185.953125 219.492188 186.710938 218.230469 187.53125 217.007812 C 188.347656 215.78125 189.226562 214.601562 190.160156 213.460938 C 191.097656 212.324219 192.085938 211.234375 193.128906 210.191406 C 194.167969 209.148438 195.257812 208.160156 196.398438 207.226562 C 197.535156 206.292969 198.71875 205.414062 199.941406 204.59375 C 201.167969 203.773438 202.425781 203.015625 203.726562 202.320312 C 205.023438 201.625 206.355469 200.996094 207.714844 200.429688 C 209.074219 199.863281 210.460938 199.363281 211.867188 198.933594 C 213.277344 198.503906 214.703125 198.144531 216.148438 197.855469 C 217.59375 197.5625 219.046875 197.34375 220.511719 197.195312 C 221.980469 197.046875 223.449219 196.972656 224.921875 196.96875 L 585.078125 196.96875 C 586.550781 196.972656 588.019531 197.046875 589.484375 197.195312 C 590.953125 197.34375 592.40625 197.5625 593.851562 197.855469 C 595.296875 198.144531 596.722656 198.503906 598.128906 198.933594 C 599.539062 199.363281 600.925781 199.863281 602.285156 200.429688 C 603.644531 200.996094 604.972656 201.625 606.273438 202.320312 C 607.570312 203.015625 608.832031 203.773438 610.058594 204.59375 C 611.28125 205.414062 612.464844 206.292969 613.601562 207.226562 C 614.738281 208.160156 615.832031 209.148438 616.871094 210.191406 C 617.914062 211.234375 618.902344 212.324219 619.835938 213.460938 C 620.773438 214.601562 621.648438 215.78125 622.46875 217.007812 C 623.289062 218.230469 624.046875 219.492188 624.742188 220.789062 C 625.4375 222.089844 626.070312 223.417969 626.632812 224.777344 C 627.199219 226.140625 627.699219 227.523438 628.128906 228.933594 C 628.558594 230.339844 628.917969 231.769531 629.210938 233.210938 C 629.5 234.65625 629.71875 236.113281 629.867188 237.578125 C 630.015625 239.042969 630.09375 240.511719 630.097656 241.988281 Z M 630.097656 483.515625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">Eletroneuromiografia<\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tExames neurol\u00f3gicos de membros inferiores e superiores especializados\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/exame-de-eletroneuromiografia-enmg\/\">\n\t\t\t\t\t\tSaiba mais\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d7cd90 elementor-cta--skin-cover animated-slow elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"0d7cd90\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-stacked elementor-shape-circle elementor-animated-item--grow\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><path fill=\"#960033\" d=\"M 286.921875 340.199219 C 339.757812 340.199219 372.601562 294.90625 372.601562 221.992188 C 372.730469 219.710938 372.734375 217.429688 372.605469 215.148438 C 372.480469 212.867188 372.230469 210.601562 371.847656 208.347656 C 371.46875 206.09375 370.964844 203.867188 370.335938 201.671875 C 369.707031 199.476562 368.953125 197.320312 368.082031 195.207031 C 367.210938 193.097656 366.226562 191.039062 365.125 189.035156 C 364.019531 187.035156 362.8125 185.101562 361.492188 183.234375 C 360.171875 181.371094 358.753906 179.582031 357.234375 177.875 C 355.714844 176.167969 354.105469 174.554688 352.402344 173.027344 C 326.871094 151.242188 286.921875 157.292969 285.226562 157.582031 C 284.167969 157.761719 283.152344 158.085938 282.1875 158.5625 C 281.226562 159.039062 280.347656 159.644531 279.5625 160.378906 C 278.777344 161.113281 278.113281 161.949219 277.574219 162.878906 C 277.035156 163.808594 276.640625 164.796875 276.394531 165.84375 C 276.070312 167.257812 267.679688 200.40625 221.378906 200.40625 C 220.667969 200.40625 219.96875 200.472656 219.269531 200.613281 C 218.574219 200.75 217.902344 200.957031 217.246094 201.226562 C 216.589844 201.5 215.96875 201.832031 215.378906 202.226562 C 214.789062 202.617188 214.242188 203.066406 213.742188 203.566406 C 213.238281 204.070312 212.792969 204.613281 212.398438 205.203125 C 212.003906 205.792969 211.671875 206.417969 211.402344 207.070312 C 211.128906 207.726562 210.925781 208.402344 210.785156 209.097656 C 210.648438 209.792969 210.578125 210.496094 210.578125 211.203125 C 210.601562 323.449219 258.410156 340.199219 286.921875 340.199219 Z M 295.003906 178.339844 C 298.808594 177.941406 302.621094 177.882812 306.441406 178.164062 C 310.257812 178.445312 314.019531 179.0625 317.726562 180.015625 C 321.4375 180.96875 325.03125 182.238281 328.511719 183.832031 C 331.992188 185.425781 335.304688 187.3125 338.449219 189.496094 C 340.648438 191.558594 342.589844 193.84375 344.273438 196.34375 C 345.960938 198.84375 347.34375 201.5 348.433594 204.3125 C 349.519531 207.125 350.277344 210.023438 350.710938 213.007812 C 351.144531 215.992188 351.242188 218.988281 351 221.992188 C 351 244.652344 346.355469 318.601562 286.921875 318.601562 C 244.804688 318.601562 233.667969 268.003906 232.328125 221.507812 C 235.667969 221.335938 238.980469 220.9375 242.261719 220.308594 C 245.546875 219.675781 248.769531 218.824219 251.933594 217.75 C 255.101562 216.675781 258.175781 215.390625 261.164062 213.890625 C 264.152344 212.390625 267.023438 210.691406 269.777344 208.796875 C 272.53125 206.898438 275.140625 204.824219 277.605469 202.566406 C 280.070312 200.308594 282.371094 197.894531 284.503906 195.320312 C 286.636719 192.746094 288.582031 190.035156 290.339844 187.191406 C 292.097656 184.347656 293.652344 181.398438 295.003906 178.339844 Z M 295.003906 178.339844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 696.601562 113.398438 L 369.121094 113.398438 C 366.324219 110.832031 363.414062 108.398438 360.390625 106.097656 C 357.367188 103.800781 354.242188 101.644531 351.019531 99.636719 C 347.796875 97.625 344.488281 95.769531 341.09375 94.066406 C 337.699219 92.363281 334.230469 90.820312 330.695312 89.4375 C 327.15625 88.054688 323.5625 86.839844 319.910156 85.789062 C 316.261719 84.742188 312.570312 83.863281 308.839844 83.152344 C 305.105469 82.445312 301.351562 81.914062 297.570312 81.554688 C 293.789062 81.191406 290 81.007812 286.199219 81 C 213.527344 81 156.601562 143.855469 156.601562 224.101562 L 156.601562 290.304688 C 156.582031 292.425781 156.46875 294.539062 156.261719 296.648438 C 156.054688 298.757812 155.753906 300.855469 155.363281 302.941406 C 154.972656 305.023438 154.488281 307.085938 153.914062 309.125 C 153.339844 311.167969 152.679688 313.179688 151.925781 315.160156 C 151.175781 317.144531 150.335938 319.089844 149.414062 320.996094 C 148.492188 322.90625 147.484375 324.769531 146.398438 326.589844 C 145.308594 328.410156 144.140625 330.175781 142.898438 331.894531 C 141.652344 333.609375 140.335938 335.269531 138.945312 336.867188 C 137.554688 338.46875 136.09375 340.003906 134.566406 341.472656 C 133.042969 342.945312 131.453125 344.347656 129.800781 345.675781 C 128.152344 347.007812 126.445312 348.261719 124.683594 349.441406 C 122.921875 350.625 121.113281 351.722656 119.253906 352.742188 C 117.394531 353.761719 115.496094 354.699219 113.554688 355.550781 C 111.613281 356.402344 109.636719 357.167969 107.628906 357.847656 C 105.621094 358.523438 103.585938 359.113281 101.523438 359.609375 C 99.464844 360.109375 97.386719 360.515625 95.289062 360.828125 C 94.132812 361.003906 92.96875 361.109375 91.800781 361.152344 C 91.390625 361.152344 90.984375 361.175781 90.574219 361.222656 C 90.167969 361.269531 89.765625 361.335938 89.367188 361.429688 C 88.96875 361.519531 88.574219 361.636719 88.191406 361.773438 C 87.804688 361.910156 87.425781 362.066406 87.058594 362.246094 C 86.691406 362.425781 86.335938 362.625 85.988281 362.847656 C 85.644531 363.066406 85.3125 363.304688 84.996094 363.5625 C 84.675781 363.820312 84.375 364.097656 84.089844 364.386719 C 83.800781 364.679688 83.53125 364.988281 83.28125 365.3125 C 83.027344 365.632812 82.796875 365.96875 82.582031 366.320312 C 82.371094 366.667969 82.175781 367.027344 82.003906 367.398438 C 81.832031 367.769531 81.679688 368.152344 81.550781 368.539062 C 81.421875 368.929688 81.316406 369.324219 81.230469 369.722656 C 81.144531 370.125 81.085938 370.527344 81.046875 370.933594 C 81.007812 371.34375 80.992188 371.75 81 372.160156 C 81.007812 372.570312 81.039062 372.976562 81.09375 373.382812 C 81.148438 373.789062 81.222656 374.191406 81.324219 374.585938 C 83.382812 380.890625 85.976562 386.964844 89.105469 392.8125 C 92.230469 398.664062 95.839844 404.195312 99.9375 409.410156 C 104.035156 414.621094 108.554688 419.441406 113.496094 423.863281 C 118.4375 428.285156 123.726562 432.242188 129.363281 435.738281 L 130.195312 436.296875 C 126.1875 447.105469 124.191406 458.273438 124.199219 469.800781 L 124.199219 653.398438 C 124.199219 654.34375 124.230469 655.285156 124.292969 656.226562 C 124.355469 657.164062 124.449219 658.101562 124.570312 659.039062 C 124.695312 659.972656 124.847656 660.902344 125.03125 661.828125 C 125.214844 662.75 125.429688 663.667969 125.675781 664.578125 C 125.917969 665.488281 126.191406 666.390625 126.496094 667.285156 C 126.800781 668.175781 127.132812 669.058594 127.492188 669.929688 C 127.851562 670.800781 128.242188 671.65625 128.660156 672.503906 C 129.078125 673.347656 129.519531 674.179688 129.992188 674.996094 C 130.464844 675.8125 130.960938 676.613281 131.484375 677.394531 C 132.007812 678.179688 132.558594 678.945312 133.132812 679.691406 C 133.707031 680.441406 134.304688 681.167969 134.925781 681.878906 C 135.546875 682.585938 136.191406 683.273438 136.859375 683.941406 C 137.523438 684.605469 138.210938 685.25 138.921875 685.871094 C 139.628906 686.492188 140.359375 687.089844 141.105469 687.664062 C 141.855469 688.238281 142.621094 688.789062 143.40625 689.3125 C 144.1875 689.835938 144.988281 690.332031 145.804688 690.804688 C 146.621094 691.273438 147.453125 691.71875 148.296875 692.136719 C 149.144531 692.550781 150 692.941406 150.871094 693.300781 C 151.742188 693.664062 152.625 693.996094 153.519531 694.296875 C 154.410156 694.601562 155.3125 694.875 156.222656 695.117188 C 157.132812 695.359375 158.050781 695.574219 158.976562 695.757812 C 159.902344 695.941406 160.832031 696.097656 161.765625 696.21875 C 162.699219 696.34375 163.636719 696.433594 164.578125 696.496094 C 165.519531 696.558594 166.460938 696.589844 167.402344 696.589844 C 168.34375 696.589844 169.289062 696.558594 170.226562 696.496094 C 171.167969 696.433594 172.105469 696.339844 173.039062 696.21875 C 173.976562 696.09375 174.90625 695.941406 175.828125 695.757812 C 176.753906 695.574219 177.671875 695.359375 178.582031 695.117188 C 179.492188 694.871094 180.394531 694.597656 181.289062 694.296875 C 182.179688 693.992188 183.0625 693.660156 183.933594 693.300781 C 184.804688 692.9375 185.660156 692.550781 186.507812 692.132812 C 187.351562 691.714844 188.183594 691.273438 189 690.800781 L 189 707.398438 C 189 708.105469 189.035156 708.8125 189.105469 709.515625 C 189.171875 710.222656 189.277344 710.921875 189.414062 711.613281 C 189.554688 712.308594 189.726562 712.992188 189.929688 713.671875 C 190.136719 714.347656 190.375 715.011719 190.644531 715.664062 C 190.914062 716.320312 191.21875 716.957031 191.550781 717.582031 C 191.882812 718.207031 192.246094 718.8125 192.640625 719.398438 C 193.035156 719.988281 193.453125 720.554688 193.902344 721.101562 C 194.351562 721.648438 194.828125 722.171875 195.328125 722.671875 C 195.828125 723.171875 196.351562 723.648438 196.898438 724.097656 C 197.445312 724.546875 198.011719 724.964844 198.601562 725.359375 C 199.1875 725.753906 199.792969 726.117188 200.417969 726.449219 C 201.042969 726.78125 201.679688 727.085938 202.335938 727.355469 C 202.988281 727.625 203.652344 727.863281 204.328125 728.070312 C 205.007812 728.273438 205.691406 728.445312 206.386719 728.585938 C 207.078125 728.722656 207.777344 728.828125 208.484375 728.894531 C 209.1875 728.964844 209.890625 729 210.601562 729 L 383.398438 729 C 384.105469 729 384.8125 728.964844 385.515625 728.894531 C 386.222656 728.828125 386.921875 728.722656 387.613281 728.585938 C 388.308594 728.445312 388.992188 728.273438 389.671875 728.070312 C 390.347656 727.863281 391.011719 727.625 391.664062 727.355469 C 392.320312 727.085938 392.957031 726.78125 393.582031 726.449219 C 394.207031 726.117188 394.8125 725.753906 395.398438 725.359375 C 395.988281 724.964844 396.554688 724.546875 397.101562 724.097656 C 397.648438 723.648438 398.171875 723.171875 398.671875 722.671875 C 399.171875 722.171875 399.648438 721.648438 400.097656 721.101562 C 400.546875 720.554688 400.964844 719.988281 401.359375 719.398438 C 401.753906 718.8125 402.117188 718.207031 402.449219 717.582031 C 402.78125 716.957031 403.085938 716.320312 403.355469 715.664062 C 403.625 715.011719 403.863281 714.347656 404.070312 713.671875 C 404.273438 712.992188 404.445312 712.308594 404.585938 711.613281 C 404.722656 710.921875 404.828125 710.222656 404.894531 709.515625 C 404.964844 708.8125 405 708.105469 405 707.398438 L 405 620.332031 L 516.789062 671.089844 C 518.726562 671.972656 520.714844 672.703125 522.757812 673.292969 C 524.800781 673.878906 526.878906 674.3125 528.984375 674.59375 C 531.09375 674.875 533.210938 674.996094 535.335938 674.964844 C 537.460938 674.933594 539.574219 674.746094 541.671875 674.402344 C 543.769531 674.058594 545.832031 673.5625 547.855469 672.914062 C 549.882812 672.265625 551.847656 671.472656 553.757812 670.53125 C 555.664062 669.59375 557.492188 668.519531 559.242188 667.3125 C 560.992188 666.101562 562.640625 664.773438 564.195312 663.320312 C 565.75 661.867188 567.1875 660.308594 568.507812 658.644531 C 569.832031 656.980469 571.023438 655.226562 572.089844 653.386719 C 573.152344 651.546875 574.074219 649.636719 574.855469 647.660156 C 575.640625 645.679688 576.273438 643.65625 576.753906 641.585938 C 577.238281 639.515625 577.566406 637.421875 577.742188 635.300781 C 577.914062 633.183594 577.929688 631.0625 577.792969 628.941406 C 577.652344 626.820312 577.359375 624.71875 576.910156 622.640625 C 576.460938 620.5625 575.859375 618.53125 575.109375 616.539062 C 573.714844 612.859375 571.847656 609.441406 569.507812 606.277344 C 567.164062 603.117188 564.441406 600.332031 561.328125 597.921875 L 617.761719 542.289062 C 618.3125 541.804688 618.808594 541.269531 619.25 540.683594 C 619.691406 540.097656 620.070312 539.472656 620.382812 538.808594 C 620.699219 538.144531 620.945312 537.457031 621.117188 536.742188 C 621.292969 536.027344 621.390625 535.304688 621.417969 534.570312 C 621.445312 533.839844 621.398438 533.109375 621.273438 532.386719 C 621.152344 531.660156 620.960938 530.957031 620.691406 530.273438 C 620.425781 529.585938 620.09375 528.9375 619.695312 528.320312 C 619.296875 527.703125 618.839844 527.132812 618.328125 526.609375 C 617.8125 526.085938 617.25 525.621094 616.640625 525.210938 C 616.03125 524.800781 615.386719 524.460938 614.707031 524.183594 C 614.027344 523.90625 613.324219 523.699219 612.601562 523.5625 C 611.882812 523.429688 611.152344 523.371094 610.417969 523.382812 C 609.683594 523.398438 608.960938 523.484375 608.242188 523.648438 C 607.527344 523.808594 606.835938 524.042969 606.164062 524.34375 C 605.496094 524.648438 604.867188 525.015625 604.273438 525.449219 C 603.679688 525.878906 603.132812 526.367188 602.640625 526.910156 L 541.273438 587.390625 L 456.0625 548.640625 L 449.28125 480.601562 L 696.601562 480.601562 C 697.660156 480.601562 698.71875 480.546875 699.777344 480.445312 C 700.832031 480.339844 701.878906 480.183594 702.921875 479.976562 C 703.960938 479.769531 704.988281 479.511719 706.003906 479.203125 C 707.019531 478.898438 708.019531 478.539062 709 478.132812 C 709.980469 477.726562 710.9375 477.273438 711.875 476.773438 C 712.808594 476.273438 713.71875 475.730469 714.601562 475.140625 C 715.484375 474.550781 716.335938 473.917969 717.152344 473.246094 C 717.972656 472.574219 718.761719 471.859375 719.511719 471.109375 C 720.261719 470.359375 720.972656 469.574219 721.644531 468.753906 C 722.320312 467.933594 722.949219 467.082031 723.539062 466.199219 C 724.128906 465.316406 724.675781 464.410156 725.175781 463.472656 C 725.675781 462.539062 726.128906 461.578125 726.535156 460.597656 C 726.941406 459.617188 727.296875 458.621094 727.605469 457.605469 C 727.914062 456.589844 728.171875 455.5625 728.378906 454.519531 C 728.585938 453.480469 728.738281 452.433594 728.84375 451.375 C 728.949219 450.320312 729 449.261719 729 448.199219 L 729 145.800781 C 729 144.738281 728.949219 143.679688 728.84375 142.625 C 728.738281 141.566406 728.585938 140.519531 728.378906 139.480469 C 728.171875 138.4375 727.914062 137.410156 727.605469 136.394531 C 727.296875 135.378906 726.941406 134.382812 726.535156 133.402344 C 726.128906 132.421875 725.675781 131.460938 725.175781 130.527344 C 724.675781 129.589844 724.128906 128.683594 723.539062 127.800781 C 722.949219 126.917969 722.320312 126.066406 721.644531 125.246094 C 720.972656 124.425781 720.261719 123.640625 719.511719 122.890625 C 718.761719 122.140625 717.972656 121.425781 717.15625 120.753906 C 716.335938 120.082031 715.484375 119.449219 714.601562 118.859375 C 713.71875 118.269531 712.808594 117.726562 711.875 117.226562 C 710.9375 116.726562 709.980469 116.273438 709 115.867188 C 708.019531 115.460938 707.019531 115.101562 706.003906 114.796875 C 704.988281 114.488281 703.960938 114.230469 702.921875 114.023438 C 701.878906 113.816406 700.832031 113.660156 699.777344 113.554688 C 698.71875 113.453125 697.660156 113.398438 696.601562 113.398438 Z M 106.921875 380.722656 C 109.417969 380.085938 111.890625 379.34375 114.328125 378.507812 C 116.769531 377.667969 119.167969 376.730469 121.53125 375.695312 C 123.894531 374.65625 126.210938 373.527344 128.480469 372.300781 C 130.75 371.078125 132.96875 369.761719 135.128906 368.355469 C 137.292969 366.949219 139.394531 365.457031 141.4375 363.878906 C 143.476562 362.300781 145.449219 360.644531 147.355469 358.902344 C 149.261719 357.164062 151.089844 355.351562 152.847656 353.460938 C 154.605469 351.574219 156.28125 349.617188 157.878906 347.589844 C 159.476562 345.5625 160.988281 343.476562 162.414062 341.328125 C 163.839844 339.179688 165.179688 336.972656 166.425781 334.714844 C 167.671875 332.457031 168.824219 330.152344 169.878906 327.796875 C 170.9375 325.445312 171.898438 323.054688 172.761719 320.621094 C 173.625 318.191406 174.386719 315.726562 175.046875 313.234375 C 175.707031 310.742188 176.265625 308.226562 176.722656 305.683594 C 177.175781 303.144531 177.527344 300.59375 177.773438 298.023438 C 178.023438 295.457031 178.164062 292.882812 178.199219 290.304688 L 178.199219 224.101562 C 178.199219 155.960938 225.644531 102.601562 286.199219 102.601562 C 289.5 102.585938 292.789062 102.738281 296.074219 103.050781 C 299.355469 103.359375 302.617188 103.832031 305.851562 104.464844 C 309.089844 105.101562 312.289062 105.890625 315.449219 106.839844 C 318.605469 107.785156 321.710938 108.886719 324.761719 110.140625 C 327.8125 111.394531 330.792969 112.796875 333.707031 114.34375 C 336.621094 115.890625 339.449219 117.578125 342.195312 119.40625 C 344.941406 121.230469 347.59375 123.1875 350.144531 125.277344 C 352.699219 127.363281 355.144531 129.570312 357.480469 131.902344 C 360.445312 134.941406 363.253906 138.121094 365.90625 141.4375 C 368.5625 144.753906 371.042969 148.195312 373.359375 151.757812 C 375.671875 155.316406 377.804688 158.984375 379.757812 162.757812 C 381.707031 166.53125 383.46875 170.390625 385.042969 174.335938 C 386.613281 178.28125 387.988281 182.296875 389.164062 186.375 C 390.339844 190.457031 391.3125 194.585938 392.078125 198.765625 C 392.847656 202.941406 393.410156 207.148438 393.765625 211.378906 C 394.117188 215.613281 394.265625 219.851562 394.199219 224.101562 L 394.199219 290.304688 C 394.234375 292.867188 394.375 295.421875 394.617188 297.972656 C 394.859375 300.523438 395.203125 303.058594 395.652344 305.582031 C 396.101562 308.105469 396.652344 310.605469 397.304688 313.082031 C 397.957031 315.5625 398.707031 318.007812 399.554688 320.425781 C 400.40625 322.84375 401.351562 325.21875 402.394531 327.5625 C 403.4375 329.902344 404.574219 332.195312 405.804688 334.441406 C 407.035156 336.691406 408.351562 338.886719 409.761719 341.027344 C 411.167969 343.167969 412.660156 345.246094 414.238281 347.265625 C 415.8125 349.285156 417.46875 351.238281 419.203125 353.125 C 420.9375 355.007812 422.746094 356.820312 424.628906 358.558594 C 426.511719 360.296875 428.460938 361.957031 430.476562 363.539062 C 432.492188 365.117188 434.570312 366.613281 436.707031 368.027344 C 438.847656 369.4375 441.039062 370.761719 443.285156 371.996094 C 445.527344 373.226562 447.820312 374.371094 450.160156 375.417969 C 452.496094 376.464844 454.875 377.417969 457.289062 378.269531 C 459.703125 379.125 462.148438 379.882812 464.625 380.539062 C 460.265625 387.421875 455.339844 393.875 449.847656 399.894531 C 444.355469 405.914062 438.378906 411.410156 431.925781 416.382812 C 429.734375 413.035156 427.34375 409.839844 424.753906 406.789062 C 422.167969 403.738281 419.402344 400.859375 416.457031 398.152344 C 413.511719 395.445312 410.410156 392.929688 407.15625 390.605469 C 403.898438 388.285156 400.511719 386.171875 396.992188 384.265625 C 393.476562 382.363281 389.855469 380.683594 386.128906 379.230469 C 382.402344 377.777344 378.601562 376.558594 374.722656 375.574219 C 370.84375 374.589844 366.921875 373.847656 362.953125 373.351562 C 358.984375 372.855469 355 372.605469 351 372.601562 L 221.398438 372.601562 C 217.371094 372.617188 213.359375 372.882812 209.367188 373.394531 C 205.371094 373.910156 201.421875 374.667969 197.523438 375.667969 C 193.621094 376.671875 189.796875 377.90625 186.046875 379.382812 C 182.300781 380.855469 178.65625 382.554688 175.121094 384.480469 C 171.582031 386.40625 168.175781 388.539062 164.902344 390.886719 C 161.625 393.230469 158.507812 395.769531 155.550781 398.5 C 152.589844 401.230469 149.808594 404.136719 147.207031 407.210938 C 144.605469 410.285156 142.203125 413.507812 140 416.878906 C 133.035156 412.359375 126.753906 407.039062 121.148438 400.914062 C 115.546875 394.789062 110.804688 388.058594 106.921875 380.722656 Z M 543.585938 612.164062 C 544.230469 612.457031 544.859375 612.777344 545.472656 613.128906 C 546.082031 613.480469 546.675781 613.863281 547.253906 614.273438 C 547.828125 614.683594 548.382812 615.121094 548.914062 615.589844 C 549.445312 616.054688 549.953125 616.542969 550.4375 617.058594 C 550.917969 617.574219 551.375 618.113281 551.804688 618.671875 C 552.238281 619.234375 552.636719 619.8125 553.011719 620.414062 C 553.382812 621.015625 553.726562 621.632812 554.039062 622.265625 C 554.351562 622.898438 554.632812 623.546875 554.878906 624.210938 C 555.128906 624.871094 555.34375 625.542969 555.527344 626.226562 C 555.707031 626.910156 555.855469 627.597656 555.96875 628.296875 C 556.082031 628.992188 556.164062 629.695312 556.207031 630.398438 C 556.253906 631.105469 556.261719 631.8125 556.238281 632.515625 C 556.210938 633.222656 556.152344 633.925781 556.058594 634.628906 C 555.964844 635.328125 555.835938 636.023438 555.671875 636.710938 C 555.511719 637.398438 555.316406 638.074219 555.085938 638.742188 C 554.855469 639.410156 554.59375 640.066406 554.300781 640.710938 C 553.996094 641.34375 553.667969 641.964844 553.304688 642.566406 C 552.945312 643.171875 552.554688 643.753906 552.136719 644.320312 C 551.722656 644.886719 551.277344 645.433594 550.808594 645.957031 C 550.339844 646.476562 549.84375 646.976562 549.328125 647.453125 C 548.808594 647.929688 548.269531 648.378906 547.707031 648.804688 C 547.148438 649.226562 546.566406 649.621094 545.96875 649.992188 C 545.371094 650.359375 544.753906 650.695312 544.121094 651.007812 C 543.492188 651.316406 542.84375 651.59375 542.1875 651.839844 C 541.527344 652.085938 540.859375 652.300781 540.179688 652.484375 C 539.503906 652.664062 538.816406 652.816406 538.121094 652.929688 C 537.429688 653.046875 536.730469 653.128906 536.03125 653.179688 C 535.328125 653.230469 534.628906 653.246094 533.925781 653.226562 C 533.222656 653.207031 532.519531 653.15625 531.824219 653.070312 C 531.125 652.984375 530.433594 652.867188 529.746094 652.714844 C 529.058594 652.5625 528.382812 652.378906 527.714844 652.160156 C 527.046875 651.941406 526.390625 651.695312 525.742188 651.414062 L 407.050781 597.46875 C 405.085938 596.570312 403.304688 595.390625 401.714844 593.925781 L 401.554688 593.804688 C 401.554688 593.804688 401.488281 593.699219 401.4375 593.65625 C 399.460938 591.917969 397.871094 589.882812 396.660156 587.550781 C 395.449219 585.21875 394.699219 582.746094 394.414062 580.132812 L 384.371094 490.0625 C 384.292969 489.355469 384.144531 488.664062 383.929688 487.988281 C 383.714844 487.3125 383.433594 486.660156 383.089844 486.039062 C 382.746094 485.417969 382.347656 484.835938 381.890625 484.292969 C 381.429688 483.75 380.925781 483.257812 380.371094 482.816406 C 379.8125 482.375 379.222656 481.988281 378.589844 481.664062 C 377.960938 481.335938 377.304688 481.074219 376.621094 480.878906 C 375.9375 480.683594 375.242188 480.554688 374.535156 480.496094 C 373.828125 480.433594 373.121094 480.445312 372.417969 480.523438 C 371.710938 480.605469 371.019531 480.75 370.34375 480.964844 C 369.667969 481.183594 369.019531 481.460938 368.394531 481.804688 C 367.773438 482.148438 367.191406 482.550781 366.648438 483.007812 C 366.109375 483.464844 365.613281 483.972656 365.171875 484.527344 C 364.730469 485.082031 364.34375 485.675781 364.019531 486.304688 C 363.691406 486.9375 363.433594 487.59375 363.234375 488.277344 C 363.039062 488.957031 362.910156 489.652344 362.851562 490.359375 C 362.789062 491.066406 362.800781 491.773438 362.878906 492.480469 L 372.914062 582.519531 C 373.40625 586.878906 374.550781 591.058594 376.339844 595.0625 C 378.128906 599.066406 380.480469 602.703125 383.398438 605.976562 L 383.398438 707.398438 L 210.601562 707.398438 L 210.601562 491.398438 C 210.601562 490.691406 210.53125 489.988281 210.390625 489.292969 C 210.253906 488.597656 210.050781 487.921875 209.777344 487.265625 C 209.507812 486.613281 209.171875 485.988281 208.78125 485.398438 C 208.386719 484.808594 207.9375 484.265625 207.4375 483.761719 C 206.933594 483.261719 206.390625 482.8125 205.800781 482.421875 C 205.210938 482.027344 204.589844 481.695312 203.933594 481.421875 C 203.277344 481.152344 202.601562 480.945312 201.90625 480.808594 C 201.210938 480.667969 200.507812 480.601562 199.800781 480.601562 C 199.089844 480.601562 198.386719 480.667969 197.691406 480.808594 C 196.996094 480.945312 196.320312 481.152344 195.667969 481.421875 C 195.011719 481.695312 194.390625 482.027344 193.800781 482.421875 C 193.210938 482.8125 192.664062 483.261719 192.164062 483.761719 C 191.660156 484.265625 191.214844 484.808594 190.820312 485.398438 C 190.425781 485.988281 190.09375 486.613281 189.820312 487.265625 C 189.550781 487.921875 189.347656 488.597656 189.207031 489.292969 C 189.070312 489.988281 189 490.691406 189 491.398438 L 189 653.398438 C 189 654.109375 188.964844 654.8125 188.894531 655.515625 C 188.828125 656.222656 188.722656 656.921875 188.585938 657.613281 C 188.445312 658.308594 188.273438 658.992188 188.070312 659.671875 C 187.863281 660.347656 187.625 661.011719 187.355469 661.664062 C 187.085938 662.320312 186.78125 662.957031 186.449219 663.582031 C 186.117188 664.207031 185.753906 664.8125 185.359375 665.398438 C 184.964844 665.988281 184.546875 666.554688 184.097656 667.101562 C 183.648438 667.648438 183.171875 668.171875 182.671875 668.671875 C 182.171875 669.171875 181.648438 669.648438 181.101562 670.097656 C 180.554688 670.546875 179.988281 670.964844 179.398438 671.359375 C 178.8125 671.753906 178.207031 672.117188 177.582031 672.449219 C 176.957031 672.78125 176.320312 673.085938 175.664062 673.355469 C 175.011719 673.625 174.347656 673.863281 173.671875 674.070312 C 172.992188 674.273438 172.308594 674.445312 171.613281 674.585938 C 170.921875 674.722656 170.222656 674.828125 169.515625 674.894531 C 168.8125 674.964844 168.109375 675 167.398438 675 C 166.691406 675 165.988281 674.964844 165.28125 674.894531 C 164.578125 674.828125 163.878906 674.722656 163.1875 674.585938 C 162.492188 674.445312 161.808594 674.273438 161.128906 674.070312 C 160.453125 673.863281 159.789062 673.625 159.132812 673.355469 C 158.480469 673.085938 157.839844 672.78125 157.21875 672.449219 C 156.59375 672.117188 155.988281 671.753906 155.398438 671.359375 C 154.8125 670.964844 154.242188 670.546875 153.695312 670.097656 C 153.148438 669.648438 152.625 669.171875 152.125 668.671875 C 151.625 668.171875 151.152344 667.648438 150.703125 667.101562 C 150.253906 666.554688 149.832031 665.988281 149.441406 665.398438 C 149.046875 664.8125 148.683594 664.207031 148.351562 663.582031 C 148.015625 662.957031 147.714844 662.320312 147.445312 661.664062 C 147.171875 661.011719 146.933594 660.347656 146.730469 659.671875 C 146.523438 658.992188 146.351562 658.308594 146.214844 657.613281 C 146.078125 656.921875 145.972656 656.222656 145.902344 655.515625 C 145.835938 654.8125 145.800781 654.109375 145.800781 653.398438 L 145.800781 469.800781 C 145.800781 468.5625 145.832031 467.328125 145.890625 466.089844 C 145.953125 464.855469 146.042969 463.621094 146.164062 462.390625 C 146.285156 461.160156 146.4375 459.929688 146.617188 458.707031 C 146.800781 457.484375 147.011719 456.265625 147.253906 455.050781 C 147.492188 453.835938 147.765625 452.628906 148.066406 451.429688 C 148.367188 450.230469 148.695312 449.039062 149.054688 447.855469 C 149.414062 446.671875 149.800781 445.496094 150.21875 444.332031 C 150.636719 443.167969 151.082031 442.011719 151.554688 440.871094 C 152.027344 439.726562 152.53125 438.59375 153.058594 437.476562 C 153.585938 436.359375 154.144531 435.253906 154.726562 434.164062 C 155.308594 433.070312 155.917969 431.996094 156.554688 430.933594 C 157.191406 429.871094 157.851562 428.828125 158.539062 427.800781 C 159.226562 426.769531 159.941406 425.757812 160.675781 424.765625 C 161.414062 423.769531 162.175781 422.796875 162.960938 421.839844 C 163.746094 420.882812 164.554688 419.945312 165.382812 419.03125 C 166.214844 418.113281 167.066406 417.21875 167.941406 416.34375 C 168.816406 415.46875 169.714844 414.613281 170.628906 413.785156 C 171.546875 412.953125 172.484375 412.144531 173.441406 411.359375 C 174.394531 410.574219 175.371094 409.816406 176.363281 409.078125 C 177.359375 408.339844 178.371094 407.628906 179.398438 406.941406 C 180.425781 406.253906 181.472656 405.589844 182.535156 404.957031 C 183.59375 404.320312 184.671875 403.710938 185.761719 403.125 C 186.855469 402.542969 187.957031 401.988281 189.078125 401.457031 C 190.195312 400.929688 191.324219 400.429688 192.46875 399.953125 C 193.613281 399.480469 194.765625 399.035156 195.929688 398.621094 C 197.097656 398.203125 198.269531 397.816406 199.453125 397.457031 C 200.636719 397.097656 201.832031 396.765625 203.03125 396.464844 C 204.230469 396.164062 205.4375 395.894531 206.652344 395.652344 C 207.863281 395.410156 209.082031 395.199219 210.308594 395.019531 C 211.53125 394.835938 212.757812 394.683594 213.988281 394.5625 C 215.222656 394.441406 216.453125 394.351562 217.691406 394.292969 C 218.925781 394.230469 220.164062 394.199219 221.398438 394.199219 L 351 394.199219 C 354.390625 394.195312 357.765625 394.421875 361.128906 394.875 C 364.488281 395.328125 367.804688 396.003906 371.074219 396.902344 C 374.34375 397.804688 377.535156 398.917969 380.65625 400.25 C 383.773438 401.582031 386.789062 403.113281 389.703125 404.851562 C 392.613281 406.589844 395.394531 408.515625 398.046875 410.628906 C 400.699219 412.742188 403.199219 415.023438 405.542969 417.472656 C 407.886719 419.925781 410.054688 422.519531 412.050781 425.265625 C 414.042969 428.007812 415.84375 430.871094 417.453125 433.859375 C 420.523438 439.539062 422.835938 445.515625 424.394531 451.78125 C 425.953125 458.046875 426.707031 464.410156 426.652344 470.871094 L 435.1875 556.933594 C 435.277344 557.875 435.492188 558.789062 435.824219 559.675781 C 436.15625 560.5625 436.601562 561.390625 437.152344 562.160156 C 437.703125 562.929688 438.34375 563.613281 439.074219 564.214844 C 439.804688 564.816406 440.597656 565.3125 441.460938 565.703125 Z M 707.398438 448.199219 C 707.398438 448.910156 707.332031 449.613281 707.191406 450.308594 C 707.054688 451.003906 706.847656 451.679688 706.578125 452.332031 C 706.304688 452.988281 705.972656 453.609375 705.578125 454.199219 C 705.1875 454.789062 704.738281 455.335938 704.238281 455.835938 C 703.734375 456.339844 703.191406 456.785156 702.601562 457.179688 C 702.011719 457.574219 701.386719 457.90625 700.734375 458.179688 C 700.078125 458.449219 699.402344 458.652344 698.707031 458.792969 C 698.011719 458.929688 697.308594 459 696.601562 459 L 447.519531 459 C 446.636719 451.007812 444.777344 443.25 441.945312 435.726562 C 447.402344 431.945312 452.558594 427.796875 457.417969 423.273438 C 462.277344 418.75 466.785156 413.902344 470.941406 408.730469 C 475.101562 403.554688 478.867188 398.113281 482.238281 392.394531 C 485.613281 386.679688 488.558594 380.75 491.074219 374.609375 C 491.171875 374.214844 491.246094 373.8125 491.300781 373.410156 C 491.351562 373.003906 491.382812 372.601562 491.386719 372.191406 C 491.394531 371.785156 491.378906 371.378906 491.339844 370.972656 C 491.300781 370.566406 491.238281 370.164062 491.15625 369.765625 C 491.070312 369.367188 490.964844 368.976562 490.835938 368.589844 C 490.707031 368.203125 490.558594 367.824219 490.386719 367.453125 C 490.214844 367.085938 490.023438 366.726562 489.8125 366.378906 C 489.601562 366.03125 489.371094 365.695312 489.121094 365.371094 C 488.871094 365.050781 488.605469 364.742188 488.324219 364.449219 C 488.039062 364.15625 487.738281 363.882812 487.425781 363.621094 C 487.109375 363.363281 486.78125 363.125 486.441406 362.902344 C 486.097656 362.679688 485.746094 362.480469 485.382812 362.296875 C 485.015625 362.113281 484.644531 361.953125 484.261719 361.8125 C 483.878906 361.671875 483.488281 361.554688 483.09375 361.457031 C 482.695312 361.363281 482.296875 361.289062 481.894531 361.238281 C 481.488281 361.1875 481.082031 361.15625 480.675781 361.152344 C 479.367188 361.109375 478.070312 360.988281 476.777344 360.796875 C 474.6875 360.472656 472.617188 360.0625 470.5625 359.558594 C 468.511719 359.054688 466.484375 358.460938 464.480469 357.78125 C 462.480469 357.097656 460.515625 356.328125 458.582031 355.472656 C 456.648438 354.617188 454.757812 353.675781 452.90625 352.652344 C 451.058594 351.628906 449.253906 350.527344 447.503906 349.347656 C 445.75 348.164062 444.054688 346.910156 442.410156 345.578125 C 440.769531 344.246094 439.1875 342.84375 437.671875 341.375 C 436.152344 339.902344 434.703125 338.367188 433.316406 336.769531 C 431.933594 335.171875 430.625 333.515625 429.386719 331.800781 C 428.152344 330.085938 426.992188 328.320312 425.910156 326.503906 C 424.832031 324.6875 423.832031 322.824219 422.914062 320.921875 C 421.996094 319.015625 421.164062 317.074219 420.421875 315.097656 C 419.675781 313.117188 419.015625 311.113281 418.449219 309.074219 C 417.878906 307.039062 417.402344 304.984375 417.015625 302.90625 C 416.628906 300.828125 416.332031 298.734375 416.128906 296.632812 C 415.925781 294.527344 415.816406 292.417969 415.800781 290.304688 L 415.800781 224.101562 C 415.839844 216.1875 415.277344 208.316406 414.109375 200.488281 C 412.9375 192.660156 411.179688 184.96875 408.832031 177.410156 C 406.480469 169.851562 403.566406 162.519531 400.09375 155.410156 C 396.617188 148.300781 392.617188 141.496094 388.097656 135 L 696.601562 135 C 697.308594 135 698.011719 135.070312 698.707031 135.207031 C 699.402344 135.347656 700.078125 135.550781 700.734375 135.820312 C 701.386719 136.09375 702.011719 136.425781 702.601562 136.820312 C 703.191406 137.214844 703.734375 137.660156 704.238281 138.164062 C 704.738281 138.664062 705.1875 139.210938 705.578125 139.800781 C 705.972656 140.390625 706.304688 141.011719 706.578125 141.667969 C 706.847656 142.320312 707.054688 142.996094 707.191406 143.691406 C 707.332031 144.386719 707.398438 145.089844 707.398438 145.800781 Z M 707.398438 448.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 459 199.800781 L 599.398438 199.800781 C 600.109375 199.800781 600.8125 199.730469 601.507812 199.59375 C 602.203125 199.453125 602.878906 199.25 603.53125 198.976562 C 604.1875 198.707031 604.808594 198.375 605.398438 197.980469 C 605.988281 197.585938 606.535156 197.136719 607.035156 196.636719 C 607.539062 196.136719 607.984375 195.589844 608.378906 195 C 608.773438 194.410156 609.105469 193.789062 609.378906 193.132812 C 609.648438 192.476562 609.855469 191.800781 609.992188 191.105469 C 610.128906 190.410156 610.199219 189.710938 610.199219 189 C 610.199219 188.289062 610.128906 187.589844 609.992188 186.894531 C 609.855469 186.199219 609.648438 185.523438 609.378906 184.867188 C 609.105469 184.210938 608.773438 183.589844 608.378906 183 C 607.984375 182.410156 607.539062 181.863281 607.035156 181.363281 C 606.535156 180.863281 605.988281 180.414062 605.398438 180.019531 C 604.808594 179.625 604.1875 179.292969 603.53125 179.023438 C 602.878906 178.75 602.203125 178.546875 601.507812 178.40625 C 600.8125 178.269531 600.109375 178.199219 599.398438 178.199219 L 459 178.199219 C 458.289062 178.199219 457.589844 178.269531 456.894531 178.40625 C 456.199219 178.546875 455.523438 178.75 454.867188 179.023438 C 454.210938 179.292969 453.589844 179.625 453 180.019531 C 452.410156 180.414062 451.863281 180.863281 451.363281 181.363281 C 450.863281 181.863281 450.414062 182.410156 450.019531 183 C 449.625 183.589844 449.292969 184.210938 449.023438 184.867188 C 448.75 185.523438 448.546875 186.199219 448.40625 186.894531 C 448.269531 187.589844 448.199219 188.289062 448.199219 189 C 448.199219 189.710938 448.269531 190.410156 448.40625 191.105469 C 448.546875 191.800781 448.75 192.476562 449.023438 193.132812 C 449.292969 193.789062 449.625 194.410156 450.019531 195 C 450.414062 195.589844 450.863281 196.136719 451.363281 196.636719 C 451.863281 197.136719 452.410156 197.585938 453 197.980469 C 453.589844 198.375 454.210938 198.707031 454.867188 198.976562 C 455.523438 199.25 456.199219 199.453125 456.894531 199.59375 C 457.589844 199.730469 458.289062 199.800781 459 199.800781 Z M 459 199.800781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 653.398438 178.199219 L 642.601562 178.199219 C 641.890625 178.199219 641.1875 178.269531 640.492188 178.40625 C 639.796875 178.546875 639.121094 178.75 638.46875 179.023438 C 637.8125 179.292969 637.1875 179.625 636.601562 180.019531 C 636.011719 180.414062 635.464844 180.863281 634.964844 181.363281 C 634.460938 181.863281 634.015625 182.410156 633.621094 183 C 633.226562 183.589844 632.894531 184.210938 632.621094 184.867188 C 632.351562 185.523438 632.144531 186.199219 632.007812 186.894531 C 631.871094 187.589844 631.800781 188.289062 631.800781 189 C 631.800781 189.710938 631.871094 190.410156 632.007812 191.105469 C 632.144531 191.800781 632.351562 192.476562 632.621094 193.132812 C 632.894531 193.789062 633.226562 194.410156 633.621094 195 C 634.015625 195.589844 634.460938 196.136719 634.964844 196.636719 C 635.464844 197.136719 636.011719 197.585938 636.601562 197.980469 C 637.1875 198.375 637.8125 198.707031 638.46875 198.976562 C 639.121094 199.25 639.796875 199.453125 640.492188 199.59375 C 641.1875 199.730469 641.890625 199.800781 642.601562 199.800781 L 653.398438 199.800781 C 654.109375 199.800781 654.8125 199.730469 655.507812 199.59375 C 656.203125 199.453125 656.878906 199.25 657.53125 198.976562 C 658.1875 198.707031 658.808594 198.375 659.398438 197.980469 C 659.988281 197.585938 660.535156 197.136719 661.035156 196.636719 C 661.539062 196.136719 661.984375 195.589844 662.378906 195 C 662.773438 194.410156 663.105469 193.789062 663.378906 193.132812 C 663.648438 192.476562 663.855469 191.800781 663.992188 191.105469 C 664.128906 190.410156 664.199219 189.710938 664.199219 189 C 664.199219 188.289062 664.128906 187.589844 663.992188 186.894531 C 663.855469 186.199219 663.648438 185.523438 663.378906 184.867188 C 663.105469 184.210938 662.773438 183.589844 662.378906 183 C 661.984375 182.410156 661.539062 181.863281 661.035156 181.363281 C 660.535156 180.863281 659.988281 180.414062 659.398438 180.019531 C 658.808594 179.625 658.1875 179.292969 657.53125 179.023438 C 656.878906 178.75 656.203125 178.546875 655.507812 178.40625 C 654.8125 178.269531 654.109375 178.199219 653.398438 178.199219 Z M 653.398438 178.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 653.398438 232.199219 L 513 232.199219 C 512.289062 232.199219 511.589844 232.269531 510.894531 232.40625 C 510.199219 232.546875 509.523438 232.75 508.867188 233.023438 C 508.210938 233.292969 507.589844 233.625 507 234.019531 C 506.410156 234.414062 505.863281 234.863281 505.363281 235.363281 C 504.863281 235.863281 504.414062 236.410156 504.019531 237 C 503.625 237.589844 503.292969 238.210938 503.023438 238.867188 C 502.75 239.523438 502.546875 240.199219 502.40625 240.894531 C 502.269531 241.589844 502.199219 242.289062 502.199219 243 C 502.199219 243.710938 502.269531 244.410156 502.40625 245.105469 C 502.546875 245.800781 502.75 246.476562 503.023438 247.132812 C 503.292969 247.789062 503.625 248.410156 504.019531 249 C 504.414062 249.589844 504.863281 250.136719 505.363281 250.636719 C 505.863281 251.136719 506.410156 251.585938 507 251.980469 C 507.589844 252.375 508.210938 252.707031 508.867188 252.976562 C 509.523438 253.25 510.199219 253.453125 510.894531 253.59375 C 511.589844 253.730469 512.289062 253.800781 513 253.800781 L 653.398438 253.800781 C 654.109375 253.800781 654.8125 253.730469 655.507812 253.59375 C 656.203125 253.453125 656.878906 253.25 657.53125 252.976562 C 658.1875 252.707031 658.808594 252.375 659.398438 251.980469 C 659.988281 251.585938 660.535156 251.136719 661.035156 250.636719 C 661.539062 250.136719 661.984375 249.589844 662.378906 249 C 662.773438 248.410156 663.105469 247.789062 663.378906 247.132812 C 663.648438 246.476562 663.855469 245.800781 663.992188 245.105469 C 664.128906 244.410156 664.199219 243.710938 664.199219 243 C 664.199219 242.289062 664.128906 241.589844 663.992188 240.894531 C 663.855469 240.199219 663.648438 239.523438 663.378906 238.867188 C 663.105469 238.210938 662.773438 237.589844 662.378906 237 C 661.984375 236.410156 661.539062 235.863281 661.035156 235.363281 C 660.535156 234.863281 659.988281 234.414062 659.398438 234.019531 C 658.808594 233.625 658.1875 233.292969 657.53125 233.023438 C 656.878906 232.75 656.203125 232.546875 655.507812 232.40625 C 654.8125 232.269531 654.109375 232.199219 653.398438 232.199219 Z M 653.398438 232.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 459 253.800781 L 469.800781 253.800781 C 470.507812 253.800781 471.210938 253.730469 471.90625 253.59375 C 472.601562 253.453125 473.277344 253.25 473.933594 252.976562 C 474.589844 252.707031 475.210938 252.375 475.800781 251.980469 C 476.390625 251.585938 476.933594 251.136719 477.4375 250.636719 C 477.9375 250.136719 478.386719 249.589844 478.78125 249 C 479.171875 248.410156 479.507812 247.789062 479.777344 247.132812 C 480.050781 246.476562 480.253906 245.800781 480.390625 245.105469 C 480.53125 244.410156 480.601562 243.710938 480.601562 243 C 480.601562 242.289062 480.53125 241.589844 480.390625 240.894531 C 480.253906 240.199219 480.050781 239.523438 479.777344 238.867188 C 479.507812 238.210938 479.171875 237.589844 478.78125 237 C 478.386719 236.410156 477.9375 235.863281 477.4375 235.363281 C 476.933594 234.863281 476.390625 234.414062 475.800781 234.019531 C 475.210938 233.625 474.589844 233.292969 473.933594 233.023438 C 473.277344 232.75 472.601562 232.546875 471.90625 232.40625 C 471.210938 232.269531 470.507812 232.199219 469.800781 232.199219 L 459 232.199219 C 458.289062 232.199219 457.589844 232.269531 456.894531 232.40625 C 456.199219 232.546875 455.523438 232.75 454.867188 233.023438 C 454.210938 233.292969 453.589844 233.625 453 234.019531 C 452.410156 234.414062 451.863281 234.863281 451.363281 235.363281 C 450.863281 235.863281 450.414062 236.410156 450.019531 237 C 449.625 237.589844 449.292969 238.210938 449.023438 238.867188 C 448.75 239.523438 448.546875 240.199219 448.40625 240.894531 C 448.269531 241.589844 448.199219 242.289062 448.199219 243 C 448.199219 243.710938 448.269531 244.410156 448.40625 245.105469 C 448.546875 245.800781 448.75 246.476562 449.023438 247.132812 C 449.292969 247.789062 449.625 248.410156 450.019531 249 C 450.414062 249.589844 450.863281 250.136719 451.363281 250.636719 C 451.863281 251.136719 452.410156 251.585938 453 251.980469 C 453.589844 252.375 454.210938 252.707031 454.867188 252.976562 C 455.523438 253.25 456.199219 253.453125 456.894531 253.59375 C 457.589844 253.730469 458.289062 253.800781 459 253.800781 Z M 459 253.800781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 577.800781 286.199219 L 459 286.199219 C 458.289062 286.199219 457.589844 286.269531 456.894531 286.40625 C 456.199219 286.546875 455.523438 286.75 454.867188 287.023438 C 454.210938 287.292969 453.589844 287.625 453 288.019531 C 452.410156 288.414062 451.863281 288.863281 451.363281 289.363281 C 450.863281 289.863281 450.414062 290.410156 450.019531 291 C 449.625 291.589844 449.292969 292.210938 449.023438 292.867188 C 448.75 293.523438 448.546875 294.199219 448.40625 294.894531 C 448.269531 295.589844 448.199219 296.289062 448.199219 297 C 448.199219 297.710938 448.269531 298.410156 448.40625 299.105469 C 448.546875 299.800781 448.75 300.476562 449.023438 301.132812 C 449.292969 301.789062 449.625 302.410156 450.019531 303 C 450.414062 303.589844 450.863281 304.136719 451.363281 304.636719 C 451.863281 305.136719 452.410156 305.585938 453 305.980469 C 453.589844 306.375 454.210938 306.707031 454.867188 306.976562 C 455.523438 307.25 456.199219 307.453125 456.894531 307.59375 C 457.589844 307.730469 458.289062 307.800781 459 307.800781 L 577.800781 307.800781 C 578.507812 307.800781 579.210938 307.730469 579.90625 307.59375 C 580.601562 307.453125 581.277344 307.25 581.933594 306.976562 C 582.589844 306.707031 583.210938 306.375 583.800781 305.980469 C 584.390625 305.585938 584.933594 305.136719 585.4375 304.636719 C 585.9375 304.136719 586.386719 303.589844 586.78125 303 C 587.171875 302.410156 587.507812 301.789062 587.777344 301.132812 C 588.050781 300.476562 588.253906 299.800781 588.390625 299.105469 C 588.53125 298.410156 588.601562 297.710938 588.601562 297 C 588.601562 296.289062 588.53125 295.589844 588.390625 294.894531 C 588.253906 294.199219 588.050781 293.523438 587.777344 292.867188 C 587.507812 292.210938 587.171875 291.589844 586.78125 291 C 586.386719 290.410156 585.9375 289.863281 585.4375 289.363281 C 584.933594 288.863281 584.390625 288.414062 583.800781 288.019531 C 583.210938 287.625 582.589844 287.292969 581.933594 287.023438 C 581.277344 286.75 580.601562 286.546875 579.90625 286.40625 C 579.210938 286.269531 578.507812 286.199219 577.800781 286.199219 Z M 577.800781 286.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 243 577.800781 C 243.710938 577.800781 244.410156 577.730469 245.105469 577.59375 C 245.800781 577.453125 246.476562 577.25 247.132812 576.976562 C 247.789062 576.707031 248.410156 576.375 249 575.980469 C 249.589844 575.585938 250.136719 575.136719 250.636719 574.636719 C 251.136719 574.136719 251.585938 573.589844 251.980469 573 C 252.375 572.410156 252.707031 571.789062 252.976562 571.132812 C 253.25 570.476562 253.453125 569.800781 253.59375 569.105469 C 253.730469 568.410156 253.800781 567.710938 253.800781 567 L 253.800781 556.199219 C 253.800781 555.492188 253.730469 554.789062 253.59375 554.09375 C 253.453125 553.398438 253.25 552.722656 252.976562 552.066406 C 252.707031 551.410156 252.375 550.789062 251.980469 550.199219 C 251.585938 549.609375 251.136719 549.066406 250.636719 548.5625 C 250.136719 548.0625 249.589844 547.613281 249 547.21875 C 248.410156 546.824219 247.789062 546.492188 247.132812 546.222656 C 246.476562 545.949219 245.800781 545.746094 245.105469 545.609375 C 244.410156 545.46875 243.710938 545.398438 243 545.398438 C 242.289062 545.398438 241.589844 545.46875 240.894531 545.609375 C 240.199219 545.746094 239.523438 545.949219 238.867188 546.222656 C 238.210938 546.492188 237.589844 546.824219 237 547.21875 C 236.410156 547.613281 235.863281 548.0625 235.363281 548.5625 C 234.863281 549.066406 234.414062 549.609375 234.019531 550.199219 C 233.625 550.789062 233.292969 551.410156 233.023438 552.066406 C 232.75 552.722656 232.546875 553.398438 232.40625 554.09375 C 232.269531 554.789062 232.199219 555.492188 232.199219 556.199219 L 232.199219 567 C 232.199219 567.710938 232.269531 568.410156 232.40625 569.105469 C 232.546875 569.800781 232.75 570.476562 233.023438 571.132812 C 233.292969 571.789062 233.625 572.410156 234.019531 573 C 234.414062 573.589844 234.863281 574.136719 235.363281 574.636719 C 235.863281 575.136719 236.410156 575.585938 237 575.980469 C 237.589844 576.375 238.210938 576.707031 238.867188 576.976562 C 239.523438 577.25 240.199219 577.453125 240.894531 577.59375 C 241.589844 577.730469 242.289062 577.800781 243 577.800781 Z M 243 577.800781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 264.601562 664.199219 L 253.800781 664.199219 L 253.800781 610.199219 C 253.800781 609.492188 253.730469 608.789062 253.59375 608.09375 C 253.453125 607.398438 253.25 606.722656 252.976562 606.066406 C 252.707031 605.410156 252.375 604.789062 251.980469 604.199219 C 251.585938 603.609375 251.136719 603.066406 250.636719 602.5625 C 250.136719 602.0625 249.589844 601.613281 249 601.21875 C 248.410156 600.824219 247.789062 600.492188 247.132812 600.222656 C 246.476562 599.949219 245.800781 599.746094 245.105469 599.609375 C 244.410156 599.46875 243.710938 599.398438 243 599.398438 C 242.289062 599.398438 241.589844 599.46875 240.894531 599.609375 C 240.199219 599.746094 239.523438 599.949219 238.867188 600.222656 C 238.210938 600.492188 237.589844 600.824219 237 601.21875 C 236.410156 601.613281 235.863281 602.0625 235.363281 602.5625 C 234.863281 603.066406 234.414062 603.609375 234.019531 604.199219 C 233.625 604.789062 233.292969 605.410156 233.023438 606.066406 C 232.75 606.722656 232.546875 607.398438 232.40625 608.09375 C 232.269531 608.789062 232.199219 609.492188 232.199219 610.199219 L 232.199219 664.199219 C 232.199219 664.90625 232.234375 665.613281 232.304688 666.316406 C 232.375 667.019531 232.476562 667.71875 232.613281 668.414062 C 232.753906 669.109375 232.925781 669.792969 233.128906 670.46875 C 233.335938 671.148438 233.574219 671.8125 233.84375 672.464844 C 234.113281 673.121094 234.417969 673.757812 234.75 674.382812 C 235.082031 675.007812 235.445312 675.613281 235.839844 676.199219 C 236.234375 676.789062 236.652344 677.355469 237.101562 677.902344 C 237.550781 678.449219 238.027344 678.972656 238.527344 679.472656 C 239.027344 679.972656 239.550781 680.449219 240.097656 680.898438 C 240.644531 681.347656 241.210938 681.765625 241.800781 682.160156 C 242.386719 682.550781 242.992188 682.914062 243.617188 683.25 C 244.242188 683.582031 244.878906 683.886719 245.535156 684.15625 C 246.1875 684.425781 246.851562 684.664062 247.53125 684.871094 C 248.207031 685.074219 248.890625 685.246094 249.585938 685.386719 C 250.28125 685.523438 250.980469 685.625 251.683594 685.695312 C 252.386719 685.765625 253.09375 685.800781 253.800781 685.800781 L 264.601562 685.800781 C 265.308594 685.800781 266.011719 685.730469 266.707031 685.59375 C 267.402344 685.453125 268.078125 685.25 268.734375 684.976562 C 269.386719 684.707031 270.011719 684.375 270.601562 683.980469 C 271.191406 683.585938 271.734375 683.136719 272.238281 682.636719 C 272.738281 682.136719 273.1875 681.589844 273.578125 681 C 273.972656 680.410156 274.304688 679.789062 274.578125 679.132812 C 274.847656 678.476562 275.054688 677.800781 275.191406 677.105469 C 275.332031 676.410156 275.398438 675.710938 275.398438 675 C 275.398438 674.289062 275.332031 673.589844 275.191406 672.894531 C 275.054688 672.199219 274.847656 671.523438 274.578125 670.867188 C 274.304688 670.210938 273.972656 669.589844 273.578125 669 C 273.1875 668.410156 272.738281 667.863281 272.238281 667.363281 C 271.734375 666.863281 271.191406 666.414062 270.601562 666.019531 C 270.011719 665.625 269.386719 665.292969 268.734375 665.023438 C 268.078125 664.75 267.402344 664.546875 266.707031 664.40625 C 266.011719 664.269531 265.308594 664.199219 264.601562 664.199219 Z M 264.601562 664.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 318.601562 664.199219 L 307.800781 664.199219 C 307.089844 664.199219 306.386719 664.269531 305.691406 664.40625 C 304.996094 664.546875 304.320312 664.75 303.667969 665.023438 C 303.011719 665.292969 302.390625 665.625 301.800781 666.019531 C 301.210938 666.414062 300.664062 666.863281 300.164062 667.363281 C 299.660156 667.863281 299.214844 668.410156 298.820312 669 C 298.425781 669.589844 298.09375 670.210938 297.820312 670.867188 C 297.550781 671.523438 297.347656 672.199219 297.207031 672.894531 C 297.070312 673.589844 297 674.289062 297 675 C 297 675.710938 297.070312 676.410156 297.207031 677.105469 C 297.347656 677.800781 297.550781 678.476562 297.820312 679.132812 C 298.09375 679.789062 298.425781 680.410156 298.820312 681 C 299.214844 681.589844 299.660156 682.136719 300.164062 682.636719 C 300.664062 683.136719 301.210938 683.585938 301.800781 683.980469 C 302.390625 684.375 303.011719 684.707031 303.667969 684.976562 C 304.320312 685.25 304.996094 685.453125 305.691406 685.59375 C 306.386719 685.730469 307.089844 685.800781 307.800781 685.800781 L 318.601562 685.800781 C 319.308594 685.800781 320.011719 685.730469 320.707031 685.59375 C 321.402344 685.453125 322.078125 685.25 322.734375 684.976562 C 323.386719 684.707031 324.011719 684.375 324.601562 683.980469 C 325.191406 683.585938 325.734375 683.136719 326.238281 682.636719 C 326.738281 682.136719 327.1875 681.589844 327.578125 681 C 327.972656 680.410156 328.304688 679.789062 328.578125 679.132812 C 328.847656 678.476562 329.054688 677.800781 329.191406 677.105469 C 329.332031 676.410156 329.398438 675.710938 329.398438 675 C 329.398438 674.289062 329.332031 673.589844 329.191406 672.894531 C 329.054688 672.199219 328.847656 671.523438 328.578125 670.867188 C 328.304688 670.210938 327.972656 669.589844 327.578125 669 C 327.1875 668.410156 326.738281 667.863281 326.238281 667.363281 C 325.734375 666.863281 325.191406 666.414062 324.601562 666.019531 C 324.011719 665.625 323.386719 665.292969 322.734375 665.023438 C 322.078125 664.75 321.402344 664.546875 320.707031 664.40625 C 320.011719 664.269531 319.308594 664.199219 318.601562 664.199219 Z M 318.601562 664.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">Simp\u00f3sio Neuro Viva + Parkinson sem segredo<\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tPalestras e Workshops com foco em profissionais de sa\u00fade nos temas: Sa\u00fade mental, preven\u00e7\u00e3o de doen\u00e7as e intelig\u00eancial emocional com suporte para grupos de medicos, pacientes ou empreendedores que precisam de orienta\u00e7\u00e3o especializada.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/neuro-viva\/\">\n\t\t\t\t\t\tSaiba mais\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a93bafd elementor-cta--skin-cover animated-slow elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"a93bafd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-stacked elementor-shape-circle elementor-animated-item--grow\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><path fill=\"#960033\" d=\"M 390.734375 264.71875 C 377.214844 250.5 365.292969 259.929688 358.261719 275.460938 C 356.445312 285.574219 358.625 287.59375 360.398438 297.496094 C 362.675781 310.199219 368.039062 319.160156 375.785156 328.519531 C 383.800781 338.207031 391.113281 344.773438 402.347656 350.707031 C 405.359375 352.296875 408.5 352.199219 411.671875 350.707031 C 415.609375 348.851562 415.28125 349.265625 419.144531 346.953125 C 427.347656 342.046875 426.492188 341.300781 432.199219 336.609375 C 434.21875 334.953125 435.644531 332.667969 437.308594 331.4375 C 438.78125 330.355469 443.890625 323.722656 445.132812 321.847656 C 453.875 308.683594 459.839844 291.769531 452.773438 276.476562 C 448.957031 268.21875 440.597656 260.996094 431.679688 259.378906 C 429.453125 258.976562 422.148438 258.390625 420.1875 258.960938 C 418.226562 259.546875 416.484375 260.628906 414.488281 260.964844 C 414.390625 260.964844 414.296875 260.964844 414.214844 261.046875 C 413.042969 262.148438 410.96875 262.050781 409.535156 263.800781 L 406 266.46875 C 401.730469 263.46875 401.828125 265.175781 396.390625 264.550781 C 394.566406 264.410156 394.300781 265.660156 393.179688 265.46875 C 392.945312 265.382812 392.585938 265.382812 392.472656 265.550781 C 391.996094 266.300781 391.359375 266.386719 390.726562 266.71875 C 392.335938 267.84375 391.820312 268.089844 392.40625 268.722656 C 396.007812 272.609375 402.398438 272.859375 401.152344 281.730469 C 401.777344 283.566406 404.921875 282.886719 406.78125 282.222656 C 409.382812 281.324219 417.507812 273.738281 420.429688 273.355469 C 432.046875 271.832031 437.554688 277.703125 436.285156 287.269531 C 434.9375 297.398438 426.328125 311.433594 421.753906 316.347656 C 417.855469 320.574219 414.570312 324.273438 409.277344 327.605469 L 406.589844 329.691406 C 401.011719 326.464844 392.09375 319.117188 388.042969 314.011719 C 386.210938 311.699219 385.035156 310.875 383.121094 307.757812 L 379.601562 301.917969 C 379.144531 301.460938 379.992188 301.796875 378.808594 299.917969 C 377.789062 298.296875 370.980469 287.269531 370.84375 285.074219 C 369.625 265.71875 390.183594 269.425781 389.269531 267.972656 C 388.941406 267.554688 388.449219 267.804688 388.152344 267.390625 C 388.410156 266.417969 388.894531 265.972656 388.292969 265.972656 C 388.21875 265.890625 388.160156 265.890625 388.082031 265.804688 C 388.929688 265.472656 390.253906 265.289062 390.734375 264.71875 Z M 486.363281 612.046875 C 484.53125 609.738281 483.355469 608.914062 481.445312 605.792969 L 477.925781 599.953125 C 477.46875 599.5 478.316406 599.832031 477.132812 597.953125 C 476.113281 596.335938 469.304688 585.304688 469.164062 583.109375 C 467.945312 563.753906 488.507812 567.460938 487.589844 566.007812 C 487.265625 565.59375 486.773438 565.84375 486.472656 565.425781 C 486.734375 564.457031 487.21875 564.007812 486.617188 564.007812 C 486.542969 563.925781 486.484375 563.925781 486.40625 563.84375 C 487.246094 563.511719 488.574219 563.332031 489.050781 562.757812 C 475.53125 548.542969 463.613281 557.96875 456.578125 573.5 C 454.761719 583.613281 456.941406 585.632812 458.714844 595.535156 C 460.992188 608.238281 466.355469 617.199219 474.101562 626.558594 C 482.121094 636.242188 489.429688 642.8125 500.667969 648.742188 C 503.679688 650.332031 506.816406 650.234375 509.992188 648.742188 C 513.925781 646.890625 513.597656 647.300781 517.464844 644.988281 C 525.664062 640.082031 524.808594 639.335938 530.515625 634.648438 C 532.535156 632.988281 533.960938 630.703125 535.628906 629.476562 C 537.101562 628.390625 542.207031 621.757812 543.449219 619.882812 C 552.191406 606.722656 558.15625 589.808594 551.089844 574.515625 C 547.273438 566.257812 538.914062 559.03125 529.996094 557.417969 C 527.769531 557.015625 520.464844 556.429688 518.503906 557 C 516.542969 557.585938 514.800781 558.667969 512.808594 559 C 512.707031 559 512.613281 559 512.53125 559.085938 C 511.355469 560.1875 509.285156 560.085938 507.851562 561.835938 L 504.316406 564.503906 C 500.046875 561.507812 500.144531 563.210938 494.707031 562.585938 C 492.882812 562.449219 492.617188 563.699219 491.496094 563.503906 C 491.261719 563.421875 490.902344 563.421875 490.785156 563.589844 C 490.3125 564.339844 489.675781 564.421875 489.042969 564.757812 C 490.652344 565.882812 490.136719 566.128906 490.722656 566.757812 C 494.320312 570.648438 500.710938 570.894531 499.46875 579.769531 C 500.09375 581.605469 503.238281 580.925781 505.097656 580.257812 C 507.699219 579.363281 515.824219 571.773438 518.746094 571.394531 C 530.363281 569.867188 535.871094 575.738281 534.597656 585.304688 C 533.253906 595.433594 524.640625 609.46875 520.070312 614.382812 C 516.171875 618.609375 512.882812 622.308594 507.59375 625.640625 L 504.90625 627.726562 C 499.335938 624.503906 490.417969 617.152344 486.363281 612.046875 Z M 327.105469 612.046875 C 328.941406 609.738281 330.117188 608.914062 332.027344 605.792969 L 335.546875 599.953125 C 336.007812 599.5 335.15625 599.832031 336.339844 597.953125 C 337.359375 596.335938 344.171875 585.304688 344.308594 583.109375 C 345.527344 563.753906 324.964844 567.460938 325.882812 566.007812 C 326.207031 565.59375 326.699219 565.84375 327 565.425781 C 326.738281 564.457031 326.253906 564.007812 326.859375 564.007812 C 326.933594 563.925781 326.992188 563.925781 327.066406 563.84375 C 326.226562 563.511719 324.902344 563.332031 324.421875 562.757812 C 337.941406 548.542969 349.863281 557.96875 356.894531 573.5 C 358.710938 583.613281 356.53125 585.632812 354.757812 595.535156 C 352.480469 608.238281 347.117188 617.199219 339.371094 626.558594 C 331.355469 636.242188 324.042969 642.8125 312.808594 648.742188 C 309.796875 650.332031 306.65625 650.234375 303.484375 648.742188 C 299.546875 646.890625 299.875 647.300781 296.011719 644.988281 C 287.808594 640.082031 288.664062 639.335938 282.957031 634.648438 C 280.9375 632.988281 279.511719 630.703125 277.847656 629.476562 C 276.375 628.390625 271.269531 621.757812 270.023438 619.882812 C 261.28125 606.722656 255.316406 589.808594 262.382812 574.515625 C 266.199219 566.257812 274.558594 559.03125 283.476562 557.417969 C 285.703125 557.015625 293.007812 556.429688 294.96875 557 C 296.929688 557.585938 298.671875 558.667969 300.667969 559 C 300.765625 559 300.859375 559 300.941406 559.085938 C 302.113281 560.1875 304.1875 560.085938 305.621094 561.835938 L 309.15625 564.503906 C 313.425781 561.507812 313.328125 563.210938 318.765625 562.585938 C 320.589844 562.449219 320.855469 563.699219 321.976562 563.503906 C 322.210938 563.421875 322.570312 563.421875 322.683594 563.589844 C 323.160156 564.339844 323.796875 564.421875 324.429688 564.757812 C 322.820312 565.882812 323.335938 566.128906 322.75 566.757812 C 319.148438 570.648438 312.757812 570.894531 314.003906 579.769531 C 313.378906 581.605469 310.234375 580.925781 308.375 580.257812 C 305.773438 579.363281 297.648438 571.773438 294.726562 571.394531 C 283.109375 569.867188 277.601562 575.738281 278.871094 585.304688 C 280.21875 595.433594 288.828125 609.46875 293.402344 614.382812 C 297.300781 618.609375 300.585938 622.308594 305.878906 625.640625 L 308.566406 627.726562 C 314.136719 624.503906 323.054688 617.152344 327.105469 612.046875 Z M 686.933594 480.3125 C 688.363281 485.769531 687.640625 488.929688 686.109375 494.738281 C 680.738281 515.109375 675.910156 533.414062 669.847656 553.621094 C 668.945312 556.625 668.242188 559.628906 667.359375 562.628906 L 657.210938 596.15625 C 655.992188 600.410156 654.773438 604.664062 653.257812 608.832031 L 650.140625 619.09375 C 648.015625 625.546875 641.734375 630.902344 635.183594 632.519531 C 627.914062 634.316406 619.886719 632.460938 614.535156 627.265625 L 591.390625 602.664062 C 586.824219 597.03125 575.726562 599.949219 575.769531 608.75 L 576.734375 711.421875 C 576.703125 711.421875 576.695312 711.421875 576.679688 711.421875 L 531 712.003906 C 528.554688 712.085938 526.070312 712.003906 523.625 712.085938 C 513.28125 712.390625 415.578125 711.066406 414.445312 711.210938 L 415.113281 708.082031 C 414.996094 701.410156 415.277344 694.738281 414.851562 688.148438 C 414.800781 687.398438 414.785156 686.398438 414.867188 685.648438 C 415.144531 682.230469 415.011719 678.890625 414.875 675.472656 L 414.667969 651.453125 C 414.464844 626.117188 414.457031 598.609375 413.152344 573.390625 C 413.050781 571.636719 412.875 569.71875 412.707031 567.800781 C 412.835938 567.632812 412.941406 567.550781 413.085938 567.382812 C 414.710938 565.65625 414.558594 564.667969 416.035156 563.628906 C 417.160156 562.84375 419.21875 557.28125 419.738281 555.625 L 420.425781 552.703125 L 423.425781 545.53125 C 424.773438 542.847656 424.871094 541.386719 425.878906 539.195312 L 428.925781 532.355469 C 430.761719 528.160156 429.574219 529.664062 432.378906 525.683594 C 432.59375 525.351562 432.660156 524.933594 432.859375 524.597656 L 435.34375 521.011719 C 436.164062 519.378906 436.042969 520.414062 436.640625 519.261719 C 440.175781 512.394531 455.066406 501.117188 455.414062 500.660156 C 455.609375 500.207031 455.835938 500.945312 456.464844 499.996094 C 457.148438 498.960938 461.800781 497.472656 465.722656 492.574219 L 471.375 495.574219 C 474.410156 497.058594 481.832031 499.191406 485.0625 499.578125 C 491.296875 500.328125 490.539062 500.433594 497.371094 500.164062 C 501.640625 499.996094 501.425781 500.089844 505.78125 499.246094 L 514.0625 497.578125 C 522.222656 494.910156 527.109375 492.230469 533.960938 487.152344 L 544.417969 492.324219 C 554.082031 497.285156 567.226562 506.085938 575.035156 513.257812 C 578.621094 516.550781 580.472656 519.191406 583.367188 522.265625 C 590.773438 530.355469 597.144531 539.28125 602.625 548.703125 C 607.246094 557.132812 610.660156 565.90625 614.4375 574.726562 C 618.460938 584.128906 631.515625 582.710938 634.386719 574.640625 L 643.210938 553.375 L 661.988281 509.417969 C 663.699219 505.332031 662.949219 500.496094 659.6875 497.074219 C 657.023438 493.820312 655.558594 492.292969 654.117188 487.652344 C 651.863281 480.40625 653.039062 471.089844 658.960938 466.382812 C 669.347656 458.136719 683.902344 467.515625 686.933594 480.3125 Z M 391.632812 709.417969 C 393.503906 709.417969 395.386719 709.417969 397.269531 709.417969 C 397.703125 679.285156 397.445312 648.851562 397.839844 618.675781 C 397.914062 612.796875 397.277344 607.566406 398.320312 601.746094 C 398.792969 599.117188 398.96875 569.660156 398.746094 566.050781 L 397.570312 556.125 C 396.472656 549.453125 393.195312 538.109375 389.707031 532.023438 C 385.902344 525.386719 383.664062 522.761719 378.996094 517.34375 C 374.292969 511.878906 378.175781 514.546875 371.035156 508.003906 C 363.574219 501.167969 354.601562 496.539062 345.753906 491.574219 L 341.277344 493.742188 C 332.15625 497.550781 336.476562 495.925781 327.898438 497.996094 C 322.914062 499.199219 317.429688 498.96875 312.371094 498.746094 C 301.914062 498.28125 290.136719 493.707031 281.679688 488.070312 C 279.058594 488.796875 277.410156 490.410156 272.5625 492.074219 C 267.730469 493.730469 260.910156 497.28125 257.191406 500.164062 C 253.773438 502.816406 253.371094 502.480469 250.511719 504.335938 C 244.863281 508 240.652344 510.71875 235.550781 515.175781 C 225.167969 524.253906 214.308594 538.464844 207.859375 550.457031 C 204.066406 557.511719 204.6875 556.828125 202.039062 563.714844 L 197.761719 573.890625 C 194.890625 581.292969 184.917969 581.125 181.839844 574.558594 L 179.730469 570.304688 C 177.34375 563.964844 174.292969 558.292969 171.457031 552.457031 C 169.144531 547.667969 167.140625 541.761719 164.953125 537.027344 L 152.691406 509.171875 C 150.886719 504.925781 151.992188 500.578125 154.976562 497.410156 C 164.75 487.039062 164.773438 468.261719 150.523438 463.214844 C 138.824219 459.074219 122.035156 474.402344 127.105469 491.988281 C 132.835938 511.863281 138.21875 531.46875 144.25 551.371094 C 146.609375 559.128906 149.121094 566.882812 151.550781 574.640625 L 164.984375 617.007812 C 170.242188 632.695312 189.273438 634.242188 197.078125 626.433594 L 220.824219 600.910156 C 227.316406 593.683594 240.367188 597.320312 240.730469 608.75 C 241.195312 623.378906 240.890625 640.039062 240.941406 654.789062 L 240.546875 708.25 L 321.605469 709.082031 L 347.652344 709.25 C 362.308594 709.167969 376.96875 709.417969 391.632812 709.417969 Z M 350.273438 489.320312 C 349.808594 489.402344 349.367188 489.484375 348.914062 489.484375 C 349.191406 489.320312 349.492188 489.152344 349.800781 488.902344 C 349.980469 489.070312 350.140625 489.234375 350.273438 489.320312 Z M 348.007812 490.152344 C 348.34375 489.847656 348.550781 490.070312 349.273438 490.570312 C 348.847656 490.402344 348.429688 490.238281 348.007812 490.152344 Z M 453.476562 438.527344 C 454.316406 449.277344 458.363281 459.683594 466.351562 467.550781 C 471.113281 472.242188 477.558594 476.054688 484.199219 477.308594 C 488.15625 478.054688 485.929688 478.148438 491.632812 478.5625 L 499.757812 478.5625 L 506.277344 477.058594 C 516.140625 474.316406 525.335938 466.203125 530.15625 457.210938 C 535.027344 448.121094 536.515625 436.140625 533.683594 426.183594 C 532.59375 422.347656 533.402344 424.035156 531.589844 420.347656 C 528.015625 413.070312 524.128906 408.3125 518.238281 402.75 C 516.339844 400.957031 517.292969 400.746094 513.234375 397.996094 C 508.289062 394.640625 507.972656 394.222656 502.625 391.238281 C 498.902344 389.164062 500.535156 389.035156 498.171875 387.234375 L 496.953125 385.816406 L 496.40625 387.402344 C 495.863281 386.390625 495.828125 384.632812 495.660156 383.316406 L 492.574219 384.316406 C 493.757812 384.316406 492.769531 385.332031 492.542969 385.816406 C 492.9375 386.351562 496.445312 386.308594 491.074219 387.902344 C 482.980469 390.304688 474.8125 395.742188 469.316406 401.914062 C 464.132812 407.730469 458.078125 415.328125 455.785156 422.679688 L 454.628906 426.351562 L 453.535156 433.773438 Z M 493.5 382.066406 L 495.617188 382.898438 C 495.542969 382.316406 495.476562 381.648438 495.410156 381.0625 C 494.789062 383.128906 494.960938 381.96875 494.585938 381.480469 C 494.34375 381.316406 494.117188 381.0625 493.890625 380.816406 C 493.632812 381.0625 493.550781 381.5625 493.5 382.066406 Z M 708.710938 497.160156 L 697.820312 535.441406 C 696.5 539.945312 695.359375 544.617188 693.824219 548.953125 C 691.230469 556.375 689.585938 563.964844 687.175781 571.46875 L 679.167969 598.492188 L 670.585938 625.347656 C 661.191406 653.128906 623.183594 664.949219 598.976562 640.027344 L 594.957031 635.605469 L 594.390625 719.507812 C 594.339844 724.761719 590.046875 728.933594 584.792969 728.933594 L 562.941406 728.683594 L 533.25 728.515625 C 528.84375 728.386719 524.265625 729.019531 520.304688 728.015625 C 518.441406 727.542969 504.425781 727.523438 500.957031 727.433594 C 434.953125 725.691406 382.632812 727.742188 317.039062 728.265625 L 229.226562 728.433594 C 224.195312 728.433594 220.109375 724.347656 220.101562 719.34375 L 219.378906 634.273438 C 215.496094 638.355469 213.1875 641.65625 208.351562 645.113281 C 187.066406 660.332031 155.851562 652.148438 145.164062 627.015625 C 142.992188 621.898438 138.894531 608.976562 137.132812 603.664062 C 125.691406 569.121094 115.128906 532.796875 105.109375 497.660156 C 95.464844 463.847656 128.257812 430.175781 160.128906 442.863281 C 185.3125 452.890625 190.78125 486.058594 175.324219 507 L 190.664062 545.03125 C 200.585938 527.703125 208.402344 520.363281 222.699219 507.75 C 235.527344 496.429688 258.890625 485.628906 276.035156 483.648438 C 264.976562 474.03125 257.230469 459.105469 255.992188 444.449219 C 255.652344 440.4375 255.851562 436.445312 256.125 432.4375 L 259.019531 419.429688 L 264.074219 408.335938 C 268.003906 401.851562 273.160156 395.789062 279.414062 391.40625 C 281.117188 390.207031 286.152344 387.304688 288.292969 386.902344 C 292.53125 386.101562 296.140625 384.085938 301.4375 383.980469 C 304.957031 383.910156 310.328125 383.808594 313.472656 385.480469 C 313.644531 385.574219 316.851562 388.765625 318.125 389.402344 C 315.34375 390.640625 316.9375 390.761719 315.449219 390.988281 C 313.460938 391.289062 314.496094 392.066406 312.421875 392.570312 C 308.386719 393.554688 308.558594 395.039062 307.234375 395.40625 C 305.253906 395.957031 301.691406 397.128906 300.226562 398.324219 C 298.691406 399.582031 291.195312 404.039062 290.503906 405.914062 C 289.890625 407.570312 288.207031 408.078125 287.941406 409.335938 L 286.433594 411.421875 C 286.050781 412.085938 285.882812 412.921875 285.574219 413.589844 C 284.917969 415.128906 283.578125 415.375 281.296875 422.511719 C 278.152344 432.347656 279.199219 429.835938 278.21875 437.609375 C 278.09375 438.609375 278.382812 439.609375 278.425781 440.613281 C 278.839844 448.132812 281.679688 455.59375 286.15625 461.628906 C 290.546875 467.542969 299.371094 473.886719 306.625 475.722656 C 309.035156 476.332031 308.980469 476.953125 311.8125 477.058594 C 314.269531 477.148438 316.238281 477.703125 319.21875 477.394531 C 331.804688 476.089844 343.871094 470.933594 351.480469 460.378906 C 356.207031 453.816406 358.140625 448.542969 358.867188 440.445312 C 359.742188 430.722656 356.898438 420.8125 351.210938 412.921875 C 350.140625 411.4375 349.167969 411.207031 349.050781 409.585938 C 348.953125 408.261719 342.605469 402.820312 341.070312 401.664062 C 336.578125 398.28125 336.191406 397.703125 330.925781 396.574219 C 329.386719 396.242188 330.40625 395.605469 329.160156 395.238281 L 326.28125 394.320312 C 323.425781 394.417969 320.824219 393.386719 318.476562 391.820312 C 318.375 391.738281 318.292969 391.652344 318.125 391.402344 L 321.0625 390.570312 C 320.011719 390.570312 321.066406 389.449219 321.269531 389.070312 C 321.054688 388.664062 319.039062 388.292969 320.402344 387.820312 C 323.84375 386.625 329.789062 386.871094 333.507812 387.152344 C 344.386719 387.96875 356.894531 393.441406 363.746094 402.164062 C 367.820312 407.351562 370.316406 410.992188 372.730469 417.09375 C 373.515625 419.078125 374.496094 420.382812 374.496094 422.097656 L 375.75 426.019531 C 376.449219 429.09375 377.324219 435.617188 377.222656 438.695312 L 376.523438 449.289062 C 376.253906 451.75 373.964844 459.726562 372.878906 462.046875 C 368.515625 471.390625 364.667969 476.632812 356.859375 483.734375 L 351.253906 488.070312 L 356.234375 489.902344 L 364.625 494.074219 C 379.421875 501.84375 396.476562 519.167969 403.355469 534.691406 C 404.847656 530.640625 405.429688 529.914062 407.035156 526.351562 C 407.441406 525.433594 407.699219 524.433594 408.117188 523.597656 C 410.246094 519.386719 415.390625 511.84375 418.09375 507.917969 C 421.734375 502.804688 429.300781 496.980469 434.757812 493.074219 L 441.554688 488.488281 L 452.921875 482.398438 C 445.800781 475.664062 439.632812 464.144531 437.394531 454.625 C 437.234375 453.957031 437.070312 453.289062 436.875 452.621094 C 435.6875 448.699219 435.214844 442.183594 435.25 437.859375 C 435.34375 426.042969 439.722656 413.523438 446.46875 403.917969 L 449.289062 400.332031 C 450.988281 397.621094 451.960938 398.363281 453.03125 397.246094 C 454.058594 396.160156 455.214844 395.160156 456.46875 394.324219 C 457.242188 393.824219 457.851562 392.988281 458.601562 392.492188 C 462.574219 389.78125 466.433594 387.199219 471.246094 385.816406 C 474.234375 384.960938 478.832031 381.597656 480.371094 382.5625 C 481.753906 383.433594 488.324219 380.375 492.53125 381.730469 C 491.417969 375.761719 490.65625 363.960938 489.820312 357.128906 C 488.203125 343.894531 486.90625 328.207031 485.828125 314.761719 C 485.667969 312.757812 485.523438 310.671875 485.417969 308.589844 C 485.152344 303.507812 491.371094 298.28125 497.261719 303.917969 L 519.160156 326.269531 C 522.074219 329.339844 526.632812 332.636719 530.546875 333.359375 C 535.222656 334.222656 535.363281 334.570312 540.195312 333.859375 C 549.898438 332.429688 556.601562 326.320312 559.394531 316.925781 C 567.292969 290.375 575.554688 264.316406 583.28125 237.527344 L 591.980469 204.75 C 595.28125 191.984375 600.425781 181.925781 590.234375 169.722656 C 587.324219 166.054688 583.257812 163.46875 579.175781 162.550781 C 567.015625 159.800781 557.824219 171.023438 560.679688 184.652344 C 561.703125 189.542969 563.710938 193.21875 567.042969 196.746094 L 567.09375 196.746094 C 570.363281 200.246094 571.128906 205.085938 569.46875 209.253906 L 547.492188 262.300781 L 542.1875 274.558594 C 538.359375 283.933594 525.363281 283.449219 521.546875 274.644531 C 516.582031 263.1875 514.5 256.597656 507.757812 245.871094 C 498.695312 231.4375 493.335938 225.15625 479.34375 212.425781 C 476.617188 209.945312 476.109375 209.078125 472.496094 206.085938 C 469.144531 203.308594 456.140625 195.085938 452.582031 193.078125 L 443.398438 188.238281 C 438.898438 191.613281 433.488281 194.378906 428.175781 196.246094 C 425.792969 197.082031 424.828125 197.726562 422.070312 198.078125 C 419.175781 198.449219 414.601562 199.832031 411.652344 199.832031 C 405.445312 199.914062 402.5 200.371094 396.164062 199.414062 C 390.335938 198.535156 382.230469 195.714844 377.117188 192.574219 C 373.421875 190.304688 371.902344 189.003906 368.625 186.484375 C 365.34375 187.507812 357.671875 191.601562 354.445312 193.40625 L 341.003906 202.332031 C 325.34375 214.179688 308.46875 233.621094 299.757812 250.621094 C 298.1875 253.691406 295.277344 259.296875 294.136719 262.464844 C 293.480469 264.296875 292.820312 266.132812 291.769531 267.800781 L 289.585938 273.390625 C 286.726562 280.160156 277.375 279.6875 274.722656 273.222656 L 246.933594 208.25 C 245.425781 204.640625 246.40625 201.214844 248.828125 198.492188 C 259.113281 187.511719 258.585938 169.875 247.640625 163.128906 C 244.980469 161.488281 239.960938 160.625 237.117188 161.128906 C 223.707031 163.503906 215.195312 178.449219 218.652344 190.652344 L 224.53125 211.167969 L 241.4375 265.214844 L 254.699219 306.832031 L 258.691406 318.925781 C 262.023438 326.261719 268.878906 330.78125 276.925781 330.933594 C 278.773438 330.96875 283.925781 330.144531 285.4375 329.351562 C 290.363281 326.769531 291.59375 324.90625 295.253906 321.09375 L 314.761719 301.242188 C 321.105469 294.726562 332.199219 299.4375 331.910156 308.582031 C 331.746094 313.738281 331.113281 328.019531 330.242188 332.851562 C 328.917969 340.207031 328.902344 348.441406 327.617188 356.539062 C 326.234375 365.246094 326.179688 369.296875 323.828125 378.308594 C 323.46875 379.683594 322.964844 378.605469 321.613281 382.8125 C 321.25 383.933594 320.550781 383.832031 319.652344 387.398438 C 319.335938 385.8125 319.191406 384.226562 318.449219 383.226562 C 318.03125 382.65625 318.589844 380.3125 317.625 378.390625 C 316.476562 376.097656 317.183594 370.175781 315.421875 364.125 C 314.808594 362.011719 314.902344 354.71875 314.964844 352.453125 C 315.136719 346.339844 313.988281 338.90625 313.988281 331.683594 L 311.179688 334.769531 C 303.8125 343.792969 296.378906 350.480469 283.757812 352.535156 C 266.066406 355.414062 248.871094 347.140625 239.863281 331.765625 C 236.832031 326.597656 234.1875 317.328125 232.363281 311.667969 L 218.980469 268.882812 C 217.585938 264.378906 216.058594 259.875 214.683594 255.371094 L 203.28125 216.257812 C 202.324219 212.835938 201.171875 209.417969 200.445312 205.996094 C 198.769531 198.078125 196.285156 194.222656 196.34375 185.898438 C 196.46875 167.613281 205.71875 151.019531 222.929688 143.28125 C 250.972656 130.671875 280.964844 154.253906 275.542969 187.066406 C 274.355469 194.15625 271.546875 201.078125 267.191406 206.832031 L 282.90625 245.949219 C 286.101562 240.289062 289.113281 234.871094 292.90625 229.519531 L 298.007812 222.847656 C 301.824219 217.558594 301.769531 219.097656 304.28125 216.59375 C 306.257812 214.589844 308.085938 212.421875 310.328125 210.667969 C 311.65625 209.585938 312.855469 208.25 314.15625 207.082031 C 319.820312 202.238281 329.117188 195.453125 336.316406 192.15625 C 339.972656 190.480469 350.082031 183.570312 352.738281 183.980469 C 353.664062 184.125 360.828125 181.542969 362.761719 180.894531 C 358.769531 176.148438 356.160156 173.191406 353.320312 167.300781 C 344.722656 149.453125 343.636719 130.832031 352.4375 112.589844 C 353.890625 109.503906 355.648438 106.5 357.574219 103.664062 C 362.789062 96.535156 362.402344 98.601562 364.128906 97.074219 L 369.71875 92.238281 C 373.585938 89.472656 377.757812 86.976562 382.34375 85.648438 C 385.128906 84.84375 390.066406 81.425781 391.476562 82.3125 C 392.34375 82.859375 399.21875 81.089844 401.234375 81.0625 C 402.320312 81.046875 406.167969 82.160156 407.015625 82.898438 C 406.511719 83.476562 404.453125 83.949219 403.699219 84.066406 C 404.492188 84.859375 404.519531 83.511719 403.664062 85.648438 C 403.945312 86.054688 407.523438 86.15625 402.1875 87.734375 C 393.773438 90.21875 386.277344 95.265625 380.433594 101.746094 L 372.847656 111.003906 C 370.886719 113.925781 367.097656 120.210938 366.472656 123.847656 C 366.164062 125.640625 365.574219 126.234375 365.582031 126.765625 C 365.605469 129.078125 364.03125 132.0625 364.804688 140.945312 C 365.484375 148.726562 369.847656 158.757812 375.082031 164.714844 C 378.96875 169.140625 383.09375 172.5625 388.457031 174.804688 C 389.351562 175.222656 390.226562 175.722656 391.144531 176.054688 L 396.554688 177.390625 C 399.800781 178.453125 407.289062 178.773438 410.875 178.308594 L 417.398438 176.890625 C 427.066406 174.304688 436.488281 165.820312 441.269531 157.039062 C 446.132812 148.113281 447.574219 135.753906 444.796875 125.929688 C 443.234375 120.398438 443.984375 122.734375 441.160156 117.253906 C 438.335938 111.777344 433.832031 106.675781 429.339844 102.492188 C 427.207031 100.503906 428.554688 100.710938 424.339844 97.738281 C 422.980469 96.90625 421.601562 95.988281 420.269531 94.902344 C 418.960938 93.902344 411.3125 89.785156 411.011719 89.066406 C 410.316406 87.40625 409.78125 87.78125 408.984375 86.648438 C 408.097656 85.5625 408.082031 85.5625 407.015625 84.980469 C 407.832031 84.644531 408.640625 84.5625 409.191406 83.894531 C 409.527344 83.410156 410.644531 84.183594 411.828125 83.144531 C 412.957031 82.15625 416.335938 83.136719 419.785156 82.226562 C 421.308594 81.824219 424.660156 82.929688 426.105469 83.5625 C 429.011719 84.828125 433.773438 85.402344 437.222656 87.734375 L 445.503906 92.988281 C 447.375 93.714844 448.339844 95.292969 450.351562 96.574219 L 453.003906 99.160156 C 457.210938 102.347656 456.789062 103.269531 458.832031 105.914062 C 464.519531 113.28125 467 121.339844 468.332031 130.515625 C 468.742188 133.339844 468.699219 138.898438 468.582031 141.691406 C 467.941406 156.960938 461.027344 170.808594 450.800781 181.808594 L 458.898438 183.226562 C 462.441406 184.222656 475.226562 190.519531 479.015625 192.402344 C 486.15625 196.0625 493.273438 201.726562 499.523438 206.828125 C 500.285156 207.496094 501.09375 208.246094 501.910156 208.746094 C 505.597656 211.035156 508.3125 214.96875 510.21875 216.167969 L 514.789062 221.089844 C 519.445312 225.898438 519.269531 225.355469 523.3125 231.265625 L 531.117188 243.441406 C 531.683594 241.941406 532.226562 240.523438 532.820312 239.023438 L 546.070312 206.746094 C 533.632812 188.746094 534.277344 161.855469 552.535156 147.777344 C 561.976562 140.5 574.375 138.414062 585.804688 141.691406 C 602.710938 146.535156 614.824219 162.324219 617.355469 179.386719 C 618.851562 189.46875 617.140625 194.804688 614.695312 203.574219 L 605.078125 236.269531 L 584.910156 298.988281 L 580.15625 313.25 C 577.066406 323.230469 574.824219 331.570312 566.8125 339.691406 C 551.355469 355.363281 525.078125 355.929688 509.214844 340.355469 L 499.933594 330.515625 C 499.75 334.269531 499.664062 338.105469 499.28125 341.859375 C 498.773438 346.785156 500.289062 357.519531 499.1875 359.207031 C 498.597656 360.113281 498.445312 367.554688 498.53125 368.378906 C 499.109375 373.9375 498.460938 379.402344 497.210938 384.726562 C 498.464844 384.066406 497.722656 383.890625 498.964844 383.890625 C 501.144531 383.890625 500.484375 382.664062 502.816406 382.890625 C 506.40625 383.242188 508.691406 382.089844 510.105469 382.390625 L 514.992188 383.808594 C 519.351562 385.710938 520.601562 384.410156 528.769531 389.480469 L 534.402344 393.234375 C 536.828125 394.441406 539.605469 397.324219 541.890625 399.324219 C 544.058594 401.074219 545.269531 402.292969 546.804688 404.660156 C 550.214844 409.929688 553.15625 413.707031 554.933594 420.089844 C 557.351562 428.761719 557.828125 433.109375 557.476562 441.941406 C 557.011719 450.113281 554.894531 458.121094 551.28125 465.460938 C 548.535156 471.425781 544.515625 476.511719 540.222656 481.390625 L 553.523438 484.640625 C 559.453125 485.863281 573.121094 494.15625 578.835938 497.738281 C 587.9375 503.683594 587.894531 503.839844 595.460938 510.664062 L 603.53125 518.835938 L 609.480469 525.675781 C 613.652344 529.964844 614.785156 532.777344 618.378906 537.351562 L 623.007812 545.023438 C 623.015625 545.023438 623.015625 545.023438 623.03125 545.023438 C 626.558594 536.265625 630.339844 527.511719 633.832031 518.667969 C 635.410156 514.664062 637.0625 510.746094 638.726562 506.828125 C 622.859375 484.3125 630.210938 451.453125 655.140625 442.941406 C 664.417969 439.773438 672.59375 439.867188 681.988281 443.523438 C 702.195312 451.398438 714.597656 475.3125 708.710938 497.160156 Z M 708.710938 497.160156 \" fill-opacity=\"1\" fill-rule=\"evenodd\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">Doen\u00e7a de Parkinson<\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tRealizamos campanhas de arrecada\u00e7\u00e3o de fundos em projetos sociais e programas comunit\u00e1rios para pessoas que n\u00e3o tem acesso a tratamentos adequados. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/tratamento-de-parkinson\/\">\n\t\t\t\t\t\tSaiba mais\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de938f3 elementor-cta--skin-cover animated-slow elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"de938f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-stacked elementor-shape-circle elementor-animated-item--grow\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><defs><clipPath id=\"fa935d4cdc\"><path d=\"M 508 119.878906 L 634 119.878906 L 634 246 L 508 246 Z M 508 119.878906 \" clip-rule=\"nonzero\"><\/path><\/clipPath><\/defs><path fill=\"#960033\" d=\"M 721.050781 494.851562 L 673.34375 494.851562 C 668.953125 494.851562 665.394531 498.414062 665.394531 502.804688 L 665.394531 539.90625 L 508.9375 539.90625 C 509.84375 545.738281 510.316406 551.925781 510.320312 558.582031 C 510.246094 579.113281 506.078125 603.195312 497.449219 632.664062 L 665.394531 632.664062 L 665.394531 644.59375 C 665.394531 648.984375 668.953125 652.542969 673.34375 652.542969 L 721.050781 652.542969 C 725.441406 652.542969 729 648.984375 729 644.59375 L 729 502.804688 C 729 498.414062 725.441406 494.851562 721.050781 494.851562 Z M 721.050781 494.851562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 329.074219 539.90625 L 144.605469 539.90625 L 144.605469 364.984375 C 144.605469 360.59375 141.046875 357.035156 136.65625 357.035156 L 88.949219 357.035156 C 84.558594 357.035156 81 360.59375 81 364.984375 L 81 644.59375 C 81 648.984375 84.558594 652.542969 88.949219 652.542969 L 136.65625 652.542969 C 141.046875 652.542969 144.605469 648.984375 144.605469 644.59375 L 144.605469 632.664062 L 340.589844 632.664062 C 331.957031 603.191406 327.789062 579.113281 327.710938 558.597656 C 327.710938 551.953125 328.171875 545.742188 329.074219 539.90625 Z M 329.074219 539.90625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 447.773438 541.382812 C 447.390625 540.742188 447.097656 540.289062 446.785156 539.910156 L 391.261719 539.910156 C 390.84375 540.378906 390.421875 541.011719 389.867188 542.191406 C 388.925781 544.21875 387.335938 549.0625 387.34375 558.582031 C 387.285156 568.910156 389.410156 591.464844 403.003906 632.664062 L 435.03125 632.664062 C 448.628906 591.453125 450.753906 568.914062 450.691406 558.609375 C 450.699219 547.839844 448.652344 542.972656 447.773438 541.382812 Z M 447.773438 541.382812 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 253.980469 529.632812 C 258.375 529.632812 261.933594 526.070312 261.933594 521.679688 L 261.933594 493.851562 C 261.933594 489.460938 258.375 485.902344 253.980469 485.902344 L 164.441406 485.902344 C 160.050781 485.902344 156.492188 489.460938 156.492188 493.851562 L 156.492188 521.679688 C 156.492188 526.070312 160.050781 529.632812 164.441406 529.632812 Z M 253.980469 529.632812 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#fa935d4cdc)\"><path fill=\"#960033\" d=\"M 633.523438 182.570312 C 633.523438 147.992188 605.492188 119.957031 570.910156 119.957031 C 536.332031 119.957031 508.296875 147.992188 508.296875 182.570312 C 508.296875 217.148438 536.332031 245.183594 570.910156 245.183594 C 605.492188 245.183594 633.523438 217.148438 633.523438 182.570312 Z M 516.25 182.570312 C 516.25 152.429688 540.773438 127.902344 570.910156 127.902344 C 601.054688 127.902344 625.578125 152.429688 625.578125 182.570312 C 625.578125 212.710938 601.054688 237.234375 570.910156 237.234375 C 540.773438 237.234375 516.25 212.710938 516.25 182.570312 Z M 516.25 182.570312 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#960033\" d=\"M 606.355469 182.898438 L 572.5625 182.898438 L 572.5625 144.140625 L 564.613281 144.140625 L 564.613281 190.851562 L 606.355469 190.851562 Z M 606.355469 182.898438 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 446.0625 216.40625 L 437.800781 261.394531 L 455.027344 258.050781 L 443.964844 298.773438 L 445.84375 299.203125 L 464.414062 252.015625 L 445.074219 254.390625 L 454.359375 217.90625 Z M 446.0625 216.40625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 458.503906 307.550781 L 491.976562 280.722656 L 476.773438 274.335938 L 498.925781 251.453125 L 493.464844 246.871094 L 468.488281 276.425781 L 482.546875 281.207031 L 457.304688 306.453125 Z M 458.503906 307.550781 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 419.886719 268.886719 L 426.183594 303.464844 L 427.742188 303.117188 L 424.777344 260.984375 L 411.089844 269.703125 L 404.976562 238.949219 L 398.199219 240.800781 L 408.136719 277.578125 Z M 419.886719 268.886719 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 341.382812 514.769531 C 334.589844 527.3125 331.6875 541.992188 331.683594 558.589844 C 331.792969 586.664062 339.589844 621.535156 356.957031 669.695312 C 361.820312 683.113281 376.636719 690.042969 390.054688 685.179688 C 403.476562 680.320312 410.410156 665.503906 405.542969 652.085938 C 389.160156 607.113281 383.261719 576.503906 383.371094 558.589844 C 383.363281 549.128906 384.882812 543.480469 386.265625 540.496094 C 387.335938 538.222656 388.210938 537.242188 389.292969 536.277344 C 390.871094 534.914062 393.699219 533.402344 398.910156 532.304688 C 404.03125 531.214844 411.09375 530.761719 419.019531 530.773438 C 426.066406 530.761719 432.429688 531.109375 437.347656 531.972656 C 441.058594 532.597656 443.890625 533.5 445.8125 534.425781 C 448.707031 535.941406 449.652344 536.757812 451.25 539.460938 C 452.753906 542.179688 454.671875 547.917969 454.667969 558.585938 C 454.777344 576.5 448.875 607.121094 432.492188 652.082031 C 427.632812 665.5 434.566406 680.320312 447.984375 685.179688 C 450.890625 686.230469 453.863281 686.730469 456.789062 686.730469 C 467.359375 686.730469 477.277344 680.203125 481.085938 669.691406 L 481.085938 669.6875 C 498.453125 621.535156 506.242188 586.667969 506.351562 558.585938 C 506.34375 543.804688 504.066406 530.632812 498.773438 519.011719 C 494.839844 510.335938 489.089844 502.734375 482.332031 496.992188 C 479.648438 494.707031 476.855469 492.730469 474.011719 491.003906 L 474.363281 486.628906 L 478.796875 431.6875 C 479.246094 432.050781 479.695312 432.414062 480.152344 432.785156 C 486.539062 437.914062 493.257812 443.074219 499.472656 447.238281 C 502.601562 449.332031 505.578125 451.167969 508.671875 452.734375 C 510.234375 453.511719 511.824219 454.230469 513.695312 454.859375 C 515.585938 455.460938 517.710938 456.089844 520.976562 456.125 C 521.015625 456.125 521.046875 456.125 521.082031 456.125 C 523.898438 456.125 528.230469 455.441406 532.25 452.242188 C 536.371094 449.019531 538.34375 443.992188 538.667969 440.671875 C 538.667969 440.667969 538.667969 440.660156 538.667969 440.65625 C 538.671875 440.644531 538.671875 440.632812 538.675781 440.617188 C 538.6875 440.53125 538.683594 440.441406 538.691406 440.351562 C 538.746094 439.84375 538.78125 439.335938 538.789062 438.832031 C 538.796875 438.621094 538.828125 438.410156 538.828125 438.195312 C 538.773438 434.441406 538 432.023438 537.195312 429.664062 C 536.351562 427.335938 535.332031 425.160156 534.085938 422.792969 C 531.601562 418.101562 528.195312 412.671875 523.503906 405.871094 C 523.375 405.679688 523.226562 405.476562 523.09375 405.285156 C 513.722656 391.757812 499.339844 372.960938 478.011719 346.777344 C 472.460938 339.964844 462.445312 338.945312 455.636719 344.5 C 448.828125 350.046875 447.808594 360.0625 453.355469 366.871094 C 471.519531 389.15625 484.449219 405.890625 493.152344 418.015625 C 493.3125 418.234375 493.457031 418.441406 493.613281 418.660156 L 489.921875 420.332031 C 483.425781 411.289062 474.847656 400.0625 464.386719 386.910156 C 457.878906 399.984375 445.8125 410.171875 430.511719 413.738281 C 426.722656 414.617188 422.839844 415.070312 418.980469 415.070312 C 399.324219 415.066406 382.035156 403.921875 373.65625 386.917969 C 363.199219 400.070312 354.617188 411.296875 348.125 420.335938 L 344.433594 418.660156 C 344.589844 418.445312 344.738281 418.238281 344.894531 418.015625 C 353.601562 405.890625 366.53125 389.160156 384.691406 366.875 C 390.242188 360.066406 389.21875 350.046875 382.410156 344.5 C 375.601562 338.949219 365.589844 339.96875 360.039062 346.777344 C 338.707031 372.964844 324.324219 391.761719 314.957031 405.289062 C 314.820312 405.476562 314.675781 405.683594 314.542969 405.875 C 309.851562 412.675781 306.449219 418.101562 303.960938 422.792969 C 302.71875 425.160156 301.695312 427.339844 300.855469 429.664062 C 300.046875 432.027344 299.273438 434.445312 299.21875 438.199219 C 299.21875 438.398438 299.25 438.59375 299.257812 438.792969 C 299.265625 439.398438 299.296875 440.003906 299.375 440.617188 C 299.683594 443.953125 301.660156 449.019531 305.789062 452.246094 C 309.816406 455.449219 314.148438 456.128906 316.957031 456.128906 C 316.996094 456.128906 317.03125 456.128906 317.066406 456.128906 C 320.332031 456.089844 322.457031 455.464844 324.347656 454.863281 C 331.003906 452.484375 335.957031 449.03125 342.117188 444.796875 C 347.679688 440.859375 353.660156 436.214844 359.25 431.691406 L 363.675781 486.570312 L 364.035156 491.015625 C 355.148438 496.4375 346.871094 504.484375 341.382812 514.769531 Z M 341.382812 514.769531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 387.773438 369.386719 C 383.769531 374.296875 379.992188 378.976562 376.40625 383.460938 C 385.339844 403.480469 407.464844 415.015625 429.609375 409.859375 C 444.390625 406.421875 455.871094 396.3125 461.636719 383.457031 C 458.046875 378.972656 454.277344 374.296875 450.273438 369.386719 C 443.351562 360.890625 444.628906 348.34375 453.125 341.417969 C 454.582031 340.230469 456.203125 339.273438 457.914062 338.550781 C 447.441406 322.789062 427.941406 314.371094 408.429688 318.917969 C 396.367188 321.726562 386.5 328.988281 380.144531 338.554688 C 381.851562 339.277344 383.46875 340.234375 384.921875 341.417969 C 393.414062 348.34375 394.695312 360.890625 387.773438 369.386719 Z M 387.773438 369.386719 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">Palestras Profissionais<\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tSeja no ambiente m\u00e9dico, corporativo ou acad\u00eamico, h\u00e1 sempre um ponto em comum: pessoas enfrentando desafios que afetam sua sa\u00fade mental, f\u00edsica e emocional. A Dra. C\u00edcera Pontes, com sua vasta experi\u00eancia em neurologia e uma abordagem integrativa, transforma complexas quest\u00f5es de sa\u00fade em aprendizados acess\u00edveis e transformadores na sua institui\u00e7\u00e3o.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/o-poder-das-palestras-de-conscientizacao-transformando-vidas-com-informacao-e-inspiracao\/\">\n\t\t\t\t\t\tSaiba mais\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91d6a3e elementor-cta--skin-cover animated-slow elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-invisible elementor-widget elementor-widget-call-to-action\" data-id=\"91d6a3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-stacked elementor-shape-circle elementor-animated-item--grow\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"1080\" viewBox=\"0 0 810 809.999993\" height=\"1080\" preserveAspectRatio=\"xMidYMid meet\"><path fill=\"#960033\" d=\"M 387.148438 176.148438 C 400.59375 166.070312 408.949219 152.0625 408.949219 136.5625 C 408.949219 105.875 376.285156 81 335.992188 81 C 295.699219 81 263.035156 105.875 263.035156 136.5625 C 263.035156 167.246094 295.699219 192.125 335.992188 192.125 C 341.050781 192.125 345.984375 191.730469 350.75 190.984375 C 372.796875 208.464844 424.207031 207.808594 424.207031 207.808594 C 403.945312 200.238281 392.539062 185.3125 387.148438 176.148438 Z M 310.507812 140.28125 C 310.507812 143.480469 307.917969 146.066406 304.722656 146.066406 C 301.523438 146.066406 298.9375 143.480469 298.9375 140.28125 L 298.9375 129.160156 C 298.9375 125.964844 301.523438 123.375 304.722656 123.375 C 307.917969 123.375 310.507812 125.964844 310.507812 129.160156 Z M 341.753906 140.28125 C 341.753906 143.480469 339.164062 146.066406 335.96875 146.066406 C 332.769531 146.066406 330.179688 143.480469 330.179688 140.28125 L 330.179688 129.160156 C 330.179688 125.964844 332.769531 123.375 335.96875 123.375 C 339.164062 123.375 341.753906 125.964844 341.753906 129.160156 Z M 373.007812 140.28125 C 373.007812 143.480469 370.421875 146.066406 367.222656 146.066406 C 364.023438 146.066406 361.4375 143.480469 361.4375 140.28125 L 361.4375 129.160156 C 361.4375 125.964844 364.023438 123.375 367.222656 123.375 C 370.421875 123.375 373.007812 125.964844 373.007812 129.160156 Z M 373.007812 140.28125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 228.207031 619.941406 L 150.429688 619.941406 C 147.230469 619.941406 144.644531 622.53125 144.644531 625.726562 L 144.644531 723.214844 C 144.644531 726.414062 147.230469 729 150.429688 729 L 228.207031 729 C 231.40625 729 233.992188 726.414062 233.992188 723.214844 L 233.992188 625.726562 C 233.992188 622.53125 231.40625 619.941406 228.207031 619.941406 Z M 222.421875 717.429688 L 156.214844 717.429688 L 156.214844 631.511719 L 222.421875 631.511719 Z M 222.421875 717.429688 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 371.992188 566.535156 L 294.210938 566.535156 C 291.015625 566.535156 288.425781 569.125 288.425781 572.324219 L 288.425781 723.214844 C 288.425781 726.414062 291.015625 729 294.210938 729 L 371.992188 729 C 375.191406 729 377.777344 726.414062 377.777344 723.214844 L 377.777344 572.324219 C 377.777344 569.125 375.191406 566.535156 371.992188 566.535156 Z M 366.207031 717.429688 L 300 717.429688 L 300 578.109375 L 366.207031 578.109375 Z M 366.207031 717.429688 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 515.789062 472.859375 L 438.007812 472.859375 C 434.808594 472.859375 432.222656 475.445312 432.222656 478.644531 L 432.222656 723.214844 C 432.222656 726.414062 434.808594 729 438.007812 729 L 515.789062 729 C 518.984375 729 521.574219 726.414062 521.574219 723.214844 L 521.574219 478.644531 C 521.574219 475.445312 518.984375 472.859375 515.789062 472.859375 Z M 510 717.429688 L 443.792969 717.429688 L 443.792969 484.429688 L 510 484.429688 Z M 510 717.429688 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 659.570312 454.675781 L 581.792969 454.675781 C 578.59375 454.675781 576.007812 457.261719 576.007812 460.460938 L 576.007812 723.214844 C 576.007812 726.414062 578.59375 729 581.792969 729 L 659.570312 729 C 662.769531 729 665.355469 726.414062 665.355469 723.214844 L 665.355469 460.460938 C 665.355469 457.261719 662.769531 454.675781 659.570312 454.675781 Z M 653.785156 717.429688 L 587.578125 717.429688 L 587.578125 466.246094 L 653.785156 466.246094 Z M 653.785156 717.429688 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 368.375 306.78125 C 368.375 307.835938 368.324219 308.886719 368.222656 309.933594 C 368.117188 310.984375 367.964844 312.023438 367.757812 313.058594 C 367.550781 314.089844 367.296875 315.113281 366.992188 316.121094 C 366.683594 317.128906 366.332031 318.117188 365.925781 319.09375 C 365.523438 320.066406 365.074219 321.015625 364.578125 321.945312 C 364.082031 322.875 363.539062 323.777344 362.953125 324.652344 C 362.371094 325.53125 361.742188 326.375 361.074219 327.1875 C 360.40625 328.003906 359.699219 328.785156 358.953125 329.527344 C 358.210938 330.273438 357.429688 330.980469 356.617188 331.648438 C 355.800781 332.316406 354.957031 332.945312 354.078125 333.527344 C 353.203125 334.113281 352.300781 334.65625 351.371094 335.152344 C 350.441406 335.648438 349.492188 336.097656 348.519531 336.5 C 347.542969 336.90625 346.554688 337.257812 345.546875 337.566406 C 344.539062 337.871094 343.515625 338.125 342.484375 338.332031 C 341.449219 338.539062 340.410156 338.691406 339.359375 338.796875 C 338.3125 338.898438 337.261719 338.949219 336.207031 338.949219 C 335.15625 338.949219 334.101562 338.898438 333.054688 338.796875 C 332.007812 338.691406 330.964844 338.539062 329.933594 338.332031 C 328.898438 338.125 327.878906 337.871094 326.871094 337.566406 C 325.863281 337.257812 324.871094 336.90625 323.898438 336.5 C 322.925781 336.097656 321.972656 335.648438 321.042969 335.152344 C 320.113281 334.65625 319.210938 334.113281 318.335938 333.527344 C 317.460938 332.945312 316.613281 332.316406 315.800781 331.648438 C 314.984375 330.980469 314.207031 330.273438 313.460938 329.527344 C 312.714844 328.785156 312.007812 328.003906 311.339844 327.1875 C 310.671875 326.375 310.046875 325.53125 309.460938 324.652344 C 308.875 323.777344 308.335938 322.875 307.835938 321.945312 C 307.339844 321.015625 306.890625 320.066406 306.488281 319.09375 C 306.085938 318.117188 305.730469 317.128906 305.425781 316.121094 C 305.117188 315.113281 304.863281 314.089844 304.65625 313.058594 C 304.453125 312.023438 304.296875 310.984375 304.195312 309.933594 C 304.089844 308.886719 304.039062 307.835938 304.039062 306.78125 C 304.039062 305.726562 304.089844 304.675781 304.195312 303.628906 C 304.296875 302.582031 304.453125 301.539062 304.65625 300.507812 C 304.863281 299.472656 305.117188 298.453125 305.425781 297.445312 C 305.730469 296.433594 306.085938 295.445312 306.488281 294.472656 C 306.890625 293.496094 307.339844 292.546875 307.835938 291.617188 C 308.335938 290.6875 308.875 289.785156 309.460938 288.910156 C 310.046875 288.035156 310.671875 287.1875 311.339844 286.375 C 312.007812 285.558594 312.714844 284.78125 313.460938 284.035156 C 314.207031 283.289062 314.984375 282.582031 315.800781 281.914062 C 316.613281 281.246094 317.460938 280.621094 318.335938 280.035156 C 319.210938 279.449219 320.113281 278.910156 321.042969 278.410156 C 321.972656 277.914062 322.925781 277.464844 323.898438 277.0625 C 324.871094 276.660156 325.863281 276.304688 326.871094 276 C 327.878906 275.691406 328.898438 275.4375 329.933594 275.230469 C 330.964844 275.027344 332.007812 274.871094 333.054688 274.769531 C 334.101562 274.664062 335.15625 274.613281 336.207031 274.613281 C 337.261719 274.613281 338.3125 274.664062 339.359375 274.769531 C 340.410156 274.871094 341.449219 275.027344 342.484375 275.230469 C 343.515625 275.4375 344.539062 275.691406 345.546875 276 C 346.554688 276.304688 347.542969 276.660156 348.519531 277.0625 C 349.492188 277.464844 350.441406 277.914062 351.371094 278.410156 C 352.300781 278.910156 353.203125 279.449219 354.078125 280.035156 C 354.957031 280.621094 355.800781 281.246094 356.617188 281.914062 C 357.429688 282.582031 358.210938 283.289062 358.953125 284.035156 C 359.699219 284.78125 360.40625 285.558594 361.074219 286.375 C 361.742188 287.1875 362.371094 288.035156 362.953125 288.910156 C 363.539062 289.785156 364.082031 290.6875 364.578125 291.617188 C 365.074219 292.546875 365.523438 293.496094 365.925781 294.472656 C 366.332031 295.445312 366.683594 296.433594 366.992188 297.445312 C 367.296875 298.453125 367.550781 299.472656 367.757812 300.507812 C 367.964844 301.539062 368.117188 302.582031 368.222656 303.628906 C 368.324219 304.675781 368.375 305.726562 368.375 306.78125 Z M 368.375 306.78125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 429.550781 352.53125 C 424.691406 344.820312 414.429688 342.480469 406.648438 347.269531 L 347.210938 384.070312 L 314.453125 345.300781 C 314.140625 344.933594 313.769531 344.648438 313.433594 344.316406 C 313.207031 344.082031 312.96875 343.863281 312.734375 343.640625 C 312.324219 343.277344 311.917969 342.929688 311.484375 342.613281 C 309.808594 341.242188 307.980469 340.015625 305.863281 339.15625 C 294.53125 334.566406 281.601562 339.847656 276.914062 351.035156 L 233.792969 453.253906 C 233.429688 454.117188 201.183594 544.675781 201.183594 544.675781 L 168.492188 591.328125 C 161.507812 601.292969 164.058594 614.984375 174.144531 621.882812 C 178.019531 624.511719 182.34375 625.714844 186.777344 625.714844 C 193.757812 625.714844 200.628906 622.429688 204.949219 616.296875 L 239.414062 567.015625 C 240.632812 565.265625 241.628906 563.402344 242.296875 561.429688 C 242.296875 561.429688 266.234375 497.945312 270.503906 486.046875 L 307.394531 491.285156 L 312.058594 552.074219 C 312.933594 563.570312 322.652344 572.320312 334.132812 572.320312 C 334.695312 572.320312 335.257812 572.296875 335.832031 572.253906 C 348.039062 571.34375 357.183594 560.824219 356.253906 548.757812 L 350.246094 470.453125 C 349.46875 460.21875 341.589844 451.886719 331.296875 450.429688 L 285.652344 443.949219 L 308.625 389.65625 L 330.953125 416.089844 C 334.210938 419.949219 338.929688 421.992188 343.722656 421.992188 C 346.734375 421.992188 349.785156 421.179688 352.5 419.511719 L 424.222656 375.164062 C 432.015625 370.371094 434.398438 360.230469 429.550781 352.53125 Z M 429.550781 352.53125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 477.53125 223.074219 C 495.296875 223.074219 509.699219 208.671875 509.699219 190.90625 C 509.699219 173.136719 495.296875 158.734375 477.53125 158.734375 C 459.765625 158.734375 445.359375 173.136719 445.359375 190.90625 C 445.359375 208.671875 459.765625 223.074219 477.53125 223.074219 Z M 477.53125 223.074219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#960033\" d=\"M 629.933594 431.328125 L 606.664062 363.757812 L 603.003906 304.839844 C 603.007812 304.875 602.425781 299.03125 599.859375 295.300781 L 550.6875 216.351562 C 544.269531 206.054688 530.609375 202.835938 520.191406 209.1875 C 518.464844 210.234375 513.589844 214.214844 511.730469 218.4375 L 476.160156 299.769531 L 434.234375 332.257812 C 427.015625 337.863281 425.75 348.183594 431.410156 355.328125 C 434.6875 359.457031 439.570312 361.617188 444.503906 361.617188 C 448.097656 361.617188 451.710938 360.472656 454.753906 358.121094 L 500 323.050781 C 502.175781 321.363281 503.894531 319.160156 505 316.636719 L 528.136719 263.726562 L 552.296875 302.519531 L 491.101562 355.566406 C 487.605469 358.601562 485.160156 362.65625 484.121094 367.148438 L 464.496094 451.855469 C 461.757812 463.640625 469.214844 475.394531 481.152344 478.089844 C 482.816406 478.476562 484.472656 478.648438 486.117188 478.648438 C 496.214844 478.648438 505.347656 471.78125 507.695312 461.632812 L 525.730469 383.832031 L 561.558594 352.773438 L 562.558594 369.34375 C 562.667969 371.316406 563.109375 373.285156 563.664062 375.148438 L 588.046875 445.566406 C 591.148438 454.65625 599.792969 460.347656 608.988281 460.347656 C 611.316406 460.347656 613.753906 460.019531 616.191406 459.144531 C 627.71875 455.3125 633.921875 442.828125 629.933594 431.328125 Z M 629.933594 431.328125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">Mentoria e Coaching<\/h2>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t\tPlanos personalizados para aumentar a qualidade de vida com equil\u00edbrio entre a vida pessoal e profissional para profissionais de sa\u00fade. Instru\u00e7\u00f5es fundamentais para jovens profissionais ou estudantes com interesse em doen\u00e7as neurodegenerativas.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item elementor-animated-item--grow\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-xs\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/profissional-de-saude-descubra-como-melhorar-sua-performance-profissional-e-transformar-a-vida-dos-seus-pacientes\/\">\n\t\t\t\t\t\tSaiba mais\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b1a4ff e-flex e-con-boxed e-con e-parent\" data-id=\"0b1a4ff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-294a10b elementor-widget elementor-widget-stratum-instagram\" data-id=\"294a10b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"stratum-instagram.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9eefa8c e-flex e-con-boxed e-con e-parent\" data-id=\"9eefa8c\" data-element_type=\"container\" data-e-type=\"container\" id=\"sobremim\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a4639d9 e-con-full e-flex e-con e-child\" data-id=\"a4639d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6467bd3 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6467bd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;slideInLeft&quot;,&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sobre Dra. C\u00edcera Pontes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cfce9ab animated-slow elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"cfce9ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;slideInLeft&quot;,&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76ed320 animated-slow elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"76ed320\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInLeft&quot;,&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Neurologista com mais de 20 anos de experi\u00eancia dedicada a transformar vidas<\/strong>, minha paix\u00e3o \u00e9 ajudar pessoas a viverem com mais sa\u00fade mental e equil\u00edbrio emocional.<\/p><p><strong> Acredito que cada indiv\u00edduo merece ser acolhido<\/strong> <strong>e compreendido de forma \u00fanica<\/strong>, meu trabalho \u00e9 trazer leveza e qualidade de vida para quem enfrenta desafios neurol\u00f3gicos como Parkinson, dist\u00farbios de mem\u00f3ria ou ins\u00f4nia.\u00a0<\/p><p><strong>Minha abordagem<\/strong> visa integrar conhecimentos multidisciplinares, al\u00e9m do tratamento cl\u00ednico convencional, atrav\u00e9s da medicina integrativa busco orientar, inspirar e empoderar pessoas, seja por meio de palestras que despertam a consci\u00eancia e promovem mudan\u00e7as positivas ou com minhas mentorias que ajudam jovens profissionais a se conectarem com seus prop\u00f3sitos e a alcan\u00e7arem seu potencial m\u00e1ximo.\u00a0<\/p><p><span style=\"text-decoration: underline;\"><strong>O que mais me motiva \u00e9 saber que posso contribuir para que meus pacientes vivam com mais autonomia<\/strong><\/span>, serenidade e bem-estar, levando sempre um olhar humano e acolhedor em tudo que fa\u00e7o.<\/p><p><strong>Meu compromisso \u00e9 estar ao lado de todos os principais atores no combate \u00e0s doen\u00e7as neurodegenerativas<\/strong>, ajudando a construir uma jornada mais leve, saud\u00e1vel e significativa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-920fe15 e-con-full e-flex e-con e-child\" data-id=\"920fe15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19dd501 elementor-widget elementor-widget-image\" data-id=\"19dd501\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1150\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Conheca-a-Dra.Cicera-Pontes-1.png\" class=\"attachment-full size-full wp-image-1451\" alt=\"Quem \u00e9 a Dra C\u00edcera Pontes\" srcset=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Conheca-a-Dra.Cicera-Pontes-1.png 1080w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Conheca-a-Dra.Cicera-Pontes-1-282x300.png 282w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Conheca-a-Dra.Cicera-Pontes-1-962x1024.png 962w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Conheca-a-Dra.Cicera-Pontes-1-768x818.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Conhe\u00e7a a Dra.C\u00edcera Pontes.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d61e0a8 animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"d61e0a8\" data-element_type=\"container\" data-e-type=\"container\" id=\"convenios\" data-settings=\"{&quot;animation_mobile&quot;:&quot;zoomIn&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-18689c0 elementor-skin-coverflow elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"18689c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;coverflow&quot;,&quot;slides_per_view_mobile&quot;:&quot;2&quot;,&quot;speed&quot;:200,&quot;autoplay_speed&quot;:1000,&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;pagination&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper-container\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" style=\"background-image: url(&#039;https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Convenios-dra-cicera-2.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" style=\"background-image: url(&#039;https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Convenios-dra-cicera-1.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" style=\"background-image: url(&#039;https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Convenios-dra-cicera.png&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5a3ab7 e-flex e-con-boxed e-con e-parent\" data-id=\"b5a3ab7\" data-element_type=\"container\" data-e-type=\"container\" id=\"curriculo\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a4ad243 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"a4ad243\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation_mobile&quot;:&quot;zoomIn&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-474bb9b elementor-widget elementor-widget-heading\" data-id=\"474bb9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Meu Curriculo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c49c2fe elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c49c2fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">CRM AL 2833 RQE N\u00ba: 239023<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Curso Superior \u2013 Medicina (Graduada em Medicina pela Universidade Federal de Alagoas em 30 de Outubro de 1989)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Especializa\u00e7\u00e3o em Neurologia pela Universidade Federal Fluminense (UFF)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P\u00f3s-gradua\u00e7\u00e3o em Neurologia a n\u00edvel de Mestrado Latun-Sensu pela Universidade Federal Fluminense<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mestrado em Neurologia pela UFF<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Especialista em Neuroci\u00eancias<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mastercoach Integral Sist\u00eamico (CIS)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mais de 5.000 Clientes atendidos<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4412da elementor-widget elementor-widget-heading\" data-id=\"f4412da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Atua\u00e7\u00e3o profissional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-949f8f4 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"949f8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Neurologista especialista em Doen\u00e7a de Parkinson da InNeuro;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Neurologista da COOPNEURO-HGE;<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Neurologista respons\u00e1vel pelo ambulat\u00f3rio de dist\u00farbio do movimento e Doen\u00e7a de Parkinson no HU.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">M\u00e9dica assistente da Associa\u00e7\u00e3o Parkinson de Alagoas \u2013 AsPAL.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mais de 385 Avalia\u00e7\u00f5es no Doctor\u00e1lia<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-370e7fe elementor-widget elementor-widget-heading\" data-id=\"370e7fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Assossia\u00e7\u00f5es que participa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de216bd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"de216bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Membro da Movement Disorder Society<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">M\u00e9dica assistente da Associa\u00e7\u00e3o Parkinson Alagoas \u2013 Aspal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Membro da Sociedade de Neurofisiologia Cl\u00ednica<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Membro da Associa\u00e7\u00e3o M\u00e9dica Brasileira<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Membro do Conselho Regional de Medicina<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fcd5f3 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"1fcd5f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entrevistas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82ba5f3 elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"82ba5f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Gazeta - AL TV 1\u00aa Edi\u00e7\u00e3o e Bom dia Brasil - Falta de medicamentos para pacientes em Alagoas <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Gazeta - Bom dia Alagoas - Entrevista sobre o Dia Mundial de Parkinson - 11 de abril de 2013<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio Educativa - Entrevista sobre o Dia mundial de Parkinson - 11 de abril de 2013<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio Gazeta - Entrevista sobre o Dia Mundial de Parkinson - 10 de abril de 2013<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio Gazeta - Entrevista sobre o Dia Mundial de Parkinson - 10 de abril de 2013<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Gazeta - Reportagem sobre Dia Internacional da Doen\u00e7a de Parkinson - 11 de abril de 2012<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio CBN - Entrevista sobre Dia Nacional da Doen\u00e7a de Parkinson - 4 de Abril de 2012<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio Correio -Entrevista sobre Dia Nacional da Doen\u00e7a de Parkinson - 4 de Abril de 2012<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Gazeta - jornal Bom Dia Alagoas, com Gilvan Nunes - 20 de dezembro de 2011<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Paju\u00e7ara - programa Feito pra Voc\u00ea - Fabiola Aguiar - 19 de dezembro de 2011<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Gazeta, jornal Bom Dia Alagoas. Tema: AVC (Acidente Vascular Cerebral). Setembro 2011<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio Educativa. Tema: Encontro da Associa\u00e7\u00e3o Parkinson Alagoas. Agosto 2011<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio CBN. Tema: Doen\u00e7a de Parkinson, abril de 2011<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio Gazeta, programa Minist\u00e9rio do Povo, abril de 2011<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">NET TV, programa Planeta Fashion, Julho de 2011<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Gazeta, Bom dia Alagoas, abril de 2011<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Paju\u00e7ara, programa Feito Pra Voc\u00ea - Doen\u00e7a de Parkinson - Abril De 2010<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e1dio Gazeta, Programa Minist\u00e9rio do Povo - Doen\u00e7a De Parkinson - Abril de 2010<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Paiu\u00e7ara, programa Paju\u00e7ara Manh\u00e3 - Doen\u00e7a De Parkinson - 04\/2010<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Gazeta, jornal Bom dia Alagoas - Doen\u00e7a De Parkinson - 04\/2010<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Entrevista \/ Palestra no Programa - Perfil com 1h de dura\u00e7\u00e3o na TV Assembl\u00e9ia, 2010<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV Paiu\u00e7ara, no Programa Feito pra Voc\u00ea - em dezembro de 2010 - Doen\u00e7a de Parkinson<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-056e3ff e-flex e-con-boxed e-con e-parent\" data-id=\"056e3ff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-62bff35 e-con-full e-flex e-con e-child\" data-id=\"62bff35\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-416e59f animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"416e59f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Como Funciona Meu Atendimento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a649d19 e-grid e-con-full e-con e-child\" data-id=\"a649d19\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee7e415 elementor-position-inline-start animated-slow elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"ee7e415\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;slideInLeft&quot;,&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConsultas de 1 hora\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t1 hora pra te ouvir com aten\u00e7\u00e3o, entender suas necessidades e preocupa\u00e7\u00f5es e oferecer um atendimento individualizado.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73501ee elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"73501ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;slideInRight&quot;,&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar-day\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRetorno em at\u00e9 trinta dias\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTenha a garantia de retorno em at\u00e9 30 dias para acompanhamento do seu tratamento e ajustes quando necess\u00e1rio.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75f658d elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"75f658d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;slideInRight&quot;,&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-heartbeat\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIndica\u00e7\u00e3o de Exames\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAp\u00f3s avalia\u00e7\u00e3o se necess\u00e1rio ser\u00e1 receitado exames laboratoriais, Bioimped\u00e2ncia, Eletroneuromiografia, etc. De acordo com a necessidade (Se necess\u00e1rio).\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c2bf99 elementor-position-inline-start animated-slow elementor-view-default elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"5c2bf99\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;slideInLeft&quot;,&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAgendamento On-line\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAgende sua consulta online 24 horas por dia, 7 dias por semana, com apenas alguns cliques, no conforto da sua casa.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bf1133 elementor-align-center animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"0bf1133\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;zoomIn&quot;,&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/wa.me\/5582991062927\u200b\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar consulta<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b4f6fbb animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"b4f6fbb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeIn&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bf4911 elementor-widget elementor-widget-heading\" data-id=\"8bf4911\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">O que Meus Pacientes Est\u00e3o Falando:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de035f2 elementor-widget elementor-widget-shortcode\" data-id=\"de035f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"%d %s atr\u00e1s|hoje|dia|dias|semana|semanas|m\u00eas|meses|ano|anos\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"ligth-border\" data-pid=\"\" data-language=\"pt\" data-close-locale=\"Fechar\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"Resposta do propriet\u00e1rio\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Google\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> BOM <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/e.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">Com base em <strong>4 avalia\u00e7\u00f5es<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Google\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Pr\u00f3xima avalia\u00e7\u00e3o\" role=\"button\"><\/div> <div class=\"ti-prev\" aria-label=\"Avalia\u00e7\u00e3o anterior\" role=\"button\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"1\" data-time=\"1720396800\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado em <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ2hyq6FETpTDw2lcnIUclmryHlZZ9p2iZqBG6pqVIEv54qNA=w40-h40-c-rp-mo-br100\" alt=\"Madar Fontes profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Madar Fontes <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\"><\/span> <\/div> <\/div>  <div data-empty=\"1\" data-time=\"1705449600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado em <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjX6sX_02ZkXzcfNrdg_c63urS8cqBDf2Z5iGx6GVGTOoP8DqV4=w40-h40-c-rp-mo-br100\" alt=\"telma cavalcante profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> telma cavalcante <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/e.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\"><\/span> <\/div> <\/div>  <div data-empty=\"1\" data-time=\"1682553600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publicado em <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXtMdAiLYyvlnUU55TVsi9WaOIntCkM3ZZ6KBaTe7F6_3H7Vz9p=w40-h40-c-rp-mo-br100\" alt=\"Cicera Pontes profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Cicera Pontes <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex verifica se a fonte original da avalia\u00e7\u00e3o \u00e9 Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Esconder\" data-open-text=\"Consulte Mais informa\u00e7\u00e3o\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/trustindex-google-widget.css?1765554835\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f5d0c2e e-flex e-con-boxed e-con e-parent\" data-id=\"f5d0c2e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30301f4 elementor-widget elementor-widget-heading\" data-id=\"30301f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Blog<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c87a5b elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7c87a5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star-half\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Informa\u00e7\u00e3o e Dicas para Sua Sa\u00fade<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e79290 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"7e79290\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:22,&quot;sizes&quot;:[]},&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2072 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/a-importancia-de-consultar-um-especialista-em-disturbios-do-movimento\/\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Pagina-de-captura-simposio-neuroviva-mais-8.png\" class=\"attachment-full size-full wp-image-2075\" alt=\"Post para Consulta com especialista em disturbio do movimento\" srcset=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Pagina-de-captura-simposio-neuroviva-mais-8.png 1920w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Pagina-de-captura-simposio-neuroviva-mais-8-300x169.png 300w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Pagina-de-captura-simposio-neuroviva-mais-8-1024x576.png 1024w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Pagina-de-captura-simposio-neuroviva-mais-8-768x432.png 768w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/Pagina-de-captura-simposio-neuroviva-mais-8-1536x864.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Uncategorized<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/a-importancia-de-consultar-um-especialista-em-disturbios-do-movimento\/\" >\n\t\t\t\tA Import\u00e2ncia de Consultar um Especialista em Dist\u00farbios do Movimento\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Por que consultar com um especialista? Quando se trata de dist\u00farbios do movimento, como Doen\u00e7a de Parkinson, distonia, tremores essenciais ou outros desafios neurol\u00f3gicos, a<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/a-importancia-de-consultar-um-especialista-em-disturbios-do-movimento\/\" aria-label=\"Read more about A Import\u00e2ncia de Consultar um Especialista em Dist\u00farbios do Movimento\" >\n\t\t\tLeia Mais\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2000 post type-post status-publish format-standard has-post-thumbnail hentry category-parkinson\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/o-que-e-parkinson\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"493\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/paciente-idoso-que-sofre-de-parkinson.jpg\" class=\"attachment-full size-full wp-image-2001\" alt=\"Foto de Capa para Artigo: O que \u00e9 a doen\u00e7a de Parkinson?\" srcset=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/paciente-idoso-que-sofre-de-parkinson.jpg 740w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/paciente-idoso-que-sofre-de-parkinson-300x200.jpg 300w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Tratamento de Parkinson<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/o-que-e-parkinson\/\" >\n\t\t\t\tO que \u00e9 Parkinson?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A Doen\u00e7a de Parkinson ocorre devido \u00e0 degenera\u00e7\u00e3o das c\u00e9lulas situadas numa regi\u00e3o do c\u00e9rebro chamada subst\u00e2ncia negra, por\u00e9m n\u00e3o sabemos o que causa essa degenera\u00e7\u00e3o. Essas c\u00e9lulas produzem uma subst\u00e2ncia chamada dopamina, respons\u00e1vel junto com os n\u00facleos da base de harmonizar os movimentos do corpo, bloqueando os movimentos indesej\u00e1veis.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/o-que-e-parkinson\/\" aria-label=\"Read more about O que \u00e9 Parkinson?\" >\n\t\t\tLeia Mais\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1716 post type-post status-publish format-standard has-post-thumbnail hentry category-neurovivamais category-parkinson\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/programa-de-conscientizacao-neuro-viva\/\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"493\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/descanse-a-beira-mar_vivendo_melhor_com_parkinson.jpg\" class=\"attachment-full size-full wp-image-2006\" alt=\"Foto de capa do post: Desbloqueando o potencial na doen\u00e7a de parkinson\" srcset=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/descanse-a-beira-mar_vivendo_melhor_com_parkinson.jpg 740w, https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/2025\/01\/descanse-a-beira-mar_vivendo_melhor_com_parkinson-300x200.jpg 300w\" sizes=\"(max-width: 740px) 100vw, 740px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Neuro Viva +<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/programa-de-conscientizacao-neuro-viva\/\" >\n\t\t\t\tDesbloqueando o Potencial na Doen\u00e7a de Parkinson\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>A Doen\u00e7a de Parkinson, embora desafiante, n\u00e3o precisa ser sin\u00f4nimo de limita\u00e7\u00f5es. Hoje, a neurologia avan\u00e7a rapidamente em dire\u00e7\u00e3o a novas estrat\u00e9gias para melhorar a qualidade de vida de quem enfrenta essa condi\u00e7\u00e3o. O objetivo \u00e9 mais do que simplesmente tratar os sintomas; \u00e9 possibilitar que pacientes vivam com independ\u00eancia, dignidade e prop\u00f3sito.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/programa-de-conscientizacao-neuro-viva\/\" aria-label=\"Read more about Desbloqueando o Potencial na Doen\u00e7a de Parkinson\" >\n\t\t\tLeia Mais\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-363a163 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"363a163\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/blog\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver todos os Posts<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdb506c e-flex e-con-boxed e-con e-parent\" data-id=\"bdb506c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52635ad elementor-widget elementor-widget-heading\" data-id=\"52635ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;bounce&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acrescentar imagens (Interior da Cl\u00ednica aqui.)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8012cd8 e-con-full animated-slow e-flex elementor-invisible e-con e-parent\" data-id=\"8012cd8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96f9517 elementor-widget elementor-widget-image-carousel\" data-id=\"96f9517\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:500,&quot;speed&quot;:2000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/quem-somos-inneuro-viva-mais-dra.cicera-pontes-qzodq9vy33om7fyoqg3j3x47s4vcaxkmy1hmvf9dhk.jpg\" alt=\"Post para Consulta com especialista em disturbio do movimento\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-4-qzp71jd2r89cfj4uql9admlsczm1tyw813xqumm008.png\" alt=\"Dra.Cicera Pontes (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-5-qzp71p03w8h2d6wntnp1sl6jxau945im1vunqadmyw.png\" alt=\"Dra.Cicera Pontes (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-11-qzp7v4c7uir7tq5wzvllcnv1ejsx31c3rj2vl4qy6g.png\" alt=\"Dra.Cicera Pontes (11)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-6-qzp71756adsm8lmlpxz4z7osmzaa1wjpnfgfm14494.png\" alt=\"Dra.Cicera Pontes (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-7-qzp71cs7fe0c69eet0ewe69k7aihc363o7dchovr7s.png\" alt=\"Dra.Cicera Pontes (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-8-qzp7vl9b9jedmphc92wvljlc3hhixl79tutm841v2g.png\" alt=\"Dra.Cicera Pontes (8)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-10-qzp7uyp6pijhw2e3wt5txpa9u8kpsuppqr5ypgzb7s.png\" alt=\"Dra.Cicera Pontes (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-9-qzp7ut25kibryematqq2iqpi9xciio3bpz91tt7o94.png\" alt=\"Dra.Cicera Pontes (9)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-12-qzp7v9z8ziyxrdxq2y1crmfsyv14d7yhsazsgsil54.png\" alt=\"Dra.Cicera Pontes (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-content\/uploads\/elementor\/thumbs\/Dra.Cicera-Pontes-13-qzp7vfma4j6np1pj60h46l0kj69bnekvt2wpcga83s.png\" alt=\"Dra.Cicera Pontes (13)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2067b03 e-flex e-con-boxed e-con e-parent\" data-id=\"2067b03\" data-element_type=\"container\" data-e-type=\"container\" id=\"agendamento\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51509e7 elementor-align-center animated-slow elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"51509e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeIn&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-star-half\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chegou sua hora de cuidar de voc\u00ea<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d83858c elementor-widget elementor-widget-heading\" data-id=\"d83858c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AGENDE SUA CONSULTA PELO WHATSAPP<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c92cc70 elementor-align-center animated-slow elementor-invisible elementor-widget elementor-widget-button\" data-id=\"c92cc70\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;zoomIn&quot;,&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"https:\/\/wa.me\/5582991062927\u200b\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">AGENDAR CONSULTA VIA WHATSAPP<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-871bf92 e-con-full e-grid e-con e-child\" data-id=\"871bf92\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-84da057 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"84da057\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation_mobile&quot;:&quot;zoomIn&quot;,&quot;animation&quot;:&quot;slideInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e55a904 elementor-widget elementor-widget-heading\" data-id=\"e55a904\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ou Preencha o Formul\u00e1rio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6238712 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"6238712\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"1079\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"6238712\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-lg  elementor-field-textual\" placeholder=\"Digite seu Nome\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_9372bd6 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_9372bd6\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_9372bd6]\" id=\"form-field-field_9372bd6\" class=\"elementor-field elementor-size-lg  elementor-field-textual\" placeholder=\"Digite seu Telefone\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-lg  elementor-field-textual\" placeholder=\"Digite seu E-mail\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_b665453 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_b665453\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEspecialidades\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_b665453]\" id=\"form-field-field_b665453\" class=\"elementor-field-textual elementor-size-lg\">\n\t\t\t\t\t\t\t\t\t<option value=\"Consulta Neurol\u00f3gica\">Consulta Neurol\u00f3gica<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Contrata\u00e7\u00e3o de Palestras\">Contrata\u00e7\u00e3o de Palestras<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Disturbio do movimento\">Disturbio do movimento<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Doa\u00e7\u00f5es para a Assossia\u00e7\u00e3o\">Doa\u00e7\u00f5es para a Assossia\u00e7\u00e3o<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Eletroneuromiografia\">Eletroneuromiografia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Ins\u00f4nia\">Ins\u00f4nia<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Mentoria e Coaching\">Mentoria e Coaching<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Palestra e Workshop Neuro viva +\">Palestra e Workshop Neuro viva +<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Tratamento para Alzheimer\">Tratamento para Alzheimer<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Tratamento para Parkinson\">Tratamento para Parkinson<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Voluntariado\">Voluntariado<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"OUTRO\">OUTRO<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_4c108cd elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_4c108cd\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tModalidade\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_4c108cd]\" id=\"form-field-field_4c108cd\" class=\"elementor-field-textual elementor-size-lg\">\n\t\t\t\t\t\t\t\t\t<option value=\"Particular\">Particular<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Conv\u00eanio (Bradesco)\">Conv\u00eanio (Bradesco)<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Conv\u00eanio (Unimed)\">Conv\u00eanio (Unimed)<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">AGENDAR CONSULTA<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c51b0e e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"8c51b0e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;slideInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-029a0c8 elementor-widget elementor-widget-google_maps\" data-id=\"029a0c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=R.%20Dr.%20Jos%C3%A9%20Afonso%20de%20Melo%2C%20118%20-%20Jati%C3%BAca%2C%20Macei%C3%B3%20-%20AL%2C%2057036-510&#038;t=m&#038;z=12&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"R. Dr. Jos\u00e9 Afonso de Melo, 118 - Jati\u00faca, Macei\u00f3 - AL, 57036-510\"\n\t\t\t\t\taria-label=\"R. Dr. Jos\u00e9 Afonso de Melo, 118 - Jati\u00faca, Macei\u00f3 - AL, 57036-510\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78b7ad4 elementor-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"78b7ad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R. Dr. Jos\u00e9 Afonso de Melo, 118 - Jati\u00faca, Macei\u00f3 - AL, 57036-510<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aumente a qualidade de vida com abordagens INTEGRATIVAS inovadoras Planos terap\u00eauticos personalizados para doen\u00e7as neurol\u00f3gicas de Parkinson e Alzheimer, especialista em disturbios do movimento. Agendar consulta Neurologia Integrada Neurologista especialista em tratamento de dist\u00farbios de movimento, Parkinson e dist\u00farbios da mem\u00f3ria. Master Coach Sist\u00eamica e Medicina Integrativa. Formada pela Universidade Federal de Alagoas, com mestrado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-1079","page","type-page","status-publish","hentry"],"aioseo_notices":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"INVT - Projeto Neuro Viva Mais","author_link":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/author\/invt-projeto-neuroviva-mais\/"},"uagb_comment_info":0,"uagb_excerpt":"Aumente a qualidade de vida com abordagens INTEGRATIVAS inovadoras Planos terap\u00eauticos personalizados para doen\u00e7as neurol\u00f3gicas de Parkinson e Alzheimer, especialista em disturbios do movimento. Agendar consulta Neurologia Integrada Neurologista especialista em tratamento de dist\u00farbios de movimento, Parkinson e dist\u00farbios da mem\u00f3ria. Master Coach Sist\u00eamica e Medicina Integrativa. Formada pela Universidade Federal de Alagoas, com mestrado&hellip;","_links":{"self":[{"href":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-json\/wp\/v2\/pages\/1079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-json\/wp\/v2\/comments?post=1079"}],"version-history":[{"count":520,"href":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-json\/wp\/v2\/pages\/1079\/revisions"}],"predecessor-version":[{"id":2169,"href":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-json\/wp\/v2\/pages\/1079\/revisions\/2169"}],"wp:attachment":[{"href":"https:\/\/projeto.inovamentehub.com.br\/neurovivamais\/wp-json\/wp\/v2\/media?parent=1079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}